{"id":20622,"date":"2021-08-27T12:17:07","date_gmt":"2021-08-27T10:17:07","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=20622"},"modified":"2021-08-27T12:17:15","modified_gmt":"2021-08-27T10:17:15","slug":"livreurs-a-velo-h-f-pour-la-restauration","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/livreurs-a-velo-h-f-pour-la-restauration\/","title":{"rendered":"LIVREURS A V\u00c9LO (H\/F) POUR LA RESTAURATION"},"content":{"rendered":"\n<p><strong>Description<\/strong><\/p>\n\n\n\n<p>CATERING (DESANNE SAS), est une Entreprise sp\u00e9cialis\u00e9e dans le domaine de restauration, fort de plusieurs ann\u00e9es d\u2019exp\u00e9rience elle produit et vend des plats de la gastronomie nationale et internationale \u00e0 ses diff\u00e9rents client via la plateforme\u00a0<a href=\"http:\/\/asktatchop.fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">ASKTATCHOP.fr<\/a>\u00a0dont elle est partenaire.\u00a0<\/p>\n\n\n\n<p><strong>Missions \/ Responsabilit\u00e9s \/ Activit\u00e9s<\/strong><\/p>\n\n\n\n<p>Vous int\u00e9grez une \u00e9quipe de taille humaine dans le domaine de la restauration.<br>Votre objectif sera de R\u00e9cup\u00e9rer les commandes des clients et aller livrer dans les d\u00e9lais avec un v\u00e9lo.<br><strong>Missions Principales :<\/strong><\/p>\n\n\n\n<ul><li>R\u00e9cup\u00e9rer les commandes et les mettre dans le sac de livraison pour les acheminer aux clients<\/li><li>Etre rapide pour respecter les d\u00e9lais de livraison et le temps d\u2019attente des clients<\/li><li>Faire attention aux diff\u00e9rents colis et plats transport\u00e9s afin qu\u2019ils soient livr\u00e9s intacts aux clients<\/li><li>Faire un rapport et d\u00e9comptes de ses livraisons au responsable<\/li><\/ul>\n\n\n\n<p><strong>Comp\u00e9tences \/ Exigences \/ Qualit\u00e9s<\/strong><\/p>\n\n\n\n<ul><li>Niveau scolaire minimum CEP&nbsp;<\/li><li>Savoir p\u00e9daler correctement un v\u00e9lo avec un sac de livraison \u00e0 dos&nbsp;<\/li><li>Connaitre la ville&nbsp;<\/li><li>\u00catre majeur (21 ans)&nbsp;<\/li><li>Etre poli joviale et courtoise et de tr\u00e8s bonne moralit\u00e9&nbsp;<\/li><li>Etre en bonne sant\u00e9 et disponible&nbsp;<\/li><li>Savoir bien communiquer et s\u2019exprimer&nbsp;<\/li><li>Etre toujours propre, pr\u00e9sentable et savoir entretenir sa tenue de travail<\/li><\/ul>\n\n\n\n<p><strong>Profil du candidat<\/strong><\/p>\n\n\n\n<p>\u00bb Niveau Acad\u00e9mique Minimum: CEPE, CEP<br><strong>Documents de candidature<\/strong><\/p>\n\n\n\n<p>\u00bb Lettre de Motivation<br>\u00bb Curriculum Vitae<br><strong>NOTE: LES ARNAQUEURS SONT DE PLUS EN PLUS ASTUCIEUX! N&rsquo;envoyez jamais de l&rsquo;argent \u00e0 un inconnu au cours d&rsquo;un recrutement quelle que soit la raison! Et Si vous devriez le faire, que ce soit \u00e0 vos PROPRES RISQUES!<\/strong><\/p>\n\n\n\n<p><strong>Instructions de candidature<\/strong><\/p>\n\n\n\n<p>Vous remplissez ces crit\u00e8res et \u00eates int\u00e9ress\u00e9s ? Alors envoyez-nous votre candidature \u00e0 l&rsquo;adresse suivante :\u00a0<a href=\"mailto:recrutement@desanne.fr\" target=\"_blank\" rel=\"noreferrer noopener\">recrutement@desanne.fr<\/a><\/p>\n\n\n\n<p>Votre CV<strong>&nbsp;(sur une seule page &#8211; obligatoire)<\/strong>&nbsp;et une lettre de motivation, doivent avoir en objet du mail, le nom du poste pour lequel vous candidatez.<\/p>\n\n\n\n<p>Contact : 694 48 32 90 \/ 233 41 12 12<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desanne SAS recrute pour ses services recrute LIVREURS A V\u00c9LO (H\/F) POUR LA RESTAURATION. Postulez via l&rsquo;adresse recrutement@desanne.fr<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[1263],"tags":[3597,4,3598],"villes":[135],"contrats":[148],"diplomes":[157],"louma_meta":{"emploi_title":"LIVREURS A V\u00c9LO (H\/F) POUR LA RESTAURATION","emplois_employeur":10786,"emplois_date_publication":"2021-08-27","emplois_heure_publication":"11:13","emplois_date_cloture":"2021-08-31","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"recrutement@desanne.fr"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/20622"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=20622"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/20622\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/10787"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=20622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=20622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=20622"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=20622"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=20622"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=20622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}