{"id":20275,"date":"2021-08-21T13:42:40","date_gmt":"2021-08-21T11:42:40","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=20275"},"modified":"2021-08-21T20:27:16","modified_gmt":"2021-08-21T18:27:16","slug":"responsable-boutique","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/responsable-boutique\/","title":{"rendered":"Responsable Boutique"},"content":{"rendered":"\n<p>Dans le cadre du d\u00e9veloppement de son activit\u00e9, l\u2019entreprise BLACKSHOP sp\u00e9cialis\u00e9e dans la distribution des produits et services CANAL + proc\u00e8de au recrutement <strong>d\u2019une<\/strong> <strong>Responsable Boutique.<\/strong><\/p>\n\n\n\n<p><strong><u>Lieu du travail<\/u><\/strong>&nbsp;: Yaound\u00e9, Nkolbisson<\/p>\n\n\n\n<p><strong><u>Nombre de place<\/u><\/strong>&nbsp;: 01<\/p>\n\n\n\n<p><strong><u>Type de contrat<\/u><\/strong>&nbsp;: Essai puis CDD<\/p>\n\n\n\n<p><strong><u>Salaire<\/u><\/strong>&nbsp;: \u00e0 n\u00e9gocier<\/p>\n\n\n\n<p><strong><u>Positionnement hi\u00e9rarchique<\/u><\/strong>&nbsp;: Sous la responsabilit\u00e9 directe du Directeur Commercial<\/p>\n\n\n\n<p><strong>Missions du poste<\/strong>&nbsp;: la Responsable Boutique a pour missions :<\/p>\n\n\n\n<ul><li>De d\u00e9velopper le chiffre d\u2019affaires de la boutique en maximisant le revenu par abonn\u00e9 et en r\u00e9pondant au mieux aux attentes des clients&nbsp;;<\/li><li>Elle vise \u00e0 d\u00e9passer les objectifs fix\u00e9s et animer l\u2019\u00e9quipe commerciale de sa boutique.<\/li><\/ul>\n\n\n\n<p><strong>Activit\u00e9s du poste&nbsp;:<\/strong><\/p>\n\n\n\n<p>En plus des activit\u00e9s de la vendeuse, la RB assure au quotidien&nbsp;:<\/p>\n\n\n\n<ul><li>Le coaching de son \u00e9quipe de vendeuse&nbsp;;<\/li><li>Le suivi des performances de son \u00e9quipe&nbsp;;<\/li><li>La gestion du planning de travail&nbsp;;<\/li><li>La mise en place des animations commerciales pour dynamiser la boutique&nbsp;;<\/li><li>Le bon d\u00e9roulement des op\u00e9rations commerciales et le contr\u00f4le de la qualit\u00e9 du merchandising&nbsp;;<\/li><li>La gestion op\u00e9rationnelle de la boutique&nbsp;;<\/li><li>Le suivi de l\u2019application des proc\u00e9dures (logistique et financi\u00e8res)&nbsp;;<\/li><li>Le contr\u00f4le de la caisse et des stocks&nbsp;;<\/li><\/ul>\n\n\n\n<ul><li>La gestion du service apr\u00e8s-vente et la maintenance des \u00e9quipements de la boutique&nbsp;;<\/li><li>Le suivi des performances de la boutique&nbsp;;<\/li><li>L\u2019analyse quotidienne des KPI de la boutique et effectue les remont\u00e9es au DC&nbsp;;<\/li><li>Elle effectue des propositions d\u2019actions correctives en vue de l\u2019am\u00e9lioration des performances commerciales de la boutique.<\/li><\/ul>\n\n\n\n<p><strong>Comp\u00e9tences techniques<\/strong><\/p>\n\n\n\n<ul><li>Ma\u00eetriser les techniques du merchandising, de la vente B to C, B to B et de la n\u00e9gociation&nbsp;;<\/li><li>Maitriser des techniques du management d\u2019\u00e9quipe&nbsp;;<\/li><li>Excellent niveau de communication&nbsp;;<\/li><li>Maitriser l\u2019outil informatique (internet, messagerie, bases de donn\u00e9es, logiciels internes\u2026).<\/li><\/ul>\n\n\n\n<p><strong>Qualit\u00e9s comportementales et transversales<\/strong><\/p>\n\n\n\n<ul><li>Capacit\u00e9 d\u2019adaptation et \u00e0 l\u2019affut de nouvelles id\u00e9es&nbsp;;<\/li><li>R\u00e9activit\u00e9 et pragmatisme&nbsp;;<\/li><li>Bonne pr\u00e9sentation physique, naturel souriante&nbsp;;<\/li><li>Persuasive et dot\u00e9e d\u2019un sens du client d\u00e9velopp\u00e9&nbsp;;<\/li><li>R\u00e9sistance au stress&nbsp;;<\/li><li>Maitrise de soi et diplomatie&nbsp;;<\/li><li>Go\u00fbt du challenge et travail en \u00e9quipe&nbsp;;<\/li><li>Ecoute active, ouverture et cr\u00e9ativit\u00e9&nbsp;;<\/li><li>Ma\u00eetriser \u00e9ventuellement l\u2019anglais&nbsp;;<\/li><li>Bonnes capacit\u00e9s r\u00e9dactionnelles.<\/li><\/ul>\n\n\n\n<p><strong>Formation acad\u00e9mique<\/strong><\/p>\n\n\n\n<p>BAC + 2 minimum en marketing-commerce-vente ou dipl\u00f4me \u00e9quivalent.<\/p>\n\n\n\n<p><strong>Exp\u00e9rience professionnelle<\/strong><\/p>\n\n\n\n<p>Avoir une exp\u00e9rience de 01 an minimum \u00e0 un poste de management d\u2019\u00e9quipe commerciale id\u00e9alement dans le secteur des T\u00e9l\u00e9coms et\/ou NTIC.<\/p>\n\n\n\n<p><strong>Pour postuler, merci d\u2019envoyer votre CV et lettre de motivation par mail \u00e0 l\u2019adresse <em>blackshop237@gmail.com.<\/em><\/strong><\/p>\n\n\n\n<p><strong><em>Date limite de r\u00e9ception des candidatures&nbsp;: le 10 Septembre 2021.<\/em><\/strong><\/p>\n\n\n\n<p><strong><em>contact 691573112<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Blackshop recrute pour les besoins de ses services un Responsable Boutique. Pour postuler, merci d\u2019envoyer votre CV et lettre de motivation par mail \u00e0 l\u2019adresse blackshop237@gmail.com.<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[251,24,1273],"tags":[245,3548,7],"villes":[136],"contrats":[236],"diplomes":[248],"louma_meta":{"emploi_title":"Responsable Boutique","emplois_employeur":3046,"emplois_date_publication":"2021-08-21","emplois_heure_publication":"12:38","emplois_date_cloture":"2021-09-10","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"1","emploi_email":"blackshop237@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/20275"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=20275"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/20275\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/9483"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=20275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=20275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=20275"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=20275"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=20275"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=20275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}