{"id":20070,"date":"2021-08-17T12:53:32","date_gmt":"2021-08-17T10:53:32","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=20070"},"modified":"2021-08-17T12:53:38","modified_gmt":"2021-08-17T10:53:38","slug":"guichetier","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/guichetier\/","title":{"rendered":"GUICHETIER"},"content":{"rendered":"\n<p><strong>Description du Poste<\/strong><\/p>\n\n\n\n<p>Le guichet est la vitrine principale de l\u2019agence.<\/p>\n\n\n\n<ul><li><strong>Activit\u00e9s principales du poste<\/strong><\/li><li>Maintenir une bonne qualit\u00e9 de service au niveau du front office\u00a0;<\/li><li>Accueillir, informer et orienter les usagers\u00a0;<\/li><li>Sensibiliser les usagers sur les produits et services de AMIS FINANCE\u00a0;<\/li><li>Informer les usagers sur les conditions d\u2019ouverture de comptes\u00a0;<\/li><li>Recevoir les documents et faire signer tous les documents d\u2019entrer en relation avec les mutualistes<\/li><li>Recevoir et transmettre les ordres des clients\u00a0;<\/li><li>Etablir et mettre \u00e0 jour les livrets d\u2019\u00e9pargne des mutualistes\u00a0;<\/li><li>Tenir les diff\u00e9rents registres de son poste de travail\u00a0;<\/li><li>Saisir les informations sur les clients dans le syst\u00e8me d\u2019exploitation et veiller \u00e0 la bonne tenue de leurs dossiers\u00a0;<\/li><li>Participer aux atteintes des objectifs de l\u2019agence\u00a0;<\/li><li>Effectuer toutes les t\u00e2ches professionnelles confi\u00e9es par la hi\u00e9rarchie,<\/li><li>Produire les divers rapports dans les d\u00e9lais requis\u00a0;<\/li><\/ul>\n\n\n\n<p><strong>Ressources n\u00e9cessaires (exigences professionnelles)<\/strong><\/p>\n\n\n\n<p><strong>&nbsp;&nbsp; <u>Profil de base&nbsp;:<\/u><\/strong><\/p>\n\n\n\n<ul><li>Etre de bonne moralit\u00e9&nbsp;;<\/li><li>Jouir de ses droits civiques&nbsp;;<\/li><li>Avoir une caution morale et financi\u00e8re&nbsp;solvable ;<\/li><li>Avoir au minimum un BEPC avec une exp\u00e9rience de 2 ans au moins dans un Etablissement de microfinance&nbsp;;<\/li><\/ul>\n\n\n\n<p><strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Savoir \u2013 faire&nbsp;:<\/strong><\/p>\n\n\n\n<ul><li>Techniques d\u2019accueil&nbsp;;<\/li><li>Maitrise des techniques de service \u00e0 la client\u00e8le&nbsp;;<\/li><li>Bonne \u00e9locution et communication&nbsp;;<\/li><li>Maitrise de l\u2019outil informatique (Word-Excel \u2013 logiciel d\u2019exploitation)<\/li><\/ul>\n\n\n\n<p><strong>Savoir- \u00eatre&nbsp;:<\/strong><\/p>\n\n\n\n<ul><li>Souriant, accueillant, courtois, pr\u00e9sentable et disponible&nbsp;;<\/li><li>Attentionn\u00e9&nbsp;;<\/li><li>Consciencieux&nbsp;;<\/li><li>Engag\u00e9&nbsp;;<\/li><li>Humble&nbsp;;<\/li><li>Etre bilingue est un atout.<\/li><\/ul>\n\n\n\n<p><strong><u>Pi\u00e8ces \u00e0 fournir<\/u><\/strong>\u00a0: lettre de motivation adress\u00e9e au DG la coop\u00e9rative AMIS FINANCE, CV avec photo.\u00a0 A envoyer \u00e0 l\u2019email\u00a0\u00a0\u00a0 <a href=\"mailto:amisfinance10@gmail.com\">amisfinance10@gmail.com<\/a><\/p>\n\n\n\n<p>Date de cl\u00f4ture&nbsp;: 25 aout 2021<\/p>\n\n\n\n<p>Ville&nbsp;: Yaound\u00e9<\/p>\n\n\n\n<p>Cat\u00e9gorie&nbsp;: finances<\/p>\n\n\n\n<p>Exp\u00e9riences&nbsp;: 4 ans<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Amis Finances recrute pour les besoins de ses services un Guichetier. Postulez via l&rsquo;adresse amisfinance10@gmail.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[23],"tags":[3514,245,7],"villes":[136],"contrats":[148],"diplomes":[158],"louma_meta":{"emploi_title":"GUICHETIER","emplois_employeur":3046,"emplois_date_publication":"2021-08-17","emplois_heure_publication":"11:49","emplois_date_cloture":"2021-08-25","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"4","emploi_email":" amisfinance10@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/20070"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=20070"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/20070\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/9483"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=20070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=20070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=20070"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=20070"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=20070"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=20070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}