{"id":20068,"date":"2021-08-17T13:17:43","date_gmt":"2021-08-17T11:17:43","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=20068"},"modified":"2021-08-17T13:17:51","modified_gmt":"2021-08-17T11:17:51","slug":"agent-de-collecte-journaliere","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/agent-de-collecte-journaliere\/","title":{"rendered":"AGENT DE COLLECTE JOURNALIERE"},"content":{"rendered":"\n<p>L\u2019agent de collecte est charg\u00e9 d\u2019impl\u00e9menter la politique commerciale et marketing\u00a0 d\u2019AMIS FINANCE d\u2019AMIS. Son travail se fait essentiellement sur le terrain et consiste \u00e0 aller au contact des prospects pour leur proposer les produits <\/p>\n\n\n\n<p>et services d\u2019AMIS FINANCE, puis collecter les fonds des mutualistes<\/p>\n\n\n\n<p><strong>Description du poste<\/strong><\/p>\n\n\n\n<ol type=\"1\"><li>Cr\u00e9er et d\u00e9velopper un portefeuille de micro \u00e9pargnants ;<\/li><li>Collecter au jour le jour les fonds aupr\u00e8s des petits \u00e9pargnants sur le terrain et les reverser dans les comptes de ces derniers ouverts \u00e0 AMIS FINANCE&nbsp;;<\/li><li>Veiller au pr\u00e9l\u00e8vement des commissions sur les sommes collect\u00e9es mensuellement&nbsp;;<\/li><li>Prospecter, proposer et vendre les produits classiques de l\u2019\u00e9tablissement \u00e0 ses clients<\/li><li>Glaner les informations sur le comportement du march\u00e9 de la microfinance sur le terrain et les porter \u00e0 l\u2019attention du Chef d\u2019agence<\/li><li>&nbsp;&nbsp;Initier les dossiers des microcr\u00e9dits<\/li><li>Suivre le recouvrement des cr\u00e9dits et microcr\u00e9dits au travers de la collecte journali\u00e8re<\/li><\/ol>\n\n\n\n<p><strong>Ressources n\u00e9cessaires (exigences professionnelles)<\/strong><\/p>\n\n\n\n<p><strong>Profil de base&nbsp;:<\/strong><\/p>\n\n\n\n<ol type=\"1\"><li>Etre de bonne moralit\u00e9\u00a0;<\/li><li>Jouir de ses droits civiques\u00a0;<\/li><li>Avoir au moins une caution solidaire et personnelle\u00a0solvable ;<\/li><li>adh\u00e9rer \u00e0 la mission, valeurs et objectifs de AMIS FINANCE\u00a0;<\/li><li>Avoir au minimum un CEPE\u00a0;\u00a0<\/li><\/ol>\n\n\n\n<p><strong>Savoir faire<\/strong><\/p>\n\n\n\n<ol type=\"1\"><li>Comp\u00e9tence dans la promotion, marketing et communication&nbsp;;<\/li><li>Bonne connaissance, Int\u00e9r\u00eat et engagement \u00e0 travailler avec le secteur informel&nbsp;;<\/li><li>Aptitudes en calcul rapide&nbsp;;<\/li><li>Maitrise du fonctionnement des r\u00e9seaux sociaux<\/li><li>Mobilit\u00e9 facile&nbsp;<\/li><\/ol>\n\n\n\n<p><strong>Savoir \u2013\u00eatre<\/strong><\/p>\n\n\n\n<ol type=\"1\"><li>Honn\u00eatet\u00e9, patience et sens de l\u2019\u00e9coute&nbsp;;<\/li><li>Humilit\u00e9&nbsp;;<\/li><li>Sens de l\u2019organisation et esprit d\u2019\u00e9quipe&nbsp;;<\/li><li>Disponibilit\u00e9&nbsp;;<\/li><\/ol>\n\n\n\n<p><strong><u>Pi\u00e8ces \u00e0 fournir<\/u><\/strong>\u00a0: lettre de motivation adress\u00e9e au DG la coop\u00e9rative AMIS FINANCE, CV avec photo.\u00a0 A envoyer \u00e0 l\u2019email\u00a0\u00a0\u00a0 <a href=\"mailto:amisfinance10@gmail.com\">amisfinance10@gmail.com<\/a><\/p>\n\n\n\n<p>Date de cl\u00f4ture&nbsp;: 25 aout 2021<\/p>\n\n\n\n<p>Ville&nbsp;: Yaound\u00e9<\/p>\n\n\n\n<p>Cat\u00e9gorie&nbsp;: finances<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Amis Finances recrute pour les besoins de ses services un AGENT DE COLLECTE JOURNALIERE. Postulez via  amisfinance10@gmail.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[23],"tags":[3516,245,7],"villes":[136],"contrats":[148],"diplomes":[158,3083],"louma_meta":{"emploi_title":"AGENT DE COLLECTE JOURNALIERE","emplois_employeur":3046,"emplois_date_publication":"2021-08-17","emplois_heure_publication":"12:14","emplois_date_cloture":"2021-08-25","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"1","emploi_email":" amisfinance10@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/20068"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=20068"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/20068\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/9483"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=20068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=20068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=20068"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=20068"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=20068"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=20068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}