{"id":19466,"date":"2021-08-06T23:38:37","date_gmt":"2021-08-06T21:38:37","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=19466"},"modified":"2021-08-09T11:53:11","modified_gmt":"2021-08-09T09:53:11","slug":"assistant-e-de-direction-2","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/assistant-e-de-direction-2\/","title":{"rendered":"ASSISTANT (E) DE DIRECTION"},"content":{"rendered":"\n<p><strong>Description<\/strong><\/p>\n\n\n\n<p>OFFRE DE STAGE PROFESSIONNEL:ASSISTANT (E) DE DIRECTION&nbsp;<\/p>\n\n\n\n<p><strong>Missions \/ Responsabilit\u00e9s \/ Activit\u00e9s<\/strong><\/p>\n\n\n\n<ul><li>Accueillir les partenaires, client et visiteurs etc ;<\/li><li>Recevoir, dispatcher, suivre, enregistrer et transmettre tous les documents apr\u00e8s traitement<\/li><li>Organiser les r\u00e9ceptions, r\u00e9unions et d\u00eeners ;<\/li><li>Organiser les voyages professionnels et g\u00e9rer les d\u00e9placements (r\u00e9servations d\u2019h\u00f4tels et billets d\u2019avion) ;<\/li><li>R\u00e9diger les correspondances administratives et assurer divers classements ;<\/li><li>Faciliter d\u2019adaptation au changement du syst\u00e8me informatique<\/li><li>S\u2019acquitter des t\u00e2ches administratives et assister la Direction<\/li><li>Assurer le suivi des t\u00e2ches de secr\u00e9tariat r\u00e9alis\u00e9es par les secr\u00e9taires de direction<\/li><li>Back up en cas d\u2019absence de membres de l\u2019\u00e9quipe<\/li><li>Vous r\u00e9digerez et mettrez en forme des courriers, notes, rapports, pr\u00e9sentations et documents divers.<\/li><li>Organiser le classement et l&rsquo;archivage des dossiers<\/li><li>Planifier et organiser des r\u00e9unions et des \u00e9v\u00e8nements (instances, s\u00e9minaires\u2026) : r\u00e9diger les comptes rendus, suivre les relev\u00e9s de d\u00e9cisions et ex\u00e9cution des actions assign\u00e9es, pr\u00e9parer les supports, assurer la logistique \u2026 ;<\/li><\/ul>\n\n\n\n<p><strong>Comp\u00e9tences \/ Exigences \/ Qualit\u00e9s<\/strong><\/p>\n\n\n\n<ul><li>&nbsp;BAC + 2 minimum ou DQP<\/li><li>Bonne ma\u00eetrise de l\u2019anglais et Fran\u00e7ais;<\/li><li>Ma\u00eetrise des outils bureautiques et communication digitale ;<\/li><li>Sensibilit\u00e9 Commerciale, aisance relationnelle, orientation et relation client<\/li><li>Dynamisme, disponibilit\u00e9, rigueur, discr\u00e9tion, avenant (e) et travailleur ;<\/li><\/ul>\n\n\n\n<p><strong>Autre comp\u00e9tence<\/strong><\/p>\n\n\n\n<ul><li>Capacit\u00e9 d\u2019auto-formation et de formateur<\/li><li>Passion pour la qu\u00eate de nouveaux outils et proc\u00e9dures plus performantes et efficaces<\/li><li>Sens de la responsabilit\u00e9<\/li><li>S\u00e9r\u00e9nit\u00e9 et confiance en soi dans les actions et les choix<\/li><li>Sens de la discipline et du respect des proc\u00e9dures et m\u00e9thodes<\/li><li>Travail orient\u00e9 r\u00e9sultat<\/li><li>Travail sous pression<\/li><li>Tr\u00e8s bonnes capacit\u00e9s r\u00e9dactionnelles et d&rsquo;expression orale ;<\/li><\/ul>\n\n\n\n<p><strong>Profil du candidat<\/strong><\/p>\n\n\n\n<p>\u00bb Niveau Acad\u00e9mique Minimum: Bac+2 (BTS \/ HND,&#8230;)<br><strong>Documents de candidature<\/strong>\u00bb Une Lettre de motivation pr\u00e9cisant le poste en objet<br>\u00bb CV<br>\u00bb Une photocopie du dernier dipl\u00f4me<br>\u00bb Photocopie de la CNI<br><strong>NOTE: LES ARNAQUEURS SONT DE PLUS EN PLUS ASTUCIEUX! N&rsquo;envoyez jamais de l&rsquo;argent \u00e0 un inconnu au cours d&rsquo;un recrutement quelle que soit la raison! Et Si vous devriez le faire, que ce soit \u00e0 vos PROPRES RISQUES!<\/strong><\/p>\n\n\n\n<p><strong>Instructions de candidature<\/strong> <\/p>\n\n\n\n<p>NB : Un dossier incomplet ou comportant des pi\u00e8ces mal nomm\u00e9es ne sera pas examin\u00e9.<br>Le dossier de candidature est \u00e0 adresser par e-mail \u00e0&nbsp;<a target=\"_blank\" rel=\"noreferrer noopener\">jobs@elecit.net<\/a><br>Cl\u00f4ture des candidatures : 30\/08\/2021<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EleclT Engineering SARL recrute un(e) ASSISTANT (E) DE DIRECTION. Le dossier de candidature est \u00e0 adresser par e-mail \u00e0 jobs@elecit.net<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[251,1273],"tags":[2539,4,3419],"villes":[135],"contrats":[152],"diplomes":[248,278],"louma_meta":{"emploi_title":"ASSISTANT (E) DE DIRECTION ","emplois_employeur":13748,"emplois_date_publication":"2021-08-06","emplois_heure_publication":"22:35","emplois_date_cloture":"2021-08-30","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"1","emploi_email":"jobs@elecit.net"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/19466"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=19466"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/19466\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/13750"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=19466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=19466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=19466"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=19466"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=19466"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=19466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}