{"id":19392,"date":"2021-08-06T17:47:40","date_gmt":"2021-08-06T15:47:40","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=19392"},"modified":"2021-08-06T17:52:52","modified_gmt":"2021-08-06T15:52:52","slug":"agent-dentretien-2","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/agent-dentretien-2\/","title":{"rendered":"Agent d&rsquo;Entretien"},"content":{"rendered":"\n<p><strong>Description<\/strong><\/p>\n\n\n\n<p>Dans le cadre de son Programme de promotion de la Sant\u00e9 en entreprise, le Groupement Inter-Patronal du Cameroun (GICAM) b\u00e9n\u00e9ficie d&rsquo;un appui du Fond Mondial de lutte contre le SIDA, la Tuberculose et le Paludisme pour la mise en \u0153uvre du projet \u00ab\u00a0Pr\u00e9vention du VIH, du Paludisme et de la Tuberculose en direction du secteur priv\u00e9\u00a0\u00bb pour la p\u00e9riode de 2021 \u00e0 2023. Dans le but de renforcer l&rsquo;unit\u00e9 de Coordination du Projet, le GICAM recrute le personnel aux postes ci-apr\u00e8s :<\/p>\n\n\n\n<ul><li>Agent d&rsquo;entretien (01)<\/li><\/ul>\n\n\n\n<p>DUREE DE LA MISSION : 1 an renouvelable. En cas de succ\u00e8s \u00e0 ce poste, le contrat est susceptible d\u2019\u00eatre renouvel\u00e9.<br><strong>Missions \/ Responsabilit\u00e9s \/ Activit\u00e9s<\/strong><\/p>\n\n\n\n<p>Plac\u00e9 sous l\u2019autorit\u00e9 du Responsable Administratif et Financier, l\u2019Agent d\u2019Entretien aura pour mission principale d\u2019assurer en permanence la propret\u00e9 des locaux et espaces verts de la structure et d\u2019accomplir d\u2019autres t\u00e2ches qui lui seront confi\u00e9s.&nbsp;<br><strong>TACHES ET RESPONSABILITES<\/strong><\/p>\n\n\n\n<p>L\u2019agent d\u2019appui et d\u2019entretien \u00e0 recruter sera sp\u00e9cifiquement charg\u00e9 de :&nbsp;<\/p>\n\n\n\n<ul><li>Assurer quotidiennement et en permanence la propret\u00e9 des locaux et des bureaux ;&nbsp;<\/li><\/ul>\n\n\n\n<p>Entretenir les espaces verts ;&nbsp;<\/p>\n\n\n\n<ul><li>Assurer la garde, la propret\u00e9, la bonne utilisation du mat\u00e9riel et des produits d\u2019entretien ;&nbsp;<\/li><\/ul>\n\n\n\n<ul><li>Veiller \u00e0 ne pas endommager tout objet meublant, mat\u00e9riel et support pendant le processus de nettoyage ;&nbsp;<\/li><\/ul>\n\n\n\n<ul><li>Suivre le planning des travaux d\u2019entretien ;&nbsp;<\/li><\/ul>\n\n\n\n<ul><li>Faire les petites courses li\u00e9es au service ;&nbsp;<\/li><\/ul>\n\n\n\n<ul><li>Respecter les r\u00e8gles d\u2019hygi\u00e8ne et de s\u00e9curit\u00e9 ;&nbsp;<\/li><\/ul>\n\n\n\n<ul><li>Veiller \u00e0 ne pas perturber le s\u00e9jour des r\u00e9sidents et\/ou le travail du personnel en place ;&nbsp;<\/li><\/ul>\n\n\n\n<ul><li>Rendre compte \u00e0 qui de droit de tout droit de tout<br>dysfonctionnement ou et de toute autre anomalie ;&nbsp;<\/li><\/ul>\n\n\n\n<ul><li>Accomplir les autres t\u00e2ches \u00e0 lui confier par la hi\u00e9rarchie.&nbsp;<\/li><\/ul>\n\n\n\n<p><strong>Comp\u00e9tences \/ Exigences \/ Qualit\u00e9s<\/strong>Le candidat devra :<\/p>\n\n\n\n<ul><li>\u00catre titulaire au moins d\u2019un Certificat d\u2019Etudes Primaires (CEP);&nbsp;<\/li><li>Avoir l\u2019aptitude du travail en \u00e9quipe ;&nbsp;<\/li><li>Avoir au minimum deux(02) ann\u00e9es d\u2019exp\u00e9rience professionnelle<br>pertinente dans le domaine ;&nbsp;<\/li><li>Avoir une bonne capacit\u00e9 de collaborer avec l\u2019ensemble du<br>personnel et des usagers ;&nbsp;<\/li><li>\u00catre de bonne moralit\u00e9, honn\u00eate et int\u00e8gre ;&nbsp;<\/li><li>Jouir de bonnes capacit\u00e9s physiques et mentales<\/li><\/ul>\n\n\n\n<p><strong>Profil du candidat<\/strong><\/p>\n\n\n\n<p>\u00bb Niveau d&rsquo;exp\u00e9rience: Exp\u00e9riment\u00e9<br>\u00bb Ann\u00e9es d&rsquo;exp\u00e9rience: 02<br>\u00bb Niveau Acad\u00e9mique Minimum: CEPE, CEP<br><strong>Documents de candidature<\/strong><\/p>\n\n\n\n<p>\u00bb CV indiquant entre autres au moins 03 r\u00e9f\u00e9rences<br>\u00bb Lettre de motivation<br>\u00bb Copies de dipl\u00f4mes \/ professionnels pertinents<br>\u00bb Preuves d\u2019exp\u00e9riences de travail.<br><strong>NOTE: LES ARNAQUEURS SONT DE PLUS EN PLUS ASTUCIEUX! N&rsquo;envoyez jamais de l&rsquo;argent \u00e0 un inconnu au cours d&rsquo;un recrutement quelle que soit la raison! Et Si vous devriez le faire, que ce soit \u00e0 vos PROPRES RISQUES!<\/strong><\/p>\n\n\n\n<p><strong>Instructions de candidature<\/strong><\/p>\n\n\n\n<p>Chaque dossier de candidature r\u00e9dig\u00e9 en fran\u00e7ais ou en anglais devra parvenir au GICAM :&nbsp;<br>Par courriel \u00e0 l\u2019adresse&nbsp;<a href=\"mailto:recrutement@legicam.cm\" target=\"_blank\" rel=\"noreferrer noopener\">recrutement@legicam.cm<\/a>&nbsp;en pr\u00e9cisant&nbsp;l&rsquo;intitul\u00e9 du Poste&nbsp;suivi de la mention \u00ab&nbsp;SR GICAM, Projet Fonds Mondial&nbsp;\u00bb en objet du courriel ;&nbsp;<br>Par d\u00e9p\u00f4t au si\u00e8ge du GICAM \u00e0 Douala ou \u00e0 sa repr\u00e9sentation R\u00e9gionale de Yaound\u00e9 (contre d\u00e9charge) dans une enveloppe ferm\u00e9e portant les mentions ci-dessus indiqu\u00e9es.<br>Date limite&nbsp;: Vingt-et-un (21) jours \u00e0 compter de la date de publication de la pr\u00e9sente annonce.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GICAM recrute un Agent d&rsquo;Entretien. Chaque dossier de candidature r\u00e9dig\u00e9 en fran\u00e7ais ou en anglais devra parvenir au GICAM :<br \/>\nPar courriel \u00e0 l\u2019adresse recrutement@legicam.cm en pr\u00e9cisant l&rsquo;intitul\u00e9 du Poste suivi de la mention \u00ab SR GICAM, Projet Fonds Mondial \u00bb en objet du courriel ;<br \/>\nPar d\u00e9p\u00f4t au si\u00e8ge du GICAM \u00e0 Douala ou \u00e0 sa repr\u00e9sentation R\u00e9gionale de Yaound\u00e9 (contre d\u00e9charge) dans une enveloppe ferm\u00e9e portant les mentions ci-dessus indiqu\u00e9es.<br \/>\nDate limite : Vingt-et-un (21) jours \u00e0 compter de la date de publication de la pr\u00e9sente annonce.<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[1752],"tags":[3271,2350,315],"villes":[135,136],"contrats":[236],"diplomes":[3083],"louma_meta":{"emploi_title":"Agent d'Entretien ","emplois_employeur":3514,"emplois_date_publication":"2021-08-06","emplois_heure_publication":"16:44","emplois_date_cloture":"2021-08-18","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"2","emploi_email":"recrutement@legicam.cm"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/19392"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=19392"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/19392\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/3517"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=19392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=19392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=19392"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=19392"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=19392"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=19392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}