{"id":19254,"date":"2021-08-04T07:41:30","date_gmt":"2021-08-04T05:41:30","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=19254"},"modified":"2021-08-04T07:41:33","modified_gmt":"2021-08-04T05:41:33","slug":"charge-des-affaires-juridiques-et-du-contentieux","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/charge-des-affaires-juridiques-et-du-contentieux\/","title":{"rendered":"Charg\u00e9 des Affaires Juridiques et du Contentieux"},"content":{"rendered":"\n<p>Vous pensez \u00eatre notre prochain Charg\u00e9 des Affaires Juridiques et du Contentieux? Postulez Fiche de poste <\/p>\n\n\n\n<p>MISSIONS PRINCIPALES<\/p>\n\n\n\n<p> tieux, participer aux proc\u00e9dures judiciaires <\/p>\n\n\n\n<p>&#8211; Veiller \u00e0 rindemnisation des clients en cas de dom- mage subi <\/p>\n\n\n\n<p>Veiller au respect du droit en amont et lors de la r\u00e9alisa- tion d&rsquo;op\u00e9rations d&rsquo;assurance;<\/p>\n\n\n\n<p> &#8211; Veiller au montage harmonieux et non pr\u00e9judiciable \u00e0 la compagnie des diverses conventions sign\u00e9es avec les partenaires d&rsquo;affaires; <\/p>\n\n\n\n<p>&#8211; Suivre les dossiers contentieux des sinistres et tous autres dossiers contentieux impliquant la compagnie; <\/p>\n\n\n\n<p>&#8211; Suivre le contentieux primes en cas de besoin; <\/p>\n\n\n\n<p>&#8211; Tenir un \u00e9tat de suivi de tout le contentieux: <\/p>\n\n\n\n<p>&#8211; Orienter la prise de position sur les propositions de transaction et les jugements en cas de contentieux : <\/p>\n\n\n\n<p>Participer aux r\u00e9ponses a fournir aux \u00e9quipes op\u00e9ra- tionnelles et en particulier aux services en contact direct avec les assur\u00e9s; <\/p>\n\n\n\n<p>&#8211; G\u00e9rer les relations avec les avocats, tribunaux, com- missariats, auxiliaires de justice <\/p>\n\n\n\n<p>&#8211; Proposer la constitution des Avocats, les orienter dans la d\u00e9fense des int\u00e9r\u00eats de la compagnie et les \u00e9valuer p\u00e9riodiquement. <\/p>\n\n\n\n<p>Veille juridique et conseil<\/p>\n\n\n\n<p> &#8211; Assurer une veille sur l&rsquo;\u00e9volution de la l\u00e9gislation des op\u00e9rations d&rsquo;assurance;<\/p>\n\n\n\n<p> &#8211; Apporter des conseils aupr\u00e8s des diff\u00e9rentes directions de l&rsquo;entreprise sur la pr\u00e9vention des risques <\/p>\n\n\n\n<p>FORMATION ET COMPETENCES MASTER Il en Droit (Droit des Assurances, Droit des Al- faires, Droit Fiscal)<\/p>\n\n\n\n<p> &#8211; Exp\u00e9rience de cabinet ou en compagnie vivement re- command\u00e9e<\/p>\n\n\n\n<p> &#8211; Exp\u00e9rience de 2 ans minimum dans une fonction simi- laire ou dans le d\u00e9partement sinistre d&rsquo;une compagnie d&rsquo;assurance Comp\u00e9tences techniques<\/p>\n\n\n\n<p> &#8211; Maitriser MICROSOFT OFFICE (Word, Excel, Power- Point) <\/p>\n\n\n\n<p>&#8211; Bonne connaissance du Doit Camerounais<\/p>\n\n\n\n<p> &#8211; Bonne connaissance du code CIMA<\/p>\n\n\n\n<p> &#8211; Bonne maitrise du processus d&rsquo;indemnisation<\/p>\n\n\n\n<p> &#8211; Bonnes aptitudes redactionnelles <\/p>\n\n\n\n<p>AUTRES MISSIONS <\/p>\n\n\n\n<p>Outres les missions principales ci-dessus, le titulaire du poste devra aussi assurer les activit\u00e9s ci- apr\u00e8s Autres comp\u00e9tences <\/p>\n\n\n\n<p>ORGANISATION <\/p>\n\n\n\n<p>Aptitude a planifier et a percevoir les priorit\u00e9s, bon sens et objectivit\u00e9 <\/p>\n\n\n\n<p>Participation \u00e0 l&rsquo;\u00e9laboration des nouveaux produits<\/p>\n\n\n\n<p> &#8211; Veille de la conformit\u00e9 normative <\/p>\n\n\n\n<p>&#8211; Veille du respect des proc\u00e9dures<\/p>\n\n\n\n<p> &#8211; Suivi de l&rsquo;obtention des autorisations l\u00e9gales <\/p>\n\n\n\n<p>RELATIONNEL ET SOCIAL <\/p>\n\n\n\n<p>Travail en \u00e9quipe, excellent sens du relationnel, recti- tude morale <\/p>\n\n\n\n<p>ADAPTATION <\/p>\n\n\n\n<p>Esprit d&rsquo;initiative <\/p>\n\n\n\n<p>Participation \u00e0 la gestion du sinistre<\/p>\n\n\n\n<p> &#8211; Analyse des faits, contacts avec les experts, exploita- tion des rapports d&rsquo;enqu\u00eates et d&rsquo;expertises (corporelles et mat\u00e9rielles), mise en paiement et cloture des dossiers suivant la proc\u00e9dure transactionnelle CIMA <\/p>\n\n\n\n<p>&#8211; Pr\u00e9paration de gestion pr\u00e9contentieuse (strat\u00e9gie de r\u00e9glement amiable, conciliation) <\/p>\n\n\n\n<p>&#8211; En cas de situation contentieuse, en collaboration avec l&rsquo;avocat de l&rsquo;entreprise instruire le dossier en conten<\/p>\n\n\n\n<p> SUPERIEUR HIERARCHIQUE Directeur Technique O\u00f9 postuler A contact@atlantiqueasurances.cm <\/p>\n\n\n\n<p>Date limite : 06 Octobre 2021 a atlantique assurahces<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous pensez \u00eatre notre prochain Charg\u00e9 des Affaires Juridiques et du Contentieux? Postulez Fiche de poste MISSIONS PRINCIPALES tieux, participer aux proc\u00e9dures judiciaires &#8211; Veiller&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[23,235],"tags":[],"villes":[136],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Charg\u00e9 des Affaires Juridiques et du Contentieux","emplois_employeur":2974,"emplois_date_publication":"2021-08-04","emplois_heure_publication":"","emplois_date_cloture":"2021-10-06","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"3","emploi_email":"contact@atlantiqueasurances.cm "},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/19254"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=19254"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/19254\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/2197"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=19254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=19254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=19254"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=19254"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=19254"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=19254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}