{"id":18990,"date":"2021-07-30T22:56:06","date_gmt":"2021-07-30T20:56:06","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=18990"},"modified":"2021-07-31T08:24:56","modified_gmt":"2021-07-31T06:24:56","slug":"data-analyst","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/data-analyst\/","title":{"rendered":"Data Analyst"},"content":{"rendered":"\n<p><strong>Description<\/strong><\/p>\n\n\n\n<p><strong>Missions \/ Responsabilit\u00e9s \/ Activit\u00e9s<\/strong><\/p>\n\n\n\n<p><strong>Court r\u00e9sum\u00e9 du poste&nbsp;<\/strong>:<br>Un poste d&rsquo;analyste de donn\u00e9es destin\u00e9 \u00e0 des personnes intelligentes capables d&rsquo;apprendre rapidement les pratiques de gestion de nouveaux secteurs. Vous intervenez de l&rsquo;int\u00e9gralit\u00e9 du cycle de vente de la qualification de l&rsquo;opportunit\u00e9 \u00e0 la n\u00e9gociation, en passant par des d\u00e9monstrations de produits \u00e9poustouflantes.&nbsp;<br>Rattach\u00e9 au p\u00f4le &lsquo;DATA&rsquo;, le BI Analyst interviendra sur le projet de d\u00e9ploiement des projets BI.<br><strong>Responsabilit\u00e9s<\/strong><br>Votre go\u00fbt pour les donn\u00e9es, votre curiosit\u00e9 intellectuelle ainsi que votre esprit d&rsquo;analyse et de synth\u00e8se qui vous permettent de produire des recommandations afin d&rsquo;am\u00e9liorer la prise de d\u00e9cision.<br><strong>Quels sont les attraits de ce poste ?<\/strong><\/p>\n\n\n\n<ul><li>Participez \u00e0 la production d&rsquo;analyses<ul><li>Traitement et analyse des informations\/donn\u00e9es issues de nos outils internes (Progiciel de gestion, univers Business Intelligence, fichiers Excel) pour analyses g\u00e9n\u00e9rales ou cibl\u00e9es<\/li><li>Production de tableaux de bords adapt\u00e9s aux demandes de nos interlocuteurs internes<\/li><li>Conception de rapports synth\u00e9tiques<\/li><\/ul><ul><li>Participez au travail pr\u00e9paratoire des n\u00e9gociations (due diligence)<\/li><\/ul><ul><li>Analyse de donn\u00e9es des clients<\/li><li>Analyse des informations r\u00e9colt\u00e9es via nos outils internes sur les liens contractuels existants concernant nos connaissances&nbsp;<\/li><\/ul><ul><li>Participez \u00e0 des projets transverses : contribution \u00e0 la d\u00e9finition et la mise en place des futurs outils de pilotage contrats et \u00e9l\u00e9ments de PI<\/li><\/ul><\/li><\/ul>\n\n\n\n<ul><li>Participer \u00e0 l&rsquo;\u00e9laboration d&rsquo;une roadmap et au projet de migration de la solution BI vers une solution Microsoft Power BI<\/li><li>Collecter aupr\u00e8s des m\u00e9tiers les indicateurs existants \u00e0 reprendre et les nouveaux indicateurs \u00e0 d\u00e9velopper<\/li><li>Simplifier le process de cr\u00e9ation de nos tableaux de bord et indicateurs de performance : automatiser , informatiser, cr\u00e9er les visuels appropri\u00e9s, notamment \u00e0 travers l&rsquo;outil BI<\/li><li>D\u00e9velopper des indicateurs sous Power BI<\/li><li>Former les utilisateurs \u00e0 l&rsquo;utilisation du nouvel outil BI<\/li><li>Supporter le m\u00e9tier lors des tests de la solution et de la mise en production<\/li><li>Rendre compte de l&rsquo;avancement de l&rsquo;\u00e9laboration des indicateurs<\/li><\/ul>\n\n\n\n<p><strong>Comp\u00e9tences \/ Exigences \/ Qualit\u00e9s D\u00e9fis<\/strong><\/p>\n\n\n\n<ul><li>Vous \u00eates organis\u00e9(e) et rigoureux-se et votre excellent relationnel vous permettent de vous adapter et d\u2019interagir avec des interlocuteurs vari\u00e9s.<\/li><li>Vous \u00eates int\u00e9ress\u00e9(e)s par l\u2019analyse de donn\u00e9es (analyse statistique, data mining) et \u00eates \u00e0 l\u2019aise avec l\u2019utilisation des outils informatiques&nbsp;<\/li><\/ul>\n\n\n\n<p><strong>Requis<\/strong><\/p>\n\n\n\n<ul><li>Vous avez des connaissances des bases du langage SQL, Java et des mod\u00e8les de donn\u00e9es relationnelles.<\/li><li>Dot\u00e9(e) d&rsquo;un excellent relationnel, vous \u00eates organis\u00e9(e), disponible et poss\u00e9dez de r\u00e9elles aptitudes \u00e0 travailler en \u00e9quipe.<\/li><li>Capacit\u00e9 de mont\u00e9e en comp\u00e9tences sur les outils BI (Talend, Power BI). Il n&rsquo;est pas un pr\u00e9-requis d&rsquo;avoir des connaissances de l&rsquo;outil au pr\u00e9alable.<\/li><\/ul>\n\n\n\n<p>Vous d\u00e9montrez une forte volont\u00e9 d\u2019apprendre l\u2019utilisation de nouveaux outils progiciels et acc\u00e8s \u00e0 des bases de donn\u00e9es, notamment Business Intelligence.&nbsp;<\/p>\n\n\n\n<p><strong>Instructions de candidature<\/strong><\/p>\n\n\n\n<p>Cliquez sur le lien suivant pour postuler:&nbsp;<a href=\"https:\/\/join.philjohntech.com\/jobs\/apply\/data-analyst-46\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/join.philjohntech.com\/jobs\/apply\/data-analyst-46<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Philjohn Technologies recrute pour ses services un Data Analyst. Cliquez sur le lien suivant pour postuler: https:\/\/join.philjohntech.com\/jobs\/apply\/data-analyst-46<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[22,1273],"tags":[3343,4,2967],"villes":[135],"contrats":[148],"diplomes":[212],"louma_meta":{"emploi_title":"Data Analyst","emplois_employeur":5859,"emplois_date_publication":"2021-07-31","emplois_heure_publication":"07:21","emplois_date_cloture":"2021-08-04","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"1","emploi_email":" https:\/\/join.philjohntech.com\/jobs\/apply\/data-analyst-46"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/18990"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=18990"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/18990\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/5892"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=18990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=18990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=18990"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=18990"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=18990"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=18990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}