{"id":18212,"date":"2021-07-21T09:36:38","date_gmt":"2021-07-21T07:36:38","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=18212"},"modified":"2021-07-21T09:36:40","modified_gmt":"2021-07-21T07:36:40","slug":"responsable-qhse-2","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/responsable-qhse-2\/","title":{"rendered":"RESPONSABLE QHSE"},"content":{"rendered":"\n<p><strong><br>OBJECTIFS DU POSTE<\/strong>&nbsp;:<\/p>\n\n\n\n<p>Rattach\u00e9 au chef departement QHSE, le Responsable QHSE a pour mission de :<\/p>\n\n\n\n<p>\u2022 Assurer la qualit\u00e9 et l\u2019innocuit\u00e9 des produits pour la satisfaction des clients par le respect des normes et r\u00e8glements<\/p>\n\n\n\n<p>\u2022 Assurer un niveau d\u2019hygi\u00e8ne appropri\u00e9 du site et le respect des exigences environnementales<\/p>\n\n\n\n<p>\u2022 Garantir la s\u00e9curit\u00e9 des personnes et des installations par la maitrise des risques<\/p>\n\n\n\n<p>\u2022 G\u00e9rer la documentation et sensibiliser le personnel \u00e0 l\u2019application<\/p>\n\n\n\n<p>\u2022 Assurer la mise en place et le suivi des syst\u00e8mes de management QHSE (ISO 9001, ISO 22000, ISO 14001,) \u2022 Assurer la veille normative, l\u00e9gale et r\u00e9glementaire ACTIVITES Coordonner les activit\u00e9s de contr\u00f4le et d\u2019assurance qualit\u00e9<\/p>\n\n\n\n<p>\u2022 Superviser la mise en \u0153uvre des plans de contr\u00f4le Qualit\u00e9 de la mati\u00e8re premi\u00e8re jusqu\u2019aux produits finis<\/p>\n\n\n\n<p>\u2022 Coordonner les activit\u00e9s Qualit\u00e9, Hygi\u00e8ne et S\u00e9curit\u00e9<\/p>\n\n\n\n<p>\u2022 Valider les r\u00e9sultats de contr\u00f4le et assurer la lib\u00e9ration des produits<\/p>\n\n\n\n<p>\u2022 Veiller au traitement appropri\u00e9 des produits non conformes incidents internes, fournisseurs ou clients<\/p>\n\n\n\n<p>\u2022 Assurer le traitement des r\u00e9clamations clients<\/p>\n\n\n\n<p>\u2022 Assurer le respect de la tra\u00e7abilit\u00e9<\/p>\n\n\n\n<p>\u2022 Assurer le suivi des actions d\u2019am\u00e9lioration Assurer un niveau d\u2019hygi\u00e8ne appropri\u00e9 et le respect des exigences environnementales<\/p>\n\n\n\n<p>\u2022 Assurer la mise en \u0153uvre et l\u2019efficacit\u00e9 des plans de nettoyage<\/p>\n\n\n\n<p>\u2022 Assurer le respect et l\u2019efficacit\u00e9 des plannings de nettoyage<\/p>\n\n\n\n<p>\u2022 Assurer la gestion ad\u00e9quate des d\u00e9chets sur le site (collecte s\u00e9lective, traitement, \u00e9limination, )<\/p>\n\n\n\n<p>\u2022 Assurer la mise en \u0153uvre du Plan de Gestion environnementale et sociale (PGES) et \u00e9tablir les rapports p\u00e9riodiques<\/p>\n\n\n\n<p><strong>SOUMISSION DE CANDIDATURE<\/strong><\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<strong>Minimum BAC + 3\/4 QHSE, Gestion de la Qualit\u00e9, HSE<\/strong><\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<strong>Curriculum vitae mis \u00e0 jour avec r\u00e9f\u00e9rences&nbsp;<\/strong>;<\/p>\n\n\n\n<p>Bien vouloir envoyer vos Curriculum vitae \u00e0 l\u2019adresse suivante&nbsp;:&nbsp;<strong>elkatanbtp@gmail.com<\/strong>&nbsp;avant le&nbsp;<strong>31 Juillet 2021<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elkatan recrute pour ses services un Responsable QHSE. Bien vouloir envoyer vos Curriculum vitae \u00e0 l\u2019adresse suivante : elkatanbtp@gmail.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[1139,1278],"tags":[3209,245,1271],"villes":[2714,135],"contrats":[148],"diplomes":[212,159],"louma_meta":{"emploi_title":"RESPONSABLE QHSE","emplois_employeur":3046,"emplois_date_publication":"2021-07-20","emplois_heure_publication":"08:33","emplois_date_cloture":"2021-07-31","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"elkatanbtp@gmail.com "},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/18212"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=18212"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/18212\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/9483"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=18212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=18212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=18212"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=18212"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=18212"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=18212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}