{"id":17526,"date":"2021-07-11T19:18:49","date_gmt":"2021-07-11T17:18:49","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=17526"},"modified":"2021-07-11T19:18:52","modified_gmt":"2021-07-11T17:18:52","slug":"responsable-departement-communication-h-f","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/responsable-departement-communication-h-f\/","title":{"rendered":"Responsable D\u00e9partement Communication H\/F"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.jobs.net\/jobs\/apave\/fr\/search\/\">Revenir aux r\u00e9sultats de recherche<\/a><\/p>\n\n\n\n<p>Responsable D\u00e9partement Communication H\/FLieu&nbsp;<\/p>\n\n\n\n<p>Douala,&nbsp;LittoralPubli\u00e9&nbsp;<\/p>\n\n\n\n<p>3 joursCat\u00e9gorie du poste&nbsp;<\/p>\n\n\n\n<p>Commercialisation &#8211; Communication, Transport \/ LogistiqueType de poste&nbsp;<\/p>\n\n\n\n<p>CDI &#8211; temps pleinExp\u00e9rience&nbsp;<\/p>\n\n\n\n<p>Non pr\u00e9cis\u00e9<a href=\"https:\/\/application.careerbuilder1.eu\/apave\/apply\/cb1\/J3M5RF67RVM0TP2LB66?IPath=TNJob&amp;Job_DID=J3M5RF67RVM0TP2LB66&amp;SiteID=ns_us_g_https%3A%2F%2Fwww.jobs.net%2F_&amp;VID=VX8dfcf1d03f9a11ebb0a1a1e817f40977272845&amp;sc_cmp1=JS_JobDetails_ApplyNow&amp;TN_DID=TNKD38560K16M285NSH4&amp;language=fr\">Postuler<\/a><\/p>\n\n\n\n<p>Description du posteR\u00e9f\u00e9rence :RES\/0721\/002574<\/p>\n\n\n\n<p>Type de contrat :&nbsp;CDI<\/p>\n\n\n\n<p>M\u00e9tier\/Sp\u00e9cialit\u00e9 :&nbsp;Transport \/ Logistique<\/p>\n\n\n\n<p>Localisation g\u00e9ographique :<br>Pays : Cameroun<br>Ville : Douala, R\u00e9gion du Littoral, CM<\/p>\n\n\n\n<p><strong>Notre soci\u00e9t\u00e9 :&nbsp;<\/strong><\/p>\n\n\n\n<p>Leader en recrutement sur le continent africain, Apave International vous propose chaque semaine de nombreuses opportunit\u00e9s de carri\u00e8re au sein d&rsquo;entreprises priv\u00e9es ou publiques et d&rsquo;Institutions Internationales.<\/p>\n\n\n\n<p><strong>Mission :&nbsp;<\/strong><\/p>\n\n\n\n<p>Le Responsable d\u00e9partement Communication \u00e9labore, pilote, met en \u0153uvre et \u00e9value la strat\u00e9gie de la communication de l&rsquo;entreprise ainsi que sa strat\u00e9gie de marque au niveau du pays. A ce titre, il d\u00e9finit les programmes de communication pour promouvoir l&rsquo;image de l&rsquo;entreprise vis \u00e0 vis des parties prenantes.<\/p>\n\n\n\n<p>Il aura sp\u00e9cifiquement la charge de:<\/p>\n\n\n\n<p>&#8211; La d\u00e9finition et le d\u00e9ploiement des programmes et activit\u00e9s de communication<\/p>\n\n\n\n<p>&#8211; Participer \u00e0 la d\u00e9finition de la strat\u00e9gie de communication et \u00e9pauler la direction g\u00e9n\u00e9rale sur les relations presse<\/p>\n\n\n\n<p>&#8211; Assurer la bonne diffusion des messages, programmes et r\u00e9alisations de l&rsquo;entreprise aupr\u00e8s de ses diff\u00e9rentes cibles internes et externes dans le cadre des activit\u00e9s<\/p>\n\n\n\n<p>&#8211; R\u00e9aliser une veille sur l&rsquo;entreprise et sur son environnement ext\u00e9rieur et conduire \u00e0 ce titre, les actions correctives de communication<\/p>\n\n\n\n<p>&#8211; \u00c9v\u00e8nementiel: Structurer la promotion de l&rsquo;image de marque de l&rsquo;entreprise par le biais de \u00e9v\u00e8nementiel et participer \u00e0 l&rsquo;organisation des salons, \u00e9v\u00e8nements internes&#8230;<\/p>\n\n\n\n<p>&#8211; Relations presse: Am\u00e9liorer la r\u00e9putation de l&rsquo;entreprise aupr\u00e8s du public \u00e0 travers les m\u00e9dias, mettre en perspective les outils de veille, de monitoring et de perspective de l&rsquo;environnement des m\u00e9dias, et produire les contenus (Note d&rsquo;information, communiqu\u00e9s de presse, dossier de presse)<\/p>\n\n\n\n<p>&#8211; Web et r\u00e9seaux sociaux: Cr\u00e9er des contenus pour les r\u00e9seaux sociaux, contribuer et mod\u00e9rer les r\u00e9seaux sociaux, assurer la mise \u00e0 jour des sites internet de l&rsquo;entreprise; suivre les outils statistiques de veille et de mesure<\/p>\n\n\n\n<p>&#8211; Studio\/cr\u00e9a: R\u00e9aliser des supports de communication \u00e9crite, audiovisuelle et digitale&#8230;<\/p>\n\n\n\n<p>&#8211; Engagements: Promouvoir la marque employeur en liaison avec la Direction des Ressources Humaines, les actions de responsabilit\u00e9 soci\u00e9tale et de m\u00e9c\u00e9nat de la soci\u00e9t\u00e9.<\/p>\n\n\n\n<p><strong>Profil :&nbsp;<\/strong><\/p>\n\n\n\n<p>&#8211; Titulaire d&rsquo;un dipl\u00f4me de niveau Bac+4 minimum en Sciences et Techniques de l&rsquo;information et de la communication ou tout autre dipl\u00f4me \u00e9quivalent d&rsquo;une \u00e9cole sp\u00e9cialis\u00e9e<\/p>\n\n\n\n<p>&#8211; Au moins 05 ann\u00e9es d&rsquo;exp\u00e9rience r\u00e9ussie en journalisme\/Communication en entreprise ou au sein d&rsquo;un m\u00e9dia \u00e0 la r\u00e9putation \u00e9tablie<\/p>\n\n\n\n<p>&#8211; Maitrise des outils Powerpoint, Excel, Logiciels de PAO-vid\u00e9o<\/p>\n\n\n\n<p>&#8211; Management d&rsquo;\u00e9quipe<\/p>\n\n\n\n<p>&#8211; Parfaitement Bilingue Anglais-Fran\u00e7ais<\/p>\n\n\n\n<p>Niveau d&rsquo;\u00e9tudes : MAITRISE \/ BAC+4<\/p>\n\n\n\n<p>Sp\u00e9cialisation :&nbsp;Marketing \/ Communication \/ RP \/ Journalisme<\/p>\n\n\n\n<p>Niveau d&rsquo;exp\u00e9rience :&nbsp;Exp\u00e9riment\u00e9 (de 6 \u00e0 10 ans)<\/p>\n\n\n\n<p>Langues :&nbsp;<br>Fran\u00e7ais&nbsp;:&nbsp;Ma\u00eetrise courante<br>Anglais&nbsp;:&nbsp;Ma\u00eetrise courante<\/p>\n\n\n\n<p>Crit\u00e8res du poste<\/p>\n\n\n\n<p>&#8211; Titulaire d&rsquo;un dipl\u00f4me de niveau Bac+4 minimum en Sciences et Techniques de l&rsquo;information et de la communication ou tout autre dipl\u00f4me \u00e9quivalent d&rsquo;une \u00e9cole sp\u00e9cialis\u00e9e<\/p>\n\n\n\n<p>&#8211; Au moins 05 ann\u00e9es d&rsquo;exp\u00e9rience r\u00e9ussie en journalisme\/Communication en entreprise ou au sein d&rsquo;un m\u00e9dia \u00e0 la r\u00e9putation \u00e9tablie<\/p>\n\n\n\n<p>&#8211; Maitrise des outils Powerpoint, Excel, Logiciels de PAO-vid\u00e9o<\/p>\n\n\n\n<p>&#8211; Management d&rsquo;\u00e9quipe<\/p>\n\n\n\n<p>&#8211; Parfaitement Bilingue Anglais-Fran\u00e7ais<a href=\"https:\/\/application.careerbuilder1.eu\/apave\/apply\/cb1\/J3M5RF67RVM0TP2LB66?IPath=TNJob&amp;Job_DID=J3M5RF67RVM0TP2LB66&amp;SiteID=ns_us_g_https%3A%2F%2Fwww.jobs.net%2F_&amp;VID=VX8dfcf1d03f9a11ebb0a1a1e817f40977272845&amp;sc_cmp1=JS_JobDetails_ApplyNow&amp;TN_DID=TNKD38560K16M285NSH4&amp;language=fr\">Postuler<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Revenir aux r\u00e9sultats de recherche Responsable D\u00e9partement Communication H\/FLieu&nbsp; Douala,&nbsp;LittoralPubli\u00e9&nbsp; 3 joursCat\u00e9gorie du poste&nbsp; Commercialisation &#8211; Communication, Transport \/ LogistiqueType de poste&nbsp; CDI &#8211; temps&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[25],"tags":[],"villes":[136],"contrats":[234],"diplomes":[212],"louma_meta":{"emploi_title":"Responsable D\u00e9partement Communication H\/F","emplois_employeur":2981,"emplois_date_publication":"2021-07-11","emplois_heure_publication":"","emplois_date_cloture":"2021-07-31","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"3","emploi_email":"https:\/\/application.careerbuilder1.eu\/apave\/apply\/cb1\/J3M5RF67RVM0TP2LB66?IPath=TNJob&Job_DID=J3M5RF67RVM0TP2LB66&SiteID=ns_us_g_https%3A%2F%2Fwww.jobs.net%2F_&VID=VX8dfcf1d03f9a11ebb0a1a1e817f40977272845&sc_cmp1=JS_JobDetails_ApplyNow&TN_DID=TNKD38560K16M285NSH4&language=fr"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/17526"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=17526"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/17526\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/2982"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=17526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=17526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=17526"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=17526"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=17526"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=17526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}