{"id":17516,"date":"2021-07-10T15:24:34","date_gmt":"2021-07-10T13:24:34","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=17516"},"modified":"2021-07-10T15:24:37","modified_gmt":"2021-07-10T13:24:37","slug":"un-assistant-comptable","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/un-assistant-comptable\/","title":{"rendered":"Un Assistant Comptable"},"content":{"rendered":"\n<p>Contexte et justification : Une importante entreprise bas\u00e9e \u00e0 Douala, op\u00e9rant dans le secteur commercial, notamment dans la repr\u00e9sentation et la distribution des grandes marques des produits cosm\u00e9tiques et alimentaires de notori\u00e9t\u00e9 reconnue, recherche pour ses besoins de service <strong>Un Assistant Comptable <\/strong><\/p>\n\n\n\n<p>Lieu d&rsquo;ex\u00e9cution du contrat : Douala <\/p>\n\n\n\n<p>Type de contrat : CDD avec p\u00e9riode d&rsquo;essai <\/p>\n\n\n\n<p>Liens hi\u00e9rarchiques: N+1: Chef Comptable Salaire: \u00e0 N\u00e9gocier <\/p>\n\n\n\n<p>Missions: Assister le Chef Comptable dans toutes les activit\u00e9s comptables et fiscales de l&rsquo;entreprise <\/p>\n\n\n\n<p>Responsabilit\u00e9s : <\/p>\n\n\n\n<p>-Classement, imputation et saisie des op\u00e9rations dans Sage comptabilit\u00e9 suivant les nouvelles normes du SYSCOHADA <\/p>\n\n\n\n<p>-Traitement des op\u00e9rations courantes, achats, ventes, caisses, etc. <br><br>-Gestion du stock, suivi et analyse des inventaires<\/p>\n\n\n\n<p> -Etablissement des rapprochements bancaires <\/p>\n\n\n\n<p>-Classement et archivage des documents comptables et financiers <\/p>\n\n\n\n<p>-Suivi des arr\u00eats caisses <\/p>\n\n\n\n<p>Participation aux inventaires de stocks <\/p>\n\n\n\n<p>Autres t\u00e2ches confi\u00e9es par la hi\u00e9rarchie <\/p>\n\n\n\n<p>Profil requis Etre titulaire au minimum d&rsquo;un Bac + 3 en Comptabilit\u00e9 et finance, ou administration d&rsquo;entreprises <\/p>\n\n\n\n<p>Avoir au minimum deux(02) ans d&rsquo;exp\u00e9rience dans un service de la comptabilit\u00e9, de pr\u00e9f\u00e9rence dans le secteur de la grande distribution <\/p>\n\n\n\n<p>Maitriser les logiciels de comptabilit\u00e9 SAGE Compta 100, Sage Gescom, <\/p>\n\n\n\n<p>Ma\u00eetriser les logiciels bureautiques (word, excel, powerpoint) Etre \u00e0 l&rsquo;aise dans les chiffres et l&rsquo;interpr\u00e9tation des donn\u00e9es <\/p>\n\n\n\n<p>Poss\u00e9der de bonnes aptitudes en communication, relations interpersonnelles <\/p>\n\n\n\n<p>Avoir une bonne capacit\u00e9 d&rsquo;analyse, de synth\u00e8se, un sens de l&rsquo;observation et de l&rsquo;\u00e9coute <\/p>\n\n\n\n<p>Etre autonome, organis\u00e9 avec un go\u00fbt du travail en \u00e9quipe Etre apte \u00e0 travailler sous pression. <br><br>Constitution du dossier : CV, Lettre de motivation, copie du dipl\u00f4me, justificatifs de l&rsquo;exp\u00e9rience (certificats de travail et\/ou attestation d&#8217;emploi) et copie de la CNI <\/p>\n\n\n\n<p>D\u00e9p\u00f4t des dossiers de candidature &amp; date limite de recevabilit\u00e9 : Dossier complet \u00e0 envoyer par mail \u00e0 l&rsquo;adresse suivante : fredy.mvondo@qbafrica.fr <\/p>\n\n\n\n<p>Date limite de recevabilit\u00e9 des dossiers : le 12 Juillet 2021 \u00e0 12 heures pr\u00e9cises NB: Seuls les candidats pr\u00e9s\u00e9lectionn\u00e9s seront contact\u00e9s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Contexte et justification : Une importante entreprise bas\u00e9e \u00e0 Douala, op\u00e9rant dans le secteur commercial, notamment dans la repr\u00e9sentation et la distribution des grandes marques&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[282],"tags":[],"villes":[136],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Un Assistant Comptable ","emplois_employeur":3046,"emplois_date_publication":"2021-07-10","emplois_heure_publication":"","emplois_date_cloture":"2021-07-12","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"3","emploi_email":"fredy.mvondo@qbafrica.fr "},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/17516"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=17516"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/17516\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/9483"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=17516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=17516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=17516"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=17516"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=17516"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=17516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}