{"id":17301,"date":"2021-07-07T08:23:57","date_gmt":"2021-07-07T06:23:57","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=17301"},"modified":"2021-07-07T08:24:01","modified_gmt":"2021-07-07T06:24:01","slug":"consultant-pour-le-renforcement-des-capacites","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/consultant-pour-le-renforcement-des-capacites\/","title":{"rendered":"Consultant pour le Renforcement des Capacit\u00e9s"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\":1x\">APPEL D&rsquo;OFFRE RECRUTEMENT D&rsquo;UN CONSULTANT POUR LE RENFORCEMENT DES CAPACITES DES MEMBRES DES EXECUTIFS COMMUNAUX DES QUATRES COMMUNES DU DISTRICT DE SANTE D&rsquo;ABONG-MBANG<\/h2>\n\n\n\n<p>\u00a0<br>\u00a0<br>\u00a0<br><strong>\u00a0TERMES DE REFERENCE DE RECRUTEMENT D\u2019UN CONSULTANT POUR LE<\/strong><br><br><strong>\u00a0\u00a0\u00a0\u00a0 RENFORCEMENT DES CAPACITES DES MEMBRES DES EXECUTIFS<\/strong><br><strong>\u00a0COMMUNAUX DES QUATRES COMMUNES DU DISTRICT DE SANTE D\u2019ABONG-<\/strong><br><br><strong>\u00a0MBANG SUR LE LEADERSHIP COMMUNAL EN MATIERE DE SANTE ET SANTE<\/strong><br><strong>COMMUNAUTAIRE AFIN \u00a0\u00a0\u00a0 \u00a0D\u2019ASSURER LA GESTION EFFICACE DES PROBLEMES<\/strong><br><br><strong>DE SANTE ET LA CAPITALISATION DES ACQUIS DU PROJET BAKA<\/strong><br>\u00a0<br>\u00a0<br><br><strong>I- CONTEXTE ET JUSTIFICATION<\/strong><\/p>\n\n\n\n<p><strong>1.1. \u00a0\u00a0\u00a0 Description de l\u2019organisation de mise en \u0153uvre : FAIRMED\u00a0<\/strong><br>\u00a0<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La Fondation FAIRMED, pr\u00e9sente au Cameroun depuis 1959 est une organisation internationale de d\u00e9veloppement qui milite pour un monde o\u00f9 personne ne devrait souffrir ou mourir d\u2019une maladie curable. Elle contribue depuis lors \u00e0 am\u00e9liorer l&rsquo;acc\u00e8s aux soins de sant\u00e9 pour les communaut\u00e9s et les individus marginalis\u00e9s. Il s\u2019agit des personnes vivant dans des zones enclav\u00e9es en raison de leur pauvret\u00e9 ou de leur stigmatisation associ\u00e9e \u00e0 leur \u00e9tat, principalement des personnes atteintes de maladies tropicales n\u00e9glig\u00e9es (L\u00e8pre, Ulc\u00e8re de BURULI, pian, leishmaniose etc\u2026), de la jeune m\u00e8re, de l\u2019enfant, et des personnes vivant avec le handicap. \u00a0<br>\u00a0<br>Le Bureau FAIRMED Cameroun est une unit\u00e9 d\u00e9centralis\u00e9e de la Fondation. Il g\u00e8re le volet op\u00e9rationnel des projets sur l\u2019ensemble du territoire camerounais. FAIRMED encourage l\u2019accumulation du savoir-faire sur place en tant qu\u2019\u00e9l\u00e9ment le plus important pour garantir le caract\u00e8re durable de ses interventions. \u00a0<br>\u00a0<br>Pour mener \u00e0 bien ses missions, FAIRMED agit sur plusieurs d\u00e9terminants de la sant\u00e9 (sociaux, \u00e9conomiques etc\u2026) ce qui lui permet de travailler en partenariat avec plusieurs sectoriels et acteurs locaux que sont ; les Communes, certains minist\u00e8res avec leurs structures d\u00e9concentr\u00e9es (DDAS, DS etc\u2026)\u00a0 et les associations locales. \u00a0<\/p>\n\n\n\n<p><strong>1.2. \u00a0\u00a0\u00a0 La vision de FAIRMED<\/strong><br>Personne ne devrait souffrir ni mourir d\u2019une maladie curable.<br>Nous voulons que TOUTES les personnes aient un acc\u00e8s \u00e9quitable \u00e0 la pr\u00e9vention et \u00e0 des soins de sant\u00e9 acceptables, d\u2019une qualit\u00e9 satisfaisante \u00e0 un co\u00fbt abordable ; et b\u00e9n\u00e9ficient d\u2019un environnement sain marqu\u00e9 par l\u2019\u00e9quit\u00e9 sociale. \u00a0<br>\u00a0<br><strong>1.3. \u00a0\u00a0\u00a0 Description du projet BAKA phase III<\/strong><br>\u00a0<br>\u00a0\u00a0 Depuis 2008, la Fondation FAIRMED soutient le d\u00e9veloppement du District de Sant\u00e9 d\u2019Abong Mbang, en particulier le d\u00e9veloppement des populations autochtones BAKA \u00e0 travers le Projet BAKA.<br>\u00a0<br>La nouvelle phase du projet a vu le jour gr\u00e2ce aux avanc\u00e9es constat\u00e9es dans les phases 1 et 2 : le changement de comportement par les Baka, l\u2019am\u00e9lioration de la participation communautaire et l\u2019acc\u00e8s aux soins de sant\u00e9 \u00e0 travers les mutuelles de sant\u00e9. L\u2019\u00e9valuation externe de la deuxi\u00e8me phase a cependant permis de relever certaines faiblesses tout en recommandant le d\u00e9veloppement d\u2019une troisi\u00e8me phase.<br>\u00a0<br>La prochaine phase de ce projet 2019 &#8211; 2023 repr\u00e9sente un nouveau d\u00e9part qui r\u00e9pondra diff\u00e9remment aux probl\u00e8mes de sant\u00e9 des populations vuln\u00e9rables dont l\u2019on peut, entre autres, citer : \u00a0<br>&#8211;\u00a0\u00a0\u00a0 La faible participation communautaire,\u00a0<br>&#8211;\u00a0\u00a0\u00a0 Le faible acc\u00e8s aux soins et\u00a0<br>&#8211;\u00a0\u00a0\u00a0 La faible coordination \/ leadership de l\u2019ex\u00e9cutif communal en mati\u00e8re de sant\u00e9.<br>\u00a0<br>Le Projet d\u2019Am\u00e9lioration de l\u2019Etat Sanitaire des Populations Vuln\u00e9rables du District de Sant\u00e9 d\u2019Abong-Mbang encore appel\u00e9 \u00ab Projet BAKA \u00bb dans sa phase III se d\u00e9roule au Cameroun, dans la r\u00e9gion de l\u2019EST, dans le d\u00e9partement du Haut-Nyong r\u00e9parti en 14 arrondissements dont quatre (Abong-Mbang, Bebend, Boanz et DJA) composent le district de sant\u00e9 d\u2019Abong-Mbang o\u00f9 le projet Baka est mis en \u0153uvre.\u00a0\u00a0 \u00a0<br>\u00a0<br>Cette nouvelle phase du projet permettra \u00e0 FAIRMED de transf\u00e9rer les acquis et comp\u00e9tences aux populations Baka qui sont les principaux b\u00e9n\u00e9ficiaires, et aux communes, principaux partenaires et gages de la continuit\u00e9 et de la capitalisation des acquis du projet.<br>\u00a0<br>Un accent particulier sera notamment mis sur l\u2019implication effective des populations vuln\u00e9rables telle que les Baka et Bantu pauvres dans les processus et comit\u00e9s de prise de d\u00e9cision dans les diff\u00e9rents domaines du projet, car elles y sont le plus souvent exclues. Le renforcement des capacit\u00e9s de la communaut\u00e9 Baka sera un axe important du projet qui permettra aux Baka de prendre les d\u00e9cisions pour am\u00e9liorer leur sant\u00e9.\u00a0 \u00a0<br>\u00a0<br>Conscient de l\u2019in\u00e9galit\u00e9 des ressources, d\u2019opportunit\u00e9s et de contraintes entre les communes du District de sant\u00e9 d\u2019Abong-Mbang, le projet s\u2019attachera, en fonction du contexte \u00e0 : \u00a0<br>&#8211;\u00a0\u00a0\u00a0 Accompagner les Communes \u00e0 rendre fonctionnel le d\u00e9partement ou service de sant\u00e9 ou commission sant\u00e9-sociale destin\u00e9 \u00e0 accompagner les communes dans la gestion des probl\u00e8mes de sant\u00e9, de la sant\u00e9 communautaire et de la sant\u00e9 tout cours.<br>&#8211;\u00a0\u00a0\u00a0 Elaborer une strat\u00e9gie de mobilisation et de mise en commun des ressources financi\u00e8res et humaines pour le renforcement du leadership communal en mati\u00e8re de sant\u00e9, selon le processus de d\u00e9centralisation en cours au Cameroun.<br>\u00a0<br>Il est donc envisag\u00e9 au cours de la troisi\u00e8me phase de ce projet, un transfert de comp\u00e9tences aux Communes pour que le leadership communal en mati\u00e8re de sant\u00e9 communautaire, de gestion de sant\u00e9, gestion et coordination de partenariat soit renforc\u00e9. Le but est une gestion durable des probl\u00e8mes de sant\u00e9 des populations et leur permettre de prendre toutes leurs responsabilit\u00e9s en vue d\u2019une meilleure durabilit\u00e9 des acquis du projet \u00e0 travers : \u00a0<br>&#8211;\u00a0\u00a0\u00a0 L\u2019\u00e9valuation des besoins de renforcement institutionnel et organisationnel des quatre Communes du District de sant\u00e9 d\u2019Abong-Mbang et des structures de dialogue au niveau communautaire ;<br>&#8211;\u00a0\u00a0\u00a0 L\u2019autonomisation les structures de dialogue de chaque Commune \u00e0 travers leur redynamisation ; la tenue de leurs assembl\u00e9es g\u00e9n\u00e9rales ordinaires ; le d\u00e9veloppement des AGR, leur l\u00e9galisation en tant qu\u2019entit\u00e9 qui repr\u00e9sente la communaut\u00e9 aupr\u00e8s de la Commune pour parler des questions de sant\u00e9 des communaut\u00e9s ;<br>&#8211;\u00a0\u00a0\u00a0 La mise sur pied d\u2019un m\u00e9canisme de prise en charge des urgences m\u00e9dicales des indigents et des n\u00e9cessiteux dans le District de sant\u00e9 d\u00e9nomm\u00e9 MEPUMIN<br>&#8211;\u00a0\u00a0\u00a0 Le renforcement de la collaboration multisectorielle des parties prenantes au d\u00e9veloppement des populations vuln\u00e9rables du District de Sant\u00e9 d\u2019Abong-Mbang en assurant la mise sur pied d\u2019un cadre de partenariat de la sant\u00e9 pour y promouvoir la sant\u00e9 et le sociale et, partant, garantir un acc\u00e8s \u00e9quitable aux soins de sant\u00e9 \u00e0 toutes les couches sociales pour une meilleure contribution \u00e0 l\u2019atteinte des objectifs nationaux et internationaux en mati\u00e8re de sant\u00e9 (ODD, DSCE).\u00a0<br>&#8211;\u00a0\u00a0\u00a0 Le renforcement de capacit\u00e9s des ex\u00e9cutifs communaux sur le leadership communal en mati\u00e8re de sant\u00e9 et sant\u00e9 communautaire pour la coordination du cadre de partenariat et assurer la gestion efficace des questions de sant\u00e9.<br>\u00a0<br>Il sera question de former des ex\u00e9cutifs communaux du District de Sant\u00e9 d\u2019Abong-Mbang en leadership sant\u00e9 pour l\u2019appropriation des actions du projet d\u00e9j\u00e0 men\u00e9es ou engag\u00e9es et de d\u00e9velopper leurs potentiels de leadership sanitaire, afin qu\u2019ils deviennent des acteurs qui participent activement \u00e0 la mise en \u0153uvre du projet et le p\u00e9rennisent. Les membres de l\u2019ex\u00e9cutif communal sont des personnes politiques dont la pr\u00e9sence au sein de la commune est conditionn\u00e9e par le succ\u00e8s aux \u00e9lections. Pour une plus grande durabilit\u00e9 de ce leadership au sein de la commune, il est important que cette formation soit \u00e9tendue aux agents communaux qui eux, ont des contrats qui vont au-del\u00e0 des mandats des \u00e9lus.\u00a0 \u00a0<br>\u00a0<strong>1.4. R\u00e9sum\u00e9 des r\u00e9sultats de l\u2019\u00e9valuation des besoins de renforcement institutionnel et organisationnel des quatre Communes du District de sant\u00e9 d\u2019Abong-Mbang \u00a0<\/strong><br>\u00a0<br>a. Capacit\u00e9s des Communes \u00e0 conduire les projets de sant\u00e9<br>\u00a0<br>La gestion des projets au sein des Communes du District de Sant\u00e9 d\u2019Abong-Mbang est caract\u00e9ris\u00e9e par une faible capacit\u00e9 tant num\u00e9rique qu\u2019en termes de capacit\u00e9 technique et organisationnelles de gestion de cycle de projet en g\u00e9n\u00e9ral.<br>\u00a0<br>Pour ce qui est de la gestion sp\u00e9cifique des projets de sant\u00e9, le ratio passe \u00e0 moins de 01 personnel par commune avec notamment 01 personnel pas forc\u00e9ment sp\u00e9cialis\u00e9 dans le domaine de la sant\u00e9 respectivement pour les communes de Mindourou et d\u2019Atok et l\u2019absence de personnel sp\u00e9cialis\u00e9 pour les Communes d\u2019Angossas et d\u2019Abong-Mbang, ce qui parait insuffisant compte tenu du volume d\u2019activit\u00e9 li\u00e9 \u00e0 l\u2019identification, le montage et le suivi des projets communaux en g\u00e9n\u00e9ral et les projets de sant\u00e9 en particulier. Ce qui peut d\u2019ailleurs expliquer la sollicitation des services d\u00e9concentr\u00e9s de l\u2019\u00e9tat, les structures d\u2019accompagnement ou encore les consultants pour la r\u00e9alisation des diff\u00e9rentes phases de la gestion de projets communaux. Dans certains cas (Mindourou notamment), la commune s\u2019appuie sur les comit\u00e9s de d\u00e9veloppement pour identifier les projets. Ces derniers n\u2019ayant pas toujours les moyens techniques, financiers et mat\u00e9riels pour r\u00e9aliser cette t\u00e2che. Le m\u00eame constat s\u2019\u00e9tend au plaidoyer et la mobilisation des ressources pour le financement des projets de sant\u00e9. Cette activit\u00e9 n\u2019est d\u2019ailleurs men\u00e9e dans aucune des quatre communes concern\u00e9es.<br>\u00a0<br>Sur le plan des comp\u00e9tences techniques, il a \u00e9t\u00e9 not\u00e9 que l\u2019ensemble des personnels des quatre communes ont des comp\u00e9tences essentiellement tir\u00e9es de la pratique de terrain. Aucun des personnel n \u2018ayant re\u00e7u une formation initiale ou continue dans un domaine relatif \u00e0 la gestion de projets communaux en g\u00e9n\u00e9ral et la gestion des projets de sant\u00e9 en particulier.<br>\u00a0<br>Pour ce qui est des capacit\u00e9s organisationnelles, deux Communes sur les quatre, notamment les communes de Mindourou et d\u2019Atok disposent de services des affaires sociales au sein desquels sont trait\u00e9es accessoirement les questions de sant\u00e9. En effet, c\u2019est toujours le social qui pr\u00e9domine sur la sant\u00e9.<br>\u00a0<br>b.\u00a0\u00a0\u00a0 Participation communautaire et accompagnement des structures de dialogue du District de sant\u00e9 d\u2019Abong-Mbang par les Communes<br>\u00a0<br>Il ressort de cette \u00e9valuation que les communes ne participent pas aux activit\u00e9s des structures de dialogue dans l\u2019espace communal, notamment les COSA. Toutefois la commune est repr\u00e9sent\u00e9e dans les structures de dialogue au niveau du District de sant\u00e9. Cette situation pose entre autres, quelques probl\u00e8mes majeurs, notamment l\u2019exercice\/appropriation du transfert des comp\u00e9tences en mati\u00e8re de sant\u00e9 aux communes par l\u2019Etat et la coordination des structures de dialogue dont l\u2019absence se fait ressentir dans le fonctionnement quotidien de ces derni\u00e8res.<br>Les commues ne comprennent pas bien l\u2019importance de la sant\u00e9 communautaire, ni l\u2019int\u00e9r\u00eat de soutenir les structures de dialogue. Les communes per\u00e7oivent la sant\u00e9 seulement sur les aspects techniques, \u00e0 savoir : les infrastructures, les \u00e9quipements, les m\u00e9dicaments et les soins. Les aspects de sant\u00e9 communautaire ne sont en g\u00e9n\u00e9ral pas per\u00e7us comme \u00e9tant importants par les communes. Le District de sant\u00e9 n\u2019a pas men\u00e9 de plaidoyer aupr\u00e8s des communes pour que la situation change.\u00a0 \u00a0<br>\u00a0<br>En effet, bien que d\u00e9sormais charg\u00e9e de g\u00e9rer les questions de sant\u00e9 dans leurs espaces respectifs, les communes ne s\u2019approprient pas encore leur r\u00f4le. Ce qui a abouti \u00e0 une situation o\u00f9 jusqu\u2019\u00e0 date, toutes les structures de dialogue sont coordonn\u00e9es par le District de Sant\u00e9, y compris les COSA et COGE (Comit\u00e9 de gestion) qui est pourtant au niveau communal. L\u2019organisation communale gagnerait \u00e0 int\u00e9grer ces aspects de fa\u00e7on formelle. La question de l\u2019autonomie financi\u00e8re des COSA devrait \u00e9galement \u00eatre prise en compte dans l\u2019organisation communal.<br>\u00a0<br>c.\u00a0\u00a0\u00a0 Synergie entre les structures de dialogue, la commune et les services de sant\u00e9 de district La synergie entre les structures de dialogue au sein des communes est presque inexistante. Les seules vell\u00e9it\u00e9s de collaboration ont \u00e9t\u00e9 observ\u00e9es dans la commune de Mindourou ou les COSA de Mindourou et de Djaposten invitent la Commune lors de leurs assembl\u00e9es g\u00e9n\u00e9rales.<br>\u00a0<br>d.\u00a0\u00a0\u00a0 Proposition d\u2019un dispositif et m\u00e9canisme de fonctionnement qui permettra aux communes d\u2019engager tous les acteurs locaux de collaborer et \u0153uvrer en synergie pour la gestion des probl\u00e8mes de sant\u00e9 avec pour pivot la commune.<br>\u00a0<br>Le dispositif propos\u00e9 dans le cadre de cette \u00e9tude repose sur la d\u00e9marche suivante :<br>\u2022\u00a0\u00a0\u00a0 R\u00e9forme des organigrammes communaux en y int\u00e9grant une participation des COSA aux activit\u00e9s des commissions communales comp\u00e9tente au sein des conseils municipaux. Pour ce qui est des services communaux, un service sant\u00e9 devrait voir le jour dans chaque commune avec la structuration minimale suivante : un chef service accompagn\u00e9 d\u2019une unit\u00e9 infrastructures et \u00e9quipement, une unit\u00e9 sant\u00e9 communautaire (point focal communal), une unit\u00e9 partenariat sant\u00e9 et mobilisation des ressources, (recommandation \u00e9galement valid\u00e9e au cours de l\u2019atelier de restitution de l\u2019\u00e9valuation).\u00a0<br>\u2022\u00a0\u00a0\u00a0 Recrutement du personnel (notamment sant\u00e9 pour chaque commune et chef de service)<br>\u2022\u00a0\u00a0\u00a0 Renforcement des capacit\u00e9s du personnel communal et des autres acteurs (conseil municipal, ex\u00e9cutif communal)<br>\u2022\u00a0\u00a0\u00a0 Les COSA pourront int\u00e9grer\/activer le poste de partenariat et mobilisation des ressources pour le financement des plans d\u2019action d\u00fbment \u00e9labor\u00e9s avec l\u2019accompagnement du point focal communal en charge de la sant\u00e9 qui pourra \u00e9galement se charger du partenariat avec la commune et les autres acteurs ou partenaires.<br>\u00a0<br>Sans \u00eatre exhaustifs, les modules de renforcement des capacit\u00e9s des acteurs communaux propos\u00e9es lors de cette \u00e9valuation pourraient \u00eatre d\u00e9clin\u00e9s en :<br>\u2022\u00a0\u00a0\u00a0 Gestion de cycle de projet de sant\u00e9 (identification, planification, suivi \u00e9valuation) ;<br>\u2022\u00a0\u00a0\u00a0 Sant\u00e9 communautaire ;<br>\u2022\u00a0\u00a0\u00a0 Technique de plaidoyer et de mobilisation des ressources pour le financement des projets de sant\u00e9 ;<br>\u2022\u00a0\u00a0\u00a0 Connaissance et compr\u00e9hension des textes sur la sant\u00e9 communautaire et l\u2019accompagnement des COSA ;<br>\u2022\u00a0\u00a0\u00a0 Transfert des comp\u00e9tences aux CTD et Leadership communal en mati\u00e8re de sant\u00e9. <\/p>\n\n\n\n<p><strong>II- OBJECTIFS DE LA FORMATION<\/strong><br><br><strong>a.\u00a0\u00a0\u00a0 Objectif g\u00e9n\u00e9ral :<\/strong><br>Renforcer les capacit\u00e9s des ex\u00e9cutifs communaux du District de Sant\u00e9 d\u2019Abong-Mbang en leadership pour une gestion efficace des probl\u00e8mes de sant\u00e9 et des acquis d\u2019exp\u00e9riences du projet BAKA.<br>b.\u00a0\u00a0\u00a0 Objectifs sp\u00e9cifiques du consultant :<br>Quant aux objectifs sp\u00e9cifiques de la formation, ce sont les suivants :<br>&#8211;\u00a0\u00a0\u00a0 Renforcer les capacit\u00e9s des communes en :<br>\u2022\u00a0\u00a0\u00a0 Gestion de cycle de projet de sant\u00e9 (identification, planification, suivi \u00e9valuation) ax\u00e9 sur les gestions des acquis d\u2019exp\u00e9riences du projet BAKA ;\u00a0<br>\u2022\u00a0\u00a0\u00a0 Gestion de sant\u00e9 publique option Sant\u00e9 communautaire au sein de la commune : Connaissances et compr\u00e9hensions des textes sur la sant\u00e9 communautaire et l\u2019accompagnement des structures de dialogue ;<br>\u2022\u00a0\u00a0\u00a0 Technique de plaidoyer et strat\u00e9gie de mobilisation ou mise en commun des ressources pour le financement des projets de sant\u00e9 ;<br>\u2022\u00a0\u00a0\u00a0 Leadership communal et les comp\u00e9tences transf\u00e9r\u00e9es aux CTD en mati\u00e8re de sant\u00e9.<br>&#8211;\u00a0\u00a0\u00a0 Amener les communes dans le contexte de d\u00e9centralisation via les maires et les conseillers municipaux \u00e0 int\u00e9grer la gestion de ressources humaines dans les aspects th\u00e9oriques et pratiques et \u00e0 rendre fonctionnel le d\u00e9partement ou service de sant\u00e9 ou commission sant\u00e9-sociale destin\u00e9 \u00e0 accompagner les communes dans la gestion de la sant\u00e9 communautaire et de la sant\u00e9 tout cours ;<br>&#8211;\u00a0\u00a0\u00a0 Monter des projets \u00e0 l\u2019issue des formations qui seraient ax\u00e9s sur la capitalisation des acquis d\u2019exp\u00e9rience du projet BAKA.<br>c. Activit\u00e9s du consultant\u00a0 \u00a0<br>1-\u00a0\u00a0\u00a0 Proposition et pr\u00e9paration des crit\u00e8res et questions d\u2019\u00e9valuation (pr\u00e9\/post test), la m\u00e9thodologie d\u2019\u00e9valuation (pr\u00e9\/post test et la m\u00e9thodologie) les outils et la pr\u00e9sentation des r\u00e9sultats d\u2019\u00e9valuation ;<br>2-\u00a0\u00a0\u00a0 Faire un briefing sur le chronogramme pour le d\u00e9roulement des activit\u00e9s de formation et sur le processus de formation avec l\u2019\u00e9quipe FAIRMED Abong-Mbang pour validation ; 3- Proposer les modules de formations et de sessions pratiques ; 4- R\u00e9daction du rapport de formation.<br>\u00a0<br><strong>III-\u00a0\u00a0\u00a0 METHODOLOGIE<\/strong><br>\u00a0<br>Les m\u00e9thodologies seront d\u00e9termin\u00e9es par le Consultant retenu pour effectuer ce travail. Le consultant ou l\u2019\u00e9quipe d\u2019experts devra faire un briefing avec l\u2019\u00e9quipe projet BAKA sur le processus de conduite de la mission.<\/p>\n\n\n\n<p><strong>IV-\u00a0\u00a0\u00a0 RESULTAT ET PRODUITS ATTENDUS<\/strong><br><br><strong>4.1 : R\u00e9sultat attendu \u00a0<\/strong><br>Le principal r\u00e9sultat attendu est le renforcement des capacit\u00e9s des ex\u00e9cutifs communaux du District de Sant\u00e9 d\u2019Abong-Mbang en leadership pour une gestion efficace des probl\u00e8mes de sant\u00e9 et des acquis d\u2019exp\u00e9riences du projet BAKA.<br>Les autres r\u00e9sultats attendus sont :<br>\u00a0 Les ex\u00e9cutifs communaux comprennent la gestion de cycle de projet de sant\u00e9<br>(identification, planification, suivi \u00e9valuation) ax\u00e9 sur les acquis d\u2019exp\u00e9riences du projet BAKA ; \u00a0<br>\u00a0 Les connaissances et compr\u00e9hensions des textes sur la sant\u00e9 communautaire et l\u2019accompagnement des structures de dialogue par le Commune sont connues ;<br>\u00a0 Pour le financement des projets de sant\u00e9, les techniques de plaidoyer et les strat\u00e9gies de mobilisation ou mise en commun des ressources sont connus par les ex\u00e9cutifs communaux ;<br>\u00a0 Un rappel sur le leadership communal et les comp\u00e9tences transf\u00e9r\u00e9es aux CTD en mati\u00e8re de sant\u00e9 est fait.<br>\u00a0 Les communes dans le contexte de d\u00e9centralisation via les ex\u00e9cutifs communaux form\u00e9s facilitent le fonctionnement d\u2019un service de sant\u00e9 ou commission sant\u00e9-sociale et la mise \u00e0 disposition des ressource humaines ad\u00e9quates.<br>\u00a0 Les ex\u00e9cutifs communaux sont capacit\u00e9s au montage des projets \u00e0 l\u2019issue de la formation. \u00a0<br>\u00a0<br><strong>4.2. Produits attendus et livrables<\/strong><br><br><strong>Les produits attendus sont les suivants :<\/strong><br>&#8211;\u00a0\u00a0\u00a0 Une note m\u00e9thodologique d\u00e9taill\u00e9e ;<br>&#8211;\u00a0\u00a0\u00a0 Un questionnaire d\u2019\u00e9valuation (pr\u00e9\/post test) de la formation ;<br>&#8211;\u00a0\u00a0\u00a0 Un programme d\u00e9taill\u00e9 de la formation comprenant le planning des journ\u00e9es de formations, les diff\u00e9rents modules de formation, les sujets et modalit\u00e9s des cas pratiques et mises en situation etc\u2026.<br>&#8211;\u00a0\u00a0\u00a0 Les besoins logistiques et organisationnels n\u00e9cessaires \u00e0 la bonne r\u00e9alisation de la formation.<br>Les livrables attendus sont les suivants :<br>&#8211;\u00a0\u00a0\u00a0 Un rapport final de formation avec ses annexes ;<br>&#8211;\u00a0\u00a0\u00a0 Les supports didactiques ou documents physiques des diff\u00e9rents modules de formation ;<br>&#8211;\u00a0\u00a0\u00a0 Les pr\u00e9sentations power-point des diff\u00e9rents modules ou expos\u00e9s ;<br>&#8211;\u00a0\u00a0\u00a0 Les r\u00e9sultats d\u2019\u00e9valuation (pr\u00e9\/post test) de la formation avec courbe de progression de chaque participant ;<br>&#8211;\u00a0\u00a0\u00a0 Des recommandations \u00e0 l\u2019endroit du projet Baka pour un suivi et une meilleure appropriation par les ex\u00e9cutifs communaux.\u00a0<br>&#8211;\u00a0\u00a0\u00a0 Un plan de restitution de la formation aupr\u00e8s des personnels de chaque commune.\u00a0<br>\u00a0<br>Les engagements contractuels de la formation seront accomplis avec l\u2019approbation du rapport final du consultant\/formateur ou cabinet par FAIRMED. \u00a0<br>\u00a0<br>Le rapport d\u00e9finitif restera la propri\u00e9t\u00e9 de FAIRMED qui en assurera la diffusion.<\/p>\n\n\n\n<p><br>\u00a0<strong>V- BENEFICIAIRES :<\/strong><br>\u00a0<br>La formation sera b\u00e9n\u00e9fique pour 18 personnes :<br>\u2022\u00a0\u00a0\u00a0 Les ex\u00e9cutifs communaux Maire d\u2019Abong-Mbang : 03<br>\u2022\u00a0\u00a0\u00a0 Les ex\u00e9cutifs communaux Maire d\u2019Angossas : 03<br>\u2022\u00a0\u00a0\u00a0 Les ex\u00e9cutifs communaux Maire d\u2019Atok : 03<br>\u2022\u00a0\u00a0\u00a0 Les ex\u00e9cutifs communaux Maire de Mindourou : 03<br>\u2022\u00a0\u00a0\u00a0 Un personnel du projet Baka : 03<\/p>\n\n\n\n<p><br>\u00a0<strong>VI- MODALITES DE LA FORMATION : \u00a0<\/strong><br><br><strong>\u00a0\u00a0 \u00a06.1. \u00a0\u00a0\u00a0 Dur\u00e9e de la consultation :<\/strong><br>La dur\u00e9e de la consultation s\u2019\u00e9tendra sur un d\u00e9lai maximum de 10 jours calcul\u00e9s comme suit :<br>&#8211;\u00a0\u00a0\u00a0 Signature du contrat, le briefing de l\u2019\u00e9quipe FAIRMED Abong-Mbang, Production du programme d\u00e9taill\u00e9 (planning, modules, m\u00e9thodologie finale) : 2 jours<br>&#8211;\u00a0\u00a0\u00a0 Tenue de la formation (th\u00e9orique et pratique) : 6 jours<br>&#8211;\u00a0\u00a0\u00a0 R\u00e9daction et la livraison du rapport final de formation : 2 jours<br>\u00a0<br><strong>NB : les sessions de formation doivent \u00eatre intercal\u00e9es par les sessions pratiques.<\/strong><br><strong>\u00a0Autres modalit\u00e9s<\/strong><br>\u25aa\u00a0\u00a0\u00a0 La gestion administrative du recrutement du contrat du consultant seront assur\u00e9es par la Fondation FAIRMED Cameroun.<br>\u25aa\u00a0\u00a0\u00a0 La mobilisation et l\u2019organisation logistique de la formation des participants seront g\u00e9r\u00e9s par le bureau de Coordination FAIRMED Abong-Mbang\u00a0<br>\u25aa\u00a0\u00a0\u00a0 La proposition du consultant devra donc d\u00e9crire, de mani\u00e8re exhaustive, les besoins logistiques et organisationnels n\u00e9cessaires \u00e0 la bonne r\u00e9alisation de la formation tels que disposition et taille de la salle, mat\u00e9riel n\u00e9cessaire (vid\u00e9oprojecteur, bloc-notes, paperboard, etc\u2026), la reprographie, les supports et documents utilis\u00e9s pendant la formation, etc&#8230;<br>\u00a0<br><strong>VII-\u00a0\u00a0\u00a0 BUDGET\u00a0<\/strong><br>\u00a0<br>Il s\u2019agit ici d\u2019un besoin \u00e9mis par le Projet Baka FAIRMED Abong-Mbang. Le co\u00fbt total de la prestation du consultant\/formateur ou cabinet retenu sera subventionn\u00e9 \u00e0 hauteur du budget pr\u00e9vu par FAIRMED. \u00a0<br>\u00a0<br>Toutefois, le budget pr\u00e9sent\u00e9 comprendra uniquement les honoraires du consultant pour la mission.<br>\u00a0<br>NB : Les frais de reproduction ou de tout autre support remis aux participants directement par le consultant au cours de la formation sont \u00e0 la charge du projet BAKA.<br>\u00a0<br><strong>VIII-\u00a0\u00a0\u00a0 DOCUMENTS ET MATERIEL A FOURNIR PAR PROJET BAKA\u00a0<\/strong><br>\u00a0<br>&#8211; \u00a0\u00a0\u00a0 Liste du personnel \u00e0 former avec leur poste au sein de la structure ; &#8211; \u00a0\u00a0\u00a0 Le mat\u00e9riel de formation n\u00e9cessaire \u00e0 fournir\u00a0 aux apprenants.\u00a0<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0<br><strong>IX-\u00a0 DOCUMENTS A PRESENTER PAR LES CONSULTANTS\/FORMATEURS OU CABINET \u00a0<\/strong><br>\u00a0<br>Le consultant devra produire en fran\u00e7ais :<br>\u2022\u00a0\u00a0\u00a0 Un CV avec r\u00e9f\u00e9rences qui d\u00e9montrent son exp\u00e9rience dans les domaines pertinents pour cette formation<br>\u2022\u00a0\u00a0\u00a0 Une proposition technique et financi\u00e8re telle que d\u00e9finie plus haut et comprenant \u00e0 minima :\u00a0<br>\u00a0<br><strong>\u00a0\u00a0 \u00a09.1. \u00a0\u00a0\u00a0 Une offre technique comprenant :\u00a0<\/strong><br>&#8211;\u00a0\u00a0\u00a0 La note de compr\u00e9hension des termes de r\u00e9f\u00e9rence (2 pages maximum) ;<br>&#8211;\u00a0\u00a0\u00a0 Une pr\u00e9sentation de la m\u00e9thodologie \u00e0 utiliser et le chronogramme pour le d\u00e9roulement des activit\u00e9s de formation (8 pages maximum) ;<br>&#8211;\u00a0\u00a0\u00a0 Un programme indicatif de formation sur les 6 jours ;<br>&#8211;\u00a0\u00a0\u00a0 Les r\u00e9f\u00e9rences et exp\u00e9riences du consultant\/formateur ou cabinet (8 pages maximum) ;<br>&#8211;\u00a0\u00a0\u00a0 Les modules de formation et de sessions pratiques etc\u2026 ;<br>&#8211;\u00a0\u00a0\u00a0 La liste du mat\u00e9riel n\u00e9cessaire de formation exigible aux apprenants ; Les besoins logistiques ;<br>&#8211;\u00a0\u00a0\u00a0 La constitution de l\u2019\u00e9quipe, la r\u00e9partition des responsabilit\u00e9s entre ses membres et les CV propos\u00e9s,\u00a0<br>&#8211;\u00a0\u00a0\u00a0 Le calendrier pr\u00e9visionnel d\u2019intervention ainsi qu\u2019une estimation des charges en Personnes\/jours,\u00a0<br>&#8211;\u00a0\u00a0\u00a0 Le format du rapport.\u00a0<br>\u00a0<br>\u00a0\u00a0<strong>\u00a0\u00a09.2. \u00a0\u00a0\u00a0 Une offre financi\u00e8re comprenant :\u00a0\u00a0<\/strong><br>&#8211;\u00a0\u00a0\u00a0 Le budget global (Hors Taxe et Toutes Taxes Comprises) ;\u00a0 &#8211; \u00a0\u00a0\u00a0 Le montant des honoraires en H\/J ;<br>\u00a0<br><strong>X- PROFIL GENERAL DES CONSULTANTS\/FORMATEURS OU CABINET<\/strong><br>\u00a0<br>Les Consultants devront pr\u00e9senter le profil suivant : \u00a0<br>\u00a0<br><strong>10.1. Sur le plan acad\u00e9mique \u00a0<\/strong><br>\u00a0<br>Chaque consultant devra avoir un dipl\u00f4me universitaire ou professionnel \u00e9quivalent au moins \u00e0 un master en d\u00e9centralisation, sant\u00e9 publique, administration publique, en sociologie, \u2026 \u00a0<br>\u00a0<br><strong>10.2. Sur le plan professionnel<\/strong><br>Chaque consultant devra justifier d\u2019une exp\u00e9rience av\u00e9r\u00e9e en : \u00a0<br>&#8211;\u00a0\u00a0\u00a0 Formation sur la d\u00e9centralisation ;\u00a0<br>&#8211;\u00a0\u00a0\u00a0 Formation sur la gestion de projet sant\u00e9 : cycle du projet et montage de projet sant\u00e9<br>&#8211;\u00a0\u00a0\u00a0 Mise en \u0153uvre de la d\u00e9centralisation avec les CTD<br>&#8211;\u00a0\u00a0\u00a0 Sant\u00e9 communautaire ;<br>&#8211;\u00a0\u00a0\u00a0 Plaidoyer et mise sur pied des strat\u00e9gies de mobilisation ou de mise en commun de ressources pour le financement des projets de sant\u00e9 ;<br>&#8211;\u00a0\u00a0\u00a0 Leadership communal et les comp\u00e9tences transf\u00e9r\u00e9es aux CTD en mati\u00e8re de sant\u00e9.<br>\u00a0<br><strong>10.3. R\u00e9f\u00e9rences du consultant<\/strong><br>Exp\u00e9rience professionnelle g\u00e9n\u00e9rale et sp\u00e9cifique attendue :<br>\u2022\u00a0\u00a0\u00a0 L\u2019expert devra justifier d\u2019au moins 3 ans d\u2019exp\u00e9rience professionnelle en formation sur la d\u00e9centralisation dans les CTD en lien avec la sant\u00e9 ;<br>\u2022\u00a0\u00a0\u00a0 Au moins 4 ans d\u2019exp\u00e9rience en sant\u00e9 publique option sant\u00e9 communautaire ;<br>\u2022\u00a0\u00a0\u00a0 Au moins 3 ans d\u2019exp\u00e9rience en formation sur le plaidoyer et les strat\u00e9gies de mobilisation des ressources au niveau local ;<br>\u2022\u00a0\u00a0\u00a0 Il est, de plus, requis de l\u2019expert une expertise av\u00e9r\u00e9e en tant qu\u2019animateur-facilitateur dans des processus participatifs ainsi qu\u2019une bonne connaissance du syst\u00e8me de d\u00e9centralisation camerounaise.<br>\u00a0<br><strong>10.4. Responsabilit\u00e9 du consultant\/Formateur principal<\/strong><br>\u00a0<br>Le consultant\/Formateur est responsable de : \u00a0<br>&#8211;\u00a0\u00a0\u00a0 Conduire la formation, une formation adapt\u00e9e au contexte de d\u00e9centralisation ;<br>&#8211;\u00a0\u00a0\u00a0 Former effectivement et suivre la progression des participants ;<br>&#8211;\u00a0\u00a0\u00a0 Proposer un plan de restitution dans les diff\u00e9rentes communes ;<br>&#8211;\u00a0\u00a0\u00a0 Proposer un plan de suivi de changement au sein des ex\u00e9cutifs communaux pendant les 10 mois qui suivent la formation<br>\u00a0<br><strong>XI- SELECTION DU CONSULTANT \u00a0<\/strong><br><br>Les propositions techniques seront \u00e9valu\u00e9es sur la base de leur conformit\u00e9 aux termes de r\u00e9f\u00e9rence, \u00e0 l\u2019aide des crit\u00e8res d\u2019\u00e9valuation et du syst\u00e8me de points suivant : \u00a0<br>\u00a0<br>\u00a0<br><strong>N\u00b0 \u00a0\u00a0\u00a0 Crit\u00e8res\u00a0 \u00a0\u00a0\u00a0 Notes<\/strong><br>1 \u00a0\u00a0\u00a0 Pr\u00e9sentation g\u00e9n\u00e9rale de l\u2019Offre (Pagination, intercalaire couleur\u2026) \u00a0\u00a0\u00a0 5<br>2 \u00a0\u00a0\u00a0 Note de Compr\u00e9hension des termes de r\u00e9f\u00e9rences \u00a0\u00a0\u00a0 10<br>3 \u00a0\u00a0\u00a0 La pr\u00e9sentation de la m\u00e9thodologie \u00e0 utiliser et le chronogramme pour le d\u00e9roulement des activit\u00e9s de formation ; Un programme indicatif de formation et les modules sur les 6 jours \u00a0\u00a0\u00a0 20<br>4     R\u00e9f\u00e9rences et exp\u00e9riences du soumissionnaire :<br>&#8211;\u00a0Formation sur la d\u00e9centralisation ;\u00a0<br>&#8211;\u00a0Formation sur la gestion de projet sant\u00e9 : cycle du projet et montage de projet sant\u00e9<br>&#8211;\u00a0Mise en \u0153uvre de la d\u00e9centralisation avec les CTD<br>&#8211;\u00a0Sant\u00e9 communautaire ;<br>&#8211;\u00a0Plaidoyer et mise sur pied des strat\u00e9gies de mobilisation ou de mise en commun de ressources pour le financement des projets de sant\u00e9 ;<br>-Leadership communal et les comp\u00e9tences transf\u00e9r\u00e9es aux CTD en mati\u00e8re de sant\u00e9;<br>&#8211;\u00a0L\u2019expert devra justifier d\u2019au moins 3 ans d\u2019exp\u00e9rience professionnelle en formation sur la d\u00e9centralisation dans les CTD en lien avec la sant\u00e9;<br>&#8211;\u00a0Au moins 4 ans d\u2019exp\u00e9rience en sant\u00e9 publique option sant\u00e9 communautaire ;<br>&#8211; Au moins 3 ans d\u2019exp\u00e9rience en formation sur le plaidoyer et les strat\u00e9gies de mobilisation des ressources au niveau local ;<br>&#8211;\u00a0Il est, de plus, requis de l\u2019expert une expertise av\u00e9r\u00e9e en tant qu\u2019animateur-facilitateur dans des processus participatifs ainsi qu\u2019une bonne connaissance du syst\u00e8me de d\u00e9centralisation camerounaise. \u00a0\u00a0\u00a0 20<br><strong>5 Qualifications et coh\u00e9rence de l\u2019\u00e9quipe propos\u00e9e<\/strong><br>Constitution de l\u2019\u00e9quipe et expertise de ses membres \u00a0\u00a0\u00a0\u00a0 20<br>6 Calendrier pr\u00e9visionnel de la formation et D\u00e9lai de livraison \u00a0\u00a0\u00a0 5<br><strong>TOTAL \u00a0\u00a0\u00a0 80<\/strong><br>\u00a0<br>La proposition financi\u00e8re recevra une note maximale sur \/20.<br>\u00a0<br>\u00a0<br>\u00a0<br><strong>XIV- PLAN DE TRAVAIL PREVISIONNEL<\/strong><br>\u00a0Le tableau ci-apr\u00e8s dresse le chronogramme des activit\u00e9s \u00e0 impl\u00e9menter :<br>Action \u00a0\u00a0\u00a0 Date<br>Lancement de l\u2019appel \u00a0\u00a0\u00a0\u00a0 05 juillet 2021<br>Date limite de soumission des offres \u00a0\u00a0\u00a0 14 juillet 2021<br>Signature du contrat \u00a0\u00a0\u00a0 19 juillet 2021<br>Remise du rapport final \u00a0\u00a0\u00a0 28 juillet 2021<br>\u00a0<br>\u00a0<br><strong>XIV- SOUMISSION<\/strong><br>\u00a0<br>Pour soumettre les offres techniques et financi\u00e8res, les consultants\/Formateurs sont invit\u00e9s \u00e0 le faire par email au plus tard le 14 juillet 2021 \u00e0 l\u2019adresse recrutementscameroun@fairmed.cm L\u2019objet du mail c\u2019est BAKA-FORMATION COMMUNE-010721.<br>\u00a0<br><strong>N.B. : Dans le cadre du processus de recrutement, FAIRMED n\u2019appr\u00e9cie pas les interventions des tiers.<\/strong><br>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fairmed recrute pour ses services un Consultant pour le Renforcement des Capacit\u00e9s. Pour soumettre les offres techniques et financi\u00e8res, les consultants\/Formateurs sont invit\u00e9s \u00e0 le faire par email au plus tard le 14 juillet 2021 \u00e0 l\u2019adresse recrutementscameroun@fairmed.cm L\u2019objet du mail c\u2019est BAKA-FORMATION COMMUNE-010721.<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[21,27],"tags":[3062,13,3026],"villes":[139],"contrats":[236],"diplomes":[161,159],"louma_meta":{"emploi_title":"Consultant pour le Renforcement des Capacit\u00e9s","emplois_employeur":5463,"emplois_date_publication":"2021-07-07","emplois_heure_publication":"07:21","emplois_date_cloture":"2021-07-14","emplois_heure_cloture":"17:00","emplois_experience_min":"3","emplois_experience_max":"4","emploi_email":"recrutementscameroun@fairmed.cm "},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/17301"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=17301"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/17301\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/5464"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=17301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=17301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=17301"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=17301"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=17301"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=17301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}