{"id":16357,"date":"2021-06-22T20:24:53","date_gmt":"2021-06-22T18:24:53","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=16357"},"modified":"2021-06-22T20:24:59","modified_gmt":"2021-06-22T18:24:59","slug":"un-gestionnaire-de-projet-infrastructures","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/un-gestionnaire-de-projet-infrastructures\/","title":{"rendered":"Un Gestionnaire de projet \u2013 Infrastructures"},"content":{"rendered":"\n<p>OFFRE D\u2019EMPLOI<br>Catholic Relief Services, Organisation Non Gouvernementale Internationale recherche pour les besoins de service Un Gestionnaire de projet \u2013<br>Infrastructures qualifi\u00e9, exp\u00e9riment\u00e9, et tr\u00e8s motiv\u00e9 qui devra g\u00e9rer, coordonner et suivre toutes les activit\u00e9s de la composante Infrastructures productives et sociales, et les diff\u00e9rentes formations y relatives.<\/p>\n\n\n\n<p> Vous devrez participer activement au d\u00e9veloppement et \u00e0 la r\u00e9alisation des plans du suivi et d\u2019\u00e9valuation du projet, et apporter votre expertise au d\u00e9veloppement des indicateurs pour la composante afin renforcer le travail de CRS au service des personnes pauvres et vuln\u00e9rables. Vos comp\u00e9tences dans la gestion de projets et vos connaissances dans le domaine des infrastructures permettront au programme pays de fournir des programmes de bonne qualit\u00e9 et de travailler continuellement \u00e0 am\u00e9liorer l\u2019impact de ce projet.<\/p>\n\n\n\n<p><br>Vous fournirez un service de grande qualit\u00e9 et contribuerez \u00e0 la bonne gestion des ressources pour aider \u00e0 assurer l\u2019efficacit\u00e9 op\u00e9rationnelle \u00e0 l\u2019appui des programmes de haute qualit\u00e9.<br>Le poste est bas\u00e9 in Mokolo\/Cameroon<br>R\u00f4les et Responsabilit\u00e9s cl\u00e9s du poste :<\/p>\n\n\n\n<p><br>\u2022 Pour la Composante A (Infrastructures productives et sociales), g\u00e9rer les activit\u00e9s de gestion, suivi et rapports techniques et de budget pendant la plus grande partie du cycle du projet \u2013 d\u00e9marrage, mise en \u0153uvre et cl\u00f4ture \u2013 dans la ligne des principes et normes de qualit\u00e9 de CRS, des exigences des bailleurs de fonds et des bonnes pratiques.<\/p>\n\n\n\n<p><br>\u2022 G\u00e9rer efficacement les comp\u00e9tences et superviser. G\u00e9rer la dynamique de l\u2019\u00e9quipe et le bien-\u00eatre des employ\u00e9s. Faire du coaching, adapter strat\u00e9giquement les plans individuels de d\u00e9veloppement et g\u00e9rer la performance des employ\u00e9s directement supervis\u00e9s.<\/p>\n\n\n\n<p><br>\u2022 S\u2019assurer que l\u2019apprentissage accompagne bien les activit\u00e9s du projet tout au long du cycle du projet. Aider \u00e0 la redevabilit\u00e9 en coordonnant les activit\u00e9s d\u2019\u00e9valuation du projet, conform\u00e9ment \u00e0 la politique de Suivi, Evaluation, Redevabilit\u00e9 et Apprentissage. Identifier proactivement les probl\u00e8mes, les signaler pour orienter les ajustements aux plans et aux calendriers de mise en \u0153uvre.<\/p>\n\n\n\n<p><br>\u2022 Mettre en route et renforcer des partenariats correspondant aux objectifs du projet avec une application appropri\u00e9e des concepts, outils et approches du partenariat.<\/p>\n\n\n\n<p><br>\u2022 Repr\u00e9senter l\u2019organisation aupr\u00e8s des bailleurs de fonds, groupes de travail des ONG internationales, Nations Unies, partenaires locaux pertinents et acteurs pertinents du gouvernement local et de la communaut\u00e9 dans le domaine des infrastructures.<\/p>\n\n\n\n<p><br>\u2022 Coordonner les activit\u00e9s n\u00e9cessaires pour avoir les ressources financi\u00e8res, mat\u00e9rielles et humaines qu\u2019il faut pour une mise en \u0153uvre de qualit\u00e9 du projet. Faire des examens p\u00e9riodiques du budget et v\u00e9rifier avec les partenaires la ponctualit\u00e9 de la soumission de rapports financiers afin de faciliter le bon suivi de l\u2019utilisation des ressources.<\/p>\n\n\n\n<p><br>\u2022 Identifier les besoins en capacit\u00e9s du personnel et les besoins d\u2019assistance technique des organisations partenaires et contribuer au renforcement des capacit\u00e9s et aux interventions n\u00e9cessaires pour appuyer la mise en \u0153uvre de projets de qualit\u00e9.<\/p>\n\n\n\n<p><br>\u2022 Aider \u00e0 la pr\u00e9paration de rapports d\u2019analyse sur les tendances et diffuser les r\u00e9sultats. \u00c9tudier la documentation du projet pour v\u00e9rifier que le dossier du projet est complet, avec tous les documents demand\u00e9s et qu\u2019il est class\u00e9 selon les exigences de l\u2019agence et des bailleurs de fonds<br>Qualifications de base :<\/p>\n\n\n\n<p><br>\u2022 Niveau Licence exig\u00e9 en Ing\u00e9nierie de construction. Dipl\u00f4me d\u2019ing\u00e9nieur en G\u00e9nie Civil et\/ou Infrastructures ou dans un domaine \u00e9quivalent et des dipl\u00f4mes de troisi\u00e8me cycle G\u00e9nie Civil et\/ou Infrastructures, y compris une accr\u00e9ditation par l\u2019autorit\u00e9 certifiante du Cameroun.<\/p>\n\n\n\n<p><br>\u2022 Exp\u00e9rience avec la l\u00e9gislation et les politiques r\u00e9gissant les achats, la construction et le d\u00e9veloppement des infrastructures au Cameroun ; compr\u00e9hension approfondie des d\u00e9partements et agences du minist\u00e8re du gouvernement tchadiens qui r\u00e9glementent la construction et les infrastructures.<\/p>\n\n\n\n<p><br>\u2022 Minimum de 5 ans d&rsquo;exp\u00e9rience en conception et \/ ou supervision de construction, y compris un minimum de 2 ans en gestion de contrats. Une exp\u00e9rience minimale de 2 ans dans le d\u00e9veloppement et la mise en \u0153uvre de projets d\u2019infrastructure ou d\u2019infrastructure communautaire pour le compte d\u2019organisations de d\u00e9veloppement.<\/p>\n\n\n\n<p><br>\u2022 Une exp\u00e9rience suppl\u00e9mentaire peut remplacer une partie des \u00e9tudes.<\/p>\n\n\n\n<p><br>\u2022 Une connaissance des technologies et des mat\u00e9riaux de construction locaux.<\/p>\n\n\n\n<p><br>\u2022 Exp\u00e9rience pratique dans le d\u00e9veloppement de conceptions \/ dessins de construction, de conceptions structurelles et de devis quantitatifs.<\/p>\n\n\n\n<p><br>\u2022 Exp\u00e9rience dans la supervision d\u2019une \u00e9quipe de travail (personnel).<\/p>\n\n\n\n<p><br>\u2022 Exp\u00e9rience dans l\u2019utilisation de logiciels de construction, de MS Windows et des logiciels MS Office (Excel, Word, PowerPoint).<br>Connaissances, comp\u00e9tences et capacit\u00e9s<\/p>\n\n\n\n<p><br>\u2022 Solides comp\u00e9tences en r\u00e9flexion critique et r\u00e9solution cr\u00e9ative des probl\u00e8mes avec la capacit\u00e9 d\u2019avoir des jugements pertinents.<\/p>\n\n\n\n<p><br>\u2022 Capacit\u00e9s solides en gestion des relations et capacit\u00e9 \u00e0 travailler efficacement avec des groupes culturellement divers.<\/p>\n\n\n\n<p><br>\u2022 Fortes capacit\u00e9s en communication \u00e9crite et orale incluant la r\u00e9daction de rapports.<\/p>\n\n\n\n<p><br>\u2022 Proactif, plein de ressources, ax\u00e9 sur les solutions et les r\u00e9sultats.<\/p>\n\n\n\n<p><br>\u2022 Capacit\u00e9 \u00e0 travailler en respectant les d\u00e9lais dans des environnements multi-t\u00e2ches.<\/p>\n\n\n\n<p><br>\u2022 Excellentes capacit\u00e9s d&rsquo;organisation, de planification, d&rsquo;analyse et soucieuses des d\u00e9tails.<br>D\u00e9placement dans le cadre de ce poste : Devrait pouvoir \u00eatre pr\u00eat et dispos\u00e9 \u00e0 voyager tr\u00e8s r\u00e9guli\u00e8rement.<\/p>\n\n\n\n<p><br>Les dossiers de candidature (incluant Lettre de motivation, CV, Noms et adresses de trois personnes de r\u00e9f\u00e9rence, tous documents qui pourront appuyer votre demande) doivent \u00eatre soumis UNIQUEMENT par Email \u00e0 l\u2019adresse : crscameroon@crs.org en indiquant comme titre du mail \u00ab Gestionnaire de projet \u2013Infrastructures -Mokolo \u00bb<\/p>\n\n\n\n<p><br>La date de cl\u00f4ture de r\u00e9ception des candidatures est fix\u00e9e au 30Juin 2021 a 16h30min pr\u00e9cises.<br>Les candidatures incompl\u00e8tes ou soumisses apr\u00e8s le d\u00e9lai de cl\u00f4ture ne seront pas consid\u00e9r\u00e9es.<br>Cette position est un poste national ouvert uniquement au Camerounais.<br>Les candidatures f\u00e9minines sont fortement encourag\u00e9es.<br>En postulant \u00e0 ce poste, je comprends et je reconnais que cette organisation exige de son personnel qu\u2019il traite toutes les personnes avec<\/p>\n\n\n\n<p>dignit\u00e9 et respect et qu\u2019il pr\u00e9vient activement le harc\u00e8lement, les mauvais traitements, l\u2019exploitation et la traite de personnes. De plus, je comprends que si je suis un candidat retenu, je serai soumis \u00e0 une v\u00e9rification compl\u00e8te des ant\u00e9c\u00e9dents, et mes r\u00e9f\u00e9rences personnelles \/ professionnelles seront invit\u00e9es \u00e0 \u00e9valuer mes comportements li\u00e9s \u00e0 la politique de protection des personnes de l\u2019agence.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>OFFRE D\u2019EMPLOICatholic Relief Services, Organisation Non Gouvernementale Internationale recherche pour les besoins de service Un Gestionnaire de projet \u2013Infrastructures qualifi\u00e9, exp\u00e9riment\u00e9, et tr\u00e8s motiv\u00e9 qui&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[79,1139,436],"tags":[],"villes":[136],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Un Gestionnaire de projet \u2013 Infrastructures ","emplois_employeur":4522,"emplois_date_publication":"2021-06-22","emplois_heure_publication":"","emplois_date_cloture":"2021-06-30","emplois_heure_cloture":"","emplois_experience_min":"5","emplois_experience_max":"8","emploi_email":"crscameroon@crs.org "},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/16357"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=16357"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/16357\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/4523"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=16357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=16357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=16357"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=16357"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=16357"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=16357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}