{"id":16351,"date":"2021-06-22T17:59:16","date_gmt":"2021-06-22T15:59:16","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=16351"},"modified":"2021-06-22T17:59:19","modified_gmt":"2021-06-22T15:59:19","slug":"responsable-commercial-et-marketing","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/responsable-commercial-et-marketing\/","title":{"rendered":"RESPONSABLE COMMERCIAL ET MARKETING"},"content":{"rendered":"\n<p>RESPONSABLE COMMERCIAL ET MARKETING<\/p>\n\n\n\n<p>BASSAGAL CONSULTING AFRICA recrute, pour une PME sp\u00e9cialis\u00e9e dans l&rsquo;hygi\u00e8ne et l&rsquo;assainissement: &gt; Un (01) RESPONSABLE COMMERCIAL ET MARKETING <\/p>\n\n\n\n<p>(<\/p>\n\n\n\n<p>R\u00e9f. RCM) <\/p>\n\n\n\n<p>Missions : <\/p>\n\n\n\n<p>Participer \u00e0 la d\u00e9finition de la politique commerciale et marketing de l&rsquo;entreprise; <\/p>\n\n\n\n<p>Promouvoir l&rsquo;image de notori\u00e9t\u00e9 de l&rsquo;entreprise ; <\/p>\n\n\n\n<p>Constituer, d\u00e9velopper et g\u00e9rer le fichier clients ; <\/p>\n\n\n\n<p>Communiquer \u00e0 la client\u00e8le les informations techniques sur les produits ey services de l&rsquo;entreprise;<\/p>\n\n\n\n<p> Assurer une veille concurrentielle et d\u00e9tectez de nouveaux besoins afin de d\u00e9velopper le chiffre d&rsquo;af- faires de l&rsquo;entreprise; <\/p>\n\n\n\n<p>Rassembler les \u00e9l\u00e9ments st superviser les appels d&rsquo;offres ; <\/p>\n\n\n\n<p>Organiser et suivre le recouvrement des cr\u00e9ances;<\/p>\n\n\n\n<p> Etablir les devis et cotations en collaboration avec les membres du CODIR ; <\/p>\n\n\n\n<p>Assurer une bonne application du plan marketing ; <\/p>\n\n\n\n<p>Encadrer et d\u00e9velopper l&rsquo;\u00e9quipe commerciale et marketing.<\/p>\n\n\n\n<p> Profil :<\/p>\n\n\n\n<p> De formation sup\u00e9rieure en vente, distribution, vous avez 4 ans minimum d&rsquo;exp\u00e9rience terrain de vente et de gestion de la distribution de produis de grande consommation <\/p>\n\n\n\n<p>Vous avez d\u00e9j\u00e0 g\u00e9r\u00e9 une \u00e9quipe de commerciaux que vous avez coach\u00e9 et inspir\u00e9 en les amenant \u00e0 atteindre leurs objectifs. <br><br>Orient\u00e9 r\u00e9sultats, vous avez prouv\u00e9 votre capacit\u00e9 \u00e0 travailler d&rsquo;une mani\u00e8re ind\u00e9pendante et trans- formez les difficult\u00e9s en opportunit\u00e9s. <br><br>Homme de terrain, vous avez une parfaite ma\u00eetrise de la conduite des v\u00e9hicules de tourisme (permis de cat\u00e9gorie B). <br><br>La connaissance du secteur de l&rsquo;hygi\u00e8ne et l&rsquo;assainissement est un plus. Les candidats int\u00e9ress\u00e9s doivent envoyer leur CV en pr\u00e9cisant la r\u00e9f\u00e9rence \u00ab RCM \u00bb \u00e0 \u013e&rsquo;adresse suivante : Joseph.bassagal@yahoo.com La date limite de recevabilit\u00e9 des candidatures est fix\u00e9e au 30 juin 2021. Seuls les candidats shortlist\u00e9s seront contact\u00e9s<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RESPONSABLE COMMERCIAL ET MARKETING BASSAGAL CONSULTING AFRICA recrute, pour une PME sp\u00e9cialis\u00e9e dans l&rsquo;hygi\u00e8ne et l&rsquo;assainissement: &gt; Un (01) RESPONSABLE COMMERCIAL ET MARKETING ( R\u00e9f.&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[24],"tags":[],"villes":[136],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"RESPONSABLE COMMERCIAL ET MARKETING","emplois_employeur":4772,"emplois_date_publication":"2021-06-22","emplois_heure_publication":"","emplois_date_cloture":"2021-06-30","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"3","emploi_email":"Joseph.bassagal@yahoo.com "},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/16351"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=16351"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/16351\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/4773"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=16351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=16351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=16351"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=16351"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=16351"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=16351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}