{"id":15942,"date":"2021-06-14T12:34:08","date_gmt":"2021-06-14T10:34:08","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=15942"},"modified":"2021-06-14T12:34:11","modified_gmt":"2021-06-14T10:34:11","slug":"offre-demploi-dames-de-menage","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/offre-demploi-dames-de-menage\/","title":{"rendered":"Offre d&#8217;emploi: Dames De M\u00e9nage"},"content":{"rendered":"\n<p><strong>A PROPOS<\/strong><\/p>\n\n\n\n<p>Notre client est une entreprise \u00e9tablit sur plusieurs secteurs d\u2019activit\u00e9, notamment l\u2019agroalimentaire, la restauration et les prestations de services.<\/p>\n\n\n\n<p>L\u2019entreprise amorce la phase op\u00e9rationnelle de ses activit\u00e9s, qui se traduit par le recrutement d\u2019un grand nombre de personnels. Dans ce contexte, l\u2019entreprise recherche deux (2)&nbsp;<strong>Dames de m\u00e9nage<\/strong>&nbsp;pour assurer la propret\u00e9 des bureaux et des espaces communs.<\/p>\n\n\n\n<p><strong>PROFIL RECHERCHE<\/strong><\/p>\n\n\n\n<p>De bonne condition physique, vous \u00eates \u00e0 l\u2019aise avec les personnes, disponible et avez du respect pour la hi\u00e9rarchie.&nbsp;<\/p>\n\n\n\n<p><strong>CONDITIONS<\/strong><\/p>\n\n\n\n<p>Les candidats s\u00e9lectionn\u00e9s devront valider une p\u00e9riode d\u2019essai de trois (3) mois renouvelable. Ensuite, ils auront un CDD.<\/p>\n\n\n\n<p>Salaire&nbsp;: 35&nbsp;000 FCFA fixe mensuel<\/p>\n\n\n\n<p>R\u00e9sider \u00e0 Yaound\u00e9<\/p>\n\n\n\n<p><strong>POUR POSTULER<\/strong><\/p>\n\n\n\n<p>Vous envoyez votre CV \u00e0 l\u2019adresse e-mail&nbsp;<a href=\"mailto:recrutement@maart.pro\">recrutement@maart.pro<\/a>&nbsp;au plus tard le&nbsp;<strong>30 juin 2021<\/strong>. Veuillez pr\u00e9ciser en objet de l\u2019e-mail la r\u00e9f\u00e9rence&nbsp;:&nbsp;<strong>ME-0008-21<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une entreprise recrute pour ses services des Dames de M\u00e9nage. Vous envoyez votre CV \u00e0 l\u2019adresse e-mail recrutement@maart.pro au plus tard le 30 juin 2021. Veuillez pr\u00e9ciser en objet de l\u2019e-mail la r\u00e9f\u00e9rence : ME-0008-21.<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[1182],"tags":[2853,245,7],"villes":[136],"contrats":[149],"diplomes":[156],"louma_meta":{"emploi_title":"Offre d'emploi: Dames De M\u00e9nage","emplois_employeur":3046,"emplois_date_publication":"2021-06-14","emplois_heure_publication":"11:31","emplois_date_cloture":"2021-06-30","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"recrutement@maart.pro "},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/15942"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=15942"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/15942\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/9483"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=15942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=15942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=15942"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=15942"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=15942"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=15942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}