{"id":15783,"date":"2021-06-12T02:35:31","date_gmt":"2021-06-12T00:35:31","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=15783"},"modified":"2021-06-12T02:35:34","modified_gmt":"2021-06-12T00:35:34","slug":"responsable-commercial-nutrition-animale","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/responsable-commercial-nutrition-animale\/","title":{"rendered":"RESPONSABLE COMMERCIAL NUTRITION ANIMALE"},"content":{"rendered":"\n<p><strong>OFFRE D&rsquo;EMPLOI<\/strong><\/p>\n\n\n\n<p>Pour le compte d&rsquo;une industrie de production des nutriments pour animaux (Porcs, poissons) nous recrutons un RESPONSABLE COMMERCIAL NUTRITION ANIMALE<\/p>\n\n\n\n<p><strong>Missions:<\/strong><\/p>\n\n\n\n<ul><li>D\u00e9velopper les ventes aupr\u00e8s des clients distributeurs ;<\/li><li>Former et accompagnement des commerciaux du r\u00e9seau de distribution ;<\/li><li>D\u00e9velopper et suivre le portefeuille de clients distributeurs;<\/li><li>Prospecter activement afin de d\u00e9velopper votre portefeuille clients ;<\/li><li>Analyser le march\u00e9 potentiel sur le secteur, d\u00e9finir les approches commerciales pertinentes et susciter l\u2019int\u00e9r\u00eat de vos clients sur les produits de l\u2019entreprise ;<\/li><li>Organiser votre suivi commercial (tableau de bord, rapports de suivi, etc.).<\/li><\/ul>\n\n\n\n<p><strong>PROFIL RECHERCHE:<\/strong><\/p>\n\n\n\n<ul><li>Formation \u00e0 Bac+4 Agri\/Agro-industrie,<\/li><li>Exp\u00e9rience commerciale dans le secteur agricole ou sant\u00e9 animale<\/li><li>Bon relationnel et sens de l\u2019\u00e9coute,<\/li><li>Force de persuasion et de gestion des priorit\u00e9s.<\/li><li>App\u00e9tence commerciale pour le suivi et le conseil aux distributeurs,<\/li><li>Assertivit\u00e9 face aux distributeurs et de proximit\u00e9 avec le terrain et les \u00e9leveurs.<\/li><\/ul>\n\n\n\n<p>Laissez nous votre candidature \u00e0 l&rsquo;adresse suivante:&nbsp;<a href=\"mailto:recrutement@right-performances.com\"><strong>recrutement@right-performances.com<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RESPONSABLE COMMERCIAL NUTRITION ANIMALE<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[251],"tags":[2824],"villes":[136],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"RESPONSABLE COMMERCIAL NUTRITION ANIMALE","emplois_employeur":4666,"emplois_date_publication":"2021-06-12","emplois_heure_publication":"","emplois_date_cloture":"2021-07-12","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"3","emploi_email":"recrutement@right-performances.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/15783"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=15783"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/15783\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/4667"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=15783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=15783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=15783"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=15783"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=15783"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=15783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}