{"id":15467,"date":"2021-06-06T02:50:46","date_gmt":"2021-06-06T00:50:46","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=15467"},"modified":"2021-06-06T02:50:48","modified_gmt":"2021-06-06T00:50:48","slug":"01-responsable-qualite-h-f","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/01-responsable-qualite-h-f\/","title":{"rendered":"01 RESPONSABLE QUALIT\u00c9 (H\/F)"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">01 RESPONSABLE QUALIT\u00c9 (H\/F)<\/h2>\n\n\n\n<p><strong>Date limite de r\u00e9ception des candidatures :&nbsp;11 juin 2021<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>ACTIVA ASSURANCES<\/strong>&nbsp;recherche pour les besoins de ses services :<\/h2>\n\n\n\n<p><strong>Titre du poste<\/strong>: 01 Responsable Qualit\u00e9<\/p>\n\n\n\n<p><strong>Localisation<\/strong>: Douala\u2013 Cameroun<\/p>\n\n\n\n<p><strong>Nature du contrat&nbsp;<\/strong>: CDI<\/p>\n\n\n\n<p><strong>Mission principale<\/strong><strong>&nbsp;:&nbsp;<\/strong>Rattach\u00e9(e) \u00e0 la Direction G\u00e9n\u00e9rale,&nbsp;le Responsable Qualit\u00e9 est en charge de la gestion courante et pr\u00e9dictive du syst\u00e8me de management de la qualit\u00e9 pour le compte de la compagnie ACTIVA.&nbsp;<\/p>\n\n\n\n<p><strong>Contenu du poste :<\/strong><\/p>\n\n\n\n<ul><li>Assurer la gestion du SMQ et superviser sa d\u00e9clinaison \u00e0 tous les niveaux de l&rsquo;entreprise<\/li><li>Mener les audits SGS pour la certification<\/li><li>Organiser et&nbsp;coordonner&nbsp;la r\u00e9alisation des revues de processus et des revues de Direction<\/li><li>Veiller au suivi et au respect&nbsp;des proc\u00e9dures qualit\u00e9<\/li><li>Assurer la veille normative et r\u00e9glementaire relative au management de la qualit\u00e9<\/li><li>D\u00e9finir et mettre en \u0153uvre le plan de communication sur la politique et le programme qualit\u00e9&nbsp;<\/li><li>D\u00e9finir et suivre les outils de gestion de la qualit\u00e9 (syst\u00e8me documentaire, indicateurs, tableau de bord\u2026)<\/li><li>Identifier et analyser les probl\u00e8mes qualit\u00e9 et proposer des actions correctives<\/li><li>Pr\u00e9parer les d\u00e9marches de certification et assurer la p\u00e9rennit\u00e9 des certifications en vigueur<\/li><li>Promouvoir les plans d&rsquo;am\u00e9lioration continue et des meilleurs pratiques&nbsp;<\/li><li>Cartographier les risques techniques et fonctionnels et estimer leur criticit\u00e9 en utilisant des standard<\/li><li>Traiter les plaintes&nbsp;et contr\u00f4ler le niveau de satisfaction des clients<\/li><\/ul>\n\n\n\n<p><strong>Profil requis<\/strong><\/p>\n\n\n\n<p><strong>Dipl\u00f4me :<\/strong>&nbsp;BAC+4\/5 en Gestion de la Qualit\u00e9, Contr\u00f4le de gestion, Audit ou tout autre dipl\u00f4me \u00e9quivalent<\/p>\n\n\n\n<p><strong>Exp\u00e9rience<\/strong>&nbsp;: avoir au minimum 5 \u00e0 8 ans d\u2019exp\u00e9rience dans le domaine du management de la qualit\u00e9, l\u2019audit le contr\u00f4le etc ;&nbsp;<\/p>\n\n\n\n<p><strong>Aptitudes :<\/strong><\/p>\n\n\n\n<ul><li>Ma\u00eetrise de la norme ISO 9001 v 2015, et r\u00e9f\u00e9rentiels<\/li><li>Bonne exp\u00e9rience dans la conduite d\u2019un SMQ<\/li><li>Avoir des certifications Qualit\u00e9 serait un atout<\/li><\/ul>\n\n\n\n<p><strong>Attitudes :<\/strong><\/p>\n\n\n\n<ul><li>Leadership<\/li><li>Sens de l\u2019organisation et de la rigueur<\/li><li>Esprit de synth\u00e8se et d&rsquo;analyse<\/li><li>Capacit\u00e9 \u00e0 travailler en \u00e9quipe<\/li><\/ul>\n\n\n\n<p><strong>Dossier de candidature<\/strong><strong>&nbsp;:&nbsp;<\/strong>Le dossier de candidature, constitu\u00e9 uniquement d\u2019un CV d\u00e9taill\u00e9 (format PDF) avec contacts t\u00e9l\u00e9phoniques et adresse e-mail, devra \u00eatre d\u00e9pos\u00e9 exclusivement via le lien suivant:&nbsp;<a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSfhl7YNHGevlQXNw84PGxi_IVusIPBUc_E1XlFfxvPEQL75fA\/viewform\">Responsable Qualit\u00e9<\/a>&nbsp;au plus tard le&nbsp;<strong>11 juin 2021<\/strong>.<\/p>\n\n\n\n<p><strong>NB: Toute candidature ne respectant pas les conditions prescrites sera purement et simplement disqualifi\u00e9e. Seul(e)s les candidat(e)s pr\u00e9s\u00e9lectionn\u00e9(e)s seront contact\u00e9(e)s.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ACTIVA ASSURANCES recherche pour les besoins de ses services : Un Responsable Qualit\u00e9 H\/F<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[343],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"01 RESPONSABLE QUALIT\u00c9 (H\/F)","emplois_employeur":4944,"emplois_date_publication":"2021-06-06","emplois_heure_publication":"","emplois_date_cloture":"2021-06-11","emplois_heure_cloture":"","emplois_experience_min":"2","emplois_experience_max":"4","emploi_email":"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSfhl7YNHGevlQXNw84PGxi_IVusIPBUc_E1XlFfxvPEQL75fA\/viewform"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/15467"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=15467"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/15467\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/4945"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=15467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=15467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=15467"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=15467"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=15467"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=15467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}