{"id":15419,"date":"2021-06-04T15:41:22","date_gmt":"2021-06-04T13:41:22","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=15419"},"modified":"2021-06-04T15:44:31","modified_gmt":"2021-06-04T13:44:31","slug":"la-regionale-depargne-et-de-credit-recrute-plusieurs-profils","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/la-regionale-depargne-et-de-credit-recrute-plusieurs-profils\/","title":{"rendered":"La R\u00e9gionale d&rsquo;\u00e9pargne et de cr\u00e9dit recrute plusieurs profils"},"content":{"rendered":"\n<p>La R\u00e9gionale d&rsquo;\u00e9pargne et de cr\u00e9dit recrute plusieurs profils<\/p>\n\n\n\n<p>Dans le cadre de sa transformation prochaine en banque universelle, La R\u00e9gionale d&rsquo;\u00e9pargne et de cr\u00e9dit 1 \u00e8re entreprise financi\u00e8re cot\u00e9e \u00e0 la BVMAC , recherche des personnes d\u00e9sireuses de relever ce d\u00e9fis, et ayant une exp\u00e9rience professionnelle av\u00e9r\u00e9e dans la banque classique , ceci dans les domaines suivants:<\/p>\n\n\n\n<ul><li>Marketing<\/li><li>Commercial<\/li><li>Comptabilit\u00e9 et op\u00e9ration<\/li><li>Gestion de la tr\u00e9sorerie<\/li><li>Audit et contr\u00f4le<\/li><li>Logistique<\/li><li>Financement des PME<\/li><li>Banque digitale<\/li><li>etc<\/li><\/ul>\n\n\n\n<p><strong>Pi\u00e8ce \u00e0 fournir:<\/strong><\/p>\n\n\n\n<p>CV + \u00e9l\u00e9ments justificatifs des dipl\u00f4mes et des exp\u00e9riences <\/p>\n\n\n\n<p><strong>Les dossiers sont attendus au Plutard le 15 Juin 2021 \u00e0 l&rsquo;adresse mail suivante : recrutements@laregionalesa.com<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre de sa transformation prochaine en banque universelle, La R\u00e9gionale d&rsquo;\u00e9pargne et de cr\u00e9dit 1 \u00e8re entreprise financi\u00e8re cot\u00e9e \u00e0 la BVMAC , recherche des personnes d\u00e9sireuses de relever ce d\u00e9fis<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"closed","template":"","categories":[343,1594,251,25,282,302,23,22,235,113,24],"tags":[],"villes":[135,136],"contrats":[236,234],"diplomes":[164,163,160,212,159],"louma_meta":{"emploi_title":"Plusieurs profils","emplois_employeur":15053,"emplois_date_publication":"2021-06-04","emplois_heure_publication":"","emplois_date_cloture":"2021-06-15","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"recrutements@laregionalesa.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/15419"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=15419"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/15419\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/15055"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=15419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=15419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=15419"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=15419"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=15419"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=15419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}