{"id":15058,"date":"2021-05-25T18:46:12","date_gmt":"2021-05-25T16:46:12","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=15058"},"modified":"2021-05-25T18:46:16","modified_gmt":"2021-05-25T16:46:16","slug":"offre-demploi-plusieurs-profils-pour-sa-transformation-prochaine-en-banque-universelle","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/offre-demploi-plusieurs-profils-pour-sa-transformation-prochaine-en-banque-universelle\/","title":{"rendered":"Offre d&#8217;emploi: Plusieurs Profils pour sa Transformation Prochaine en Banque Universelle"},"content":{"rendered":"\n<p>La R\u00e9gionale d&rsquo;\u00e9pargne et de cr\u00e9dit recrute plusieurs profils<\/p>\n\n\n\n<p>Dans le cadre de sa transformation prochaine en banque universelle, La R\u00e9gionale d&rsquo;\u00e9pargne et de cr\u00e9dit 1 \u00e8re entreprise financi\u00e8re cot\u00e9e \u00e0 la BVMAC et dirig\u00e9e par un VRAI PASTEUR, recherche des vrais enfants de Dieu d\u00e9sireux de relever ce d\u00e9fis, et ayant une exp\u00e9rience bancaire dans les domaines suivants:<\/p>\n\n\n\n<ul><li>Marketing<\/li><li>Commercial<\/li><li>Comptabilit\u00e9 et op\u00e9ration<\/li><li>Gestion de la tr\u00e9sorerie<\/li><li>Audit et contr\u00f4le<\/li><li>Logistique<\/li><li>Financement des PME<\/li><li>Banque digitale<\/li><li>etc<\/li><\/ul>\n\n\n\n<p><strong>Pi\u00e8ce \u00e0 fournir:<\/strong><\/p>\n\n\n\n<p>CV + \u00e9l\u00e9ments justificatifs des dipl\u00f4mes et des exp\u00e9riences<\/p>\n\n\n\n<p><strong>Les dossiers sont attendus \u00e0 SUCCESS RADIO&nbsp;Yaound\u00e9&nbsp;<u>au plus tard le 31 Mai 2021<\/u><\/strong><\/p>\n\n\n\n<p><strong>NB: Seuls les personnes retenus seront convoqu\u00e9es<\/strong>| <\/p>\n\n\n\n<p>COMMENT POSTULER SUCCESS RADIO Yaound\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La R\u00e9gionale d&rsquo;Epargne et de Cr\u00e9dit recrute plusieurs profils. Envoyez vos CV et pi\u00e8ces justificatifs \u00e0 SUCCESS RADIO Yaound\u00e9.<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[23,113,24],"tags":[2666,2667,7],"villes":[136],"contrats":[148],"diplomes":[248,212,159],"louma_meta":{"emploi_title":"Offre d'emploi: Plusieurs Profils pour sa Transformation Prochaine en Banque Universelle","emplois_employeur":15053,"emplois_date_publication":"2021-05-25","emplois_heure_publication":"17:44","emplois_date_cloture":"2021-05-31","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"SUCCESS RADIO Yaound\u00e9"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/15058"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=15058"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/15058\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/15055"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=15058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=15058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=15058"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=15058"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=15058"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=15058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}