{"id":14811,"date":"2021-05-18T13:55:25","date_gmt":"2021-05-18T11:55:25","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=14811"},"modified":"2021-05-18T13:55:30","modified_gmt":"2021-05-18T11:55:30","slug":"offre-demploi-ingenieur-mecanique-2","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/offre-demploi-ingenieur-mecanique-2\/","title":{"rendered":"Offre d&#8217;emploi: INGENIEUR MECANIQUE"},"content":{"rendered":"\n<p>Le groupe FOKOU recrute actuellement un #ing\u00e9nieur m\u00e9canique charg\u00e9 de la maintenance et qui sera en charge de:<\/p>\n\n\n\n<ul><li>Participer dans la planification des travaux d&rsquo;entretiens e dans le suivi des actions de d\u00e9pannage et interventions planifi\u00e9es en toute s\u00e9curit\u00e9;<\/li><li>R\u00e9aliser les plans et autres documents n\u00e9cessaires \u00e0 l\u2019ex\u00e9cution correcte des travaux<\/li><li>Proposer les modes op\u00e9ratoires pour l&rsquo;ex\u00e9cution des t\u00e2ches sur le terrain<\/li><li>Manager le personnel plac\u00e9 sous sa responsabilit\u00e9<\/li><li>D\u00e9tecter les opportunit\u00e9s d&rsquo;am\u00e9lioration de la maintenance des \u00e9quipements<\/li><li>Pr\u00e9parer les travaux d&rsquo;arr\u00eats programm\u00e9s (mode op\u00e9ratoire, approvisionnement, sp\u00e9cifications et planification)<\/li><\/ul>\n\n\n\n<p>Domaine de comp\u00e9tence: <\/p>\n\n\n\n<ul><li>Maintenance industrielle,<\/li><li>Fabrication<\/li><li>m\u00e9canique,<\/li><li>Lubrification des \u00e9quipements,<\/li><li>Chaudronnerie et soudure, <\/li><li>R\u00e9sistance des mat\u00e9riaux,<\/li><li>DAO et CAO.<\/li><\/ul>\n\n\n\n<p>Pri\u00e8re d&rsquo;envoyer vos CV et lettre de motivation \u00e0 l&rsquo;adresse: julio.mbakam-guiwou@acieriesducameroun.com<\/p>\n\n\n\n<p>Delai le 24\/05\/2021<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Groupe Fokou recrute un Ing\u00e9nieur M\u00e9canique. Pri\u00e8re d&rsquo;envoyer vos CV et lettre de motivation \u00e0 l&rsquo;adresse: julio.mbakam-guiwou@acieriesducameroun.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[976],"tags":[2628,2629,7],"villes":[136],"contrats":[148],"diplomes":[278,160],"louma_meta":{"emploi_title":"Offre d'emploi: INGENIEUR MECANIQUE","emplois_employeur":14770,"emplois_date_publication":"2021-05-18","emplois_heure_publication":"12:53","emplois_date_cloture":"2021-05-24","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"julio.mbakam-guiwou@acieriesducameroun.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/14811"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=14811"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/14811\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/14771"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=14811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=14811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=14811"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=14811"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=14811"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=14811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}