{"id":14710,"date":"2021-05-14T13:46:06","date_gmt":"2021-05-14T11:46:06","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=14710"},"modified":"2021-05-17T09:47:05","modified_gmt":"2021-05-17T07:47:05","slug":"offre-de-stage-02-teleconseilleres-sav-stagiaires-professionnelles","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/offre-de-stage-02-teleconseilleres-sav-stagiaires-professionnelles\/","title":{"rendered":"Offre de Stage:  02 T\u00e9l\u00e9conseill\u00e8res SAV &#8211; Stagiaires professionnelles"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\">DVANCE-IT Group recherche dans le cadre d&rsquo;un stage professionnel r\u00e9mun\u00e9r\u00e9 d&rsquo;une dur\u00e9e de 06 mois, pouvant d\u00e9boucher sur un CDI, deux t\u00e9l\u00e9conseill\u00e8res SAV conform\u00e9ment \u00e0 ce qui suit :<\/h1>\n\n\n\n<p><strong>1- Missions<\/strong>:&nbsp;<\/p>\n\n\n\n<ul><li> Gestion compl\u00e8te des r\u00e9clamations clients; <\/li><li> Surveillance du r\u00e9seau DATACENTRAL; <\/li><li> Surveillance des syst\u00e8mes informatiques infog\u00e9r\u00e9s; <\/li><li> Assistance technique aux clients en ligne; <\/li><li> T\u00e9l\u00e9maintenance; <\/li><li> Interm\u00e9diation avec les clients dans le cadre des interventions techniques. &#8211; Assurer une permanence t\u00e9l\u00e9phonique, courriel et r\u00e9seaux sociaux aupr\u00e8s des clients; <\/li><li> G\u00e9rer les processus d&rsquo;acquisition renouvellement des composants du parc informatique de nos clients infog\u00e9r\u00e9s; <\/li><li> Interm\u00e9diation avec les prestataires tiers dans le cadre des missions chez nos clients infog\u00e9r\u00e9s; <\/li><li>Veiller en permanence \u00e0 la pleine satisfaction des clients; <\/li><li> Booster en permanence le niveau de consommation de nos services chez les clients; <\/li><li> Recenser en permanence les \u00e9volutions des besoins de la client\u00e8le; <\/li><li> D\u00e9velopper le portefeuille client existant et fid\u00e9liser la client\u00e8le; <\/li><li> Suppl\u00e9er le Service Administratif et Financier dans certaines de ses t\u00e2ches.<\/li><\/ul>\n\n\n\n<p><strong>2- Aptitudes requises<\/strong>:&nbsp;<\/p>\n\n\n\n<ul><li> Bonnes aptitudes \u00e0 l\u2019outil informatique, notamment le WEB, les outils de messagerie \u00e9lectroniques, les r\u00e9seaux sociaux, et les logiciels de gestion commerciale et comptable; <\/li><li> Bonne connaissance dans l\u2019Administration des R\u00e9seaux et Syst\u00e8mes informatiques; <\/li><li> Bonne capacit\u00e9 d\u2019\u00e9coute, d\u2019analyse et d\u2019initiative; <\/li><li> Excellent sens du relationnel, de l\u2019argumentation et de la n\u00e9gociation; <\/li><li> Bonnes bases en gestion (comptabilit\u00e9, gestion commerciale); <\/li><li> Excellente Capacit\u00e9s d\u2019expression orale et \u00e9crite; <\/li><li> Dynamique, organis\u00e9 et perspicace.<\/li><\/ul>\n\n\n\n<p><strong>3- Profil Acad\u00e9mique et Professionnel: <\/strong><\/p>\n\n\n\n<ul><li>&nbsp;Avoir au minimum un niveau LICENCE en Informatique ; <\/li><li> Avoir une exp\u00e9rience de t\u00e9l\u00e9op\u00e9ratrice\/t\u00e9l\u00e9conseill\u00e8re de 06 mois minimum;<\/li><li> Perspectives apr\u00e8s le stage professionnel; <\/li><li> Peut d\u00e9boucher sur un CDI si satisfaisant .<\/li><\/ul>\n\n\n\n<p>COMMENT POSTULER:<\/p>\n\n\n\n<p>recrutement@advance-it-group.biz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ADVANCE-IT GROUP Cameroun recrute  deux Stagiaires Professionnels T\u00e9l\u00e9conseill\u00e8res SAV. Faire parvenir vos dossiers \u00e0 l&rsquo;adresse:  recrutement@advance-it-group.biz<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[22],"tags":[2613,2614,7],"villes":[136],"contrats":[234,152],"diplomes":[212],"louma_meta":{"emploi_title":"Offre de Stage:  02 T\u00e9l\u00e9conseill\u00e8res SAV - Stagiaires professionnelles","emplois_employeur":12953,"emplois_date_publication":"2021-05-14","emplois_heure_publication":"12:44","emplois_date_cloture":"2021-05-20","emplois_heure_cloture":"17:00","emplois_experience_min":"6","emplois_experience_max":"","emploi_email":"recrutement@advance-it-group.biz"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/14710"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=14710"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/14710\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/12954"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=14710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=14710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=14710"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=14710"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=14710"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=14710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}