{"id":14566,"date":"2021-05-10T19:20:13","date_gmt":"2021-05-10T17:20:13","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=14566"},"modified":"2021-05-10T19:20:15","modified_gmt":"2021-05-10T17:20:15","slug":"offre-demploi-chef-datelier","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/offre-demploi-chef-datelier\/","title":{"rendered":"Offre d\u2019emploi : Chef d\u2019Atelier"},"content":{"rendered":"\n<p><strong>CHEF D\u2019ATELIER<\/strong><\/p>\n\n\n\n<p><em>MISSIONS<\/em><\/p>\n\n\n\n<p>Le\/la\u00a0Chef\u00a0Atelier\u00a0sous la supervision directe du Directeur\u00a0du mat\u00e9riel,\u00a0apour mission :<\/p>\n\n\n\n<p>\u2022\u00a0D\u00e9finition et mise en place d\u2019un plan g\u00e9n\u00e9ral de maintenance<\/p>\n\n\n\n<p>\u2022\u00a0D\u00e9finition et mise en place des proc\u00e9dures de maintenance pr\u00e9ventives et curatives<\/p>\n\n\n\n<p>\u2022\u00a0Assistance \u00e0 la mise en place de l\u2019organigramme cible du d\u00e9partement mat\u00e9riel<\/p>\n\n\n\n<p>\u2022\u00a0Proc\u00e9dure de maintenance de calibrage et de maintenance des engins sp\u00e9ciaux\u2022\u00a0Proc\u00e9dure d\u2019approvisionnement mat\u00e9riel\u2022\u00a0Mise en place d\u2019un syst\u00e8me informatis\u00e9 de gestion de parc<\/p>\n\n\n\n<p>\u2022\u00a0Mise en place des objectifs de performance<\/p>\n\n\n\n<p>\u2022\u00a0Conseil \u00e0 l\u2019installation et au choix de la construction d\u2019une base technique<\/p>\n\n\n\n<p>\u00a0\u2022\u00a0Implantation et am\u00e9nagement\u00a0de l\u2019atelier m\u00e9canique de la base de chantier<\/p>\n\n\n\n<p>\u2022\u00a0Gestion de l\u2019atelier\u00a0et de la planification des interventions;<\/p>\n\n\n\n<p>\u2022\u00a0Avec son \u00e9quipe\u00a0: entretien, suivi et r\u00e9paration du mat\u00e9riel et des engins de TP<\/p>\n\n\n\n<p>\u2022\u00a0Mise \u00e0 disposition\u00a0du mat\u00e9riel et des engins en mettant en place des actions de maintenance curative et en d\u00e9ployant une strat\u00e9gie de maintenance pr\u00e9ventive.<\/p>\n\n\n\n<p><em>RESPONSABILITES ET TACHES GENERALES<\/em>I.\u00a0<strong>Fonction\u00a0Gestion atelier et interventions<\/strong><\/p>\n\n\n\n<p>\u2022\u00a0Cr\u00e9er des indicateurs de performance pour l&rsquo;activit\u00e9 de maintenance et d\u00e9finir une strat\u00e9gie pr\u00e9ventive<\/p>\n\n\n\n<p>\u2022\u00a0Planifier et organiser le travail dans l&rsquo;atelier et les d\u00e9pannages<\/p>\n\n\n\n<p>\u2022\u00a0Assurer la gestion de l\u2019\u00e9quipe sous ses ordres<\/p>\n\n\n\n<p>\u2022\u00a0Conduire et contr\u00f4ler les op\u00e9rations d&rsquo;entretien courant<\/p>\n\n\n\n<p>\u2022\u00a0Suivre les prestations des fournisseurs<\/p>\n\n\n\n<p>\u2022\u00a0Proposer et suivre les commandes de l&rsquo;atelier<\/p>\n\n\n\n<p>\u2022\u00a0Proposer et suivre\u00a0l&rsquo;achat des pi\u00e8ces de rechange<\/p>\n\n\n\n<p>\u2022\u00a0R\u00e9ceptionner le mat\u00e9riel neuf<\/p>\n\n\n\n<p>\u2022\u00a0Assurer la gestion technique et financi\u00e8re des ressources mat\u00e9rielles et des \u00e9quipements de l&rsquo;atelier.<\/p>\n\n\n\n<p>\u2022\u00a0Optimiser les co\u00fbts de maintenance<\/p>\n\n\n\n<p>\u2022\u00a0Veiller au suivi des consommations de carburantII.<\/p>\n\n\n\n<p>\u00a0<strong>Fonction\u00a0Mise \u00e0 disposition et entretien du mat\u00e9riel<\/strong><\/p>\n\n\n\n<p>\u2022\u00a0Recenser les besoins en mat\u00e9riel et suivre la disponibilit\u00e9 des ressources stock\u00e9es ou immobilis\u00e9es.<\/p>\n\n\n\n<p><br>\u2022\u00a0Planifier et suivre l&rsquo;approvisionnement en mat\u00e9riel sur les chantiers en fonction du d\u00e9roulement des travaux en lien avec le coordonnateur SPS.<\/p>\n\n\n\n<p>\u2022\u00a0Mettre en place des actions de maintenance curative dans le cadre de r\u00e9paration lors d&rsquo;une casse ou d&rsquo;une panne.<\/p>\n\n\n\n<p>\u2022\u00a0Veiller \u00e0 une bonne utilisation du mat\u00e9riel et d\u00e9ployer une strat\u00e9gie de maintenance pr\u00e9ventive afin d&rsquo;anticiper les risques d&rsquo;usure.<\/p>\n\n\n\n<p>\u2022\u00a0D\u00e9livrer ou superviser les actions de formation sur le terrain aupr\u00e8s des nouveaux utilisateurs et veiller \u00e0 l&rsquo;application des consignes en mati\u00e8re de s\u00e9curit\u00e9.<\/p>\n\n\n\n<p>\u2022\u00a0V\u00e9rifier la conformit\u00e9 du mat\u00e9riel vis-\u00e0-vis de la r\u00e9glementation et pr\u00e9voir les actions d&rsquo;entretien et de mise \u00e0 niveau en cas de d\u00e9gradations ou d&rsquo;avaries.<\/p>\n\n\n\n<p><em>PROFIL RECHERCHE<\/em><\/p>\n\n\n\n<p>\u2022\u00a0Dipl\u00f4me bac +2 et 3 (BTS, DUT, licences professionnelles&#8230;) \u00e0 bac +5 (masters&#8230;) scientifiques ou techniques sp\u00e9cialis\u00e9s dans le BTP, la m\u00e9canique, la maintenance industrielle, la logistique ou en informatique industrielle<\/p>\n\n\n\n<p>\u2022\u00a0Dipl\u00f4me d&rsquo;ing\u00e9nieur g\u00e9n\u00e9raliste ou sp\u00e9cialis\u00e9 dans le secteur de la construction avec une dominante en m\u00e9canique ou en maintenance industrielle<\/p>\n\n\n\n<p>\u2022\u00a0Exp\u00e9rience solide\u00a0de minimum huit\u00a0(8) ans\u00a0sur\u00a0un poste similaire<\/p>\n\n\n\n<p>\u00a0\u2022\u00a0Bilingue fran\u00e7ais et anglais<\/p>\n\n\n\n<p>\u2022\u00a0Excellent bagage scientifique et technique, notamment dans les domaines de la m\u00e9canique, de l&rsquo;hydraulique, de l&rsquo;\u00e9lectrotechnique et en informatique industrielle<\/p>\n\n\n\n<p>\u2022\u00a0Bonne connaissance des\u00a0diff\u00e9rentes techniques d&rsquo;entretien et de r\u00e9paration du mat\u00e9riel TP<\/p>\n\n\n\n<p>\u2022\u00a0Bonne connaissance des\u00a0diff\u00e9rents engins TP utilis\u00e9s ainsi que\u00a0des marques<\/p>\n\n\n\n<p>\u2022\u00a0Tr\u00e8s bonne connaissance des imp\u00e9ratifs li\u00e9s \u00e0 l&rsquo;activit\u00e9 des \u00e9quipes travaux sur les chantiers ou sur les lignes de production<\/p>\n\n\n\n<p>\u2022\u00a0Connaissances en\u00a0informatique<\/p>\n\n\n\n<p>\u2022\u00a0Bon Manager, rigueur, organisation dans le travail<\/p>\n\n\n\n<p>\u2022\u00a0Bonne capacit\u00e9 de communication,\u00a0sens du relationnel et esprit d&rsquo;\u00e9quipe<\/p>\n\n\n\n<p>\u2022\u00a0Autonomie, r\u00e9activit\u00e9, m\u00e9thode, analyse des probl\u00e8mes<\/p>\n\n\n\n<p>\u2022\u00a0Autorit\u00e9, dynamisme. \u00c7<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CHEF D\u2019ATELIER MISSIONS Le\/la\u00a0Chef\u00a0Atelier\u00a0sous la supervision directe du Directeur\u00a0du mat\u00e9riel,\u00a0apour mission : \u2022\u00a0D\u00e9finition et mise en place d\u2019un plan g\u00e9n\u00e9ral de maintenance \u2022\u00a0D\u00e9finition et mise&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[1766,24],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"CHEF D\u2019ATELIER","emplois_employeur":2981,"emplois_date_publication":"2021-05-10","emplois_heure_publication":"","emplois_date_cloture":"2021-05-31","emplois_heure_cloture":"","emplois_experience_min":"2","emplois_experience_max":"3","emploi_email":"moukoudi.raissa@apave.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/14566"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=14566"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/14566\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/2982"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=14566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=14566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=14566"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=14566"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=14566"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=14566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}