{"id":14492,"date":"2021-05-08T14:54:40","date_gmt":"2021-05-08T12:54:40","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=14492"},"modified":"2021-05-10T13:51:40","modified_gmt":"2021-05-10T11:51:40","slug":"livreurs-easy-food","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/livreurs-easy-food\/","title":{"rendered":"Livreurs &#8211; EASY FOOD"},"content":{"rendered":"\n<p>Dans le cadre du lancement de ses activit\u00e9s, EASY FOOD, une startup de restauration mobile recrute des livreurs de nationalit\u00e9 Camerounaise \u00e2g\u00e9s de 18 \u00e0 30 ans pour la livraison de leurs repas servis dans des plats emport\u00e9s.<\/p>\n\n\n\n<p>EASY FOOD est un service de livraison de repas \u00e0 domicile, au bureau et partout ailleurs.<br>Vous \u00eates jeunes, vous savez o\u00f9 aimez vendre, vous avez l&rsquo;esprit d&rsquo;\u00e9quipe, alors ce plan de carri\u00e8re vous concerne<\/p>\n\n\n\n<p>Lieu du poste : Yaound\u00e9 ( TSINGA)<\/p>\n\n\n\n<p>Type de contrat : CDD : Essai payant \u00e0 une dur\u00e9e de 3 mois<\/p>\n\n\n\n<p>Nombre de Postulant : 10<\/p>\n\n\n\n<p>Profil :<br>\u2022 Femme\/Homme, Camerounais de nationalit\u00e9 et \u00e2g\u00e9e entre 18 \u00e0 30 ans ;<br>\u2022 Libre et disponible ;<br>\u2022 \u00catre dynamique, souriant, rigoureux et ponctuel ;<br>\u2022 Propre et de bonne moralit\u00e9 ;<br>\u2022 Une exp\u00e9rience acquise dans le secteur du marketing ou de la restauration rapide est un atout.<\/p>\n\n\n\n<p>Mission :<br>\u2022 Prospecter et recruter de nouveaux clients<br>\u2022 D\u00e9velopper et fid\u00e9liser votre portefeuille clients<br>\u2022 Effectuer des livraisons<br>\u2022 \u00c9couler son stock re\u00e7u journali\u00e8rement.<\/p>\n\n\n\n<p>Salaire :<\/p>\n\n\n\n<p>Il est variable, de 35 000 FCFA \u00e0 90 000 FCFA en fonction de vos performances.<\/p>\n\n\n\n<p>Constitution du dossier :<br>\u2022 Demande manuscrite \u00e0 la directrice de EASY-Food ;<br>\u2022 03 demi photos ;<br>\u2022 Photocopie de la CNI ;<br>\u2022 Plan de localisation ;<br>\u2022 Photocopie du dipl\u00f4me ou Attestation de formation (Un dipl\u00f4me en Marketing n\u2019est pas obligatoire) ;<br>\u2022 CNI d\u2019un tuteur o\u00f9 garantie morale et son num\u00e9ro de tel.<\/p>\n\n\n\n<p>A envoyer : \u00e0 la direction g\u00e9n\u00e9rale situ\u00e9 \u00e0 Tsinga ou<br>Sur WhatsApp par ce contact : 655929317<\/p>\n\n\n\n<p>Pour avoir des informations compl\u00e9mentaires, vous pouvez nous contacter au 655929317<\/p>\n\n\n\n<p>Les candidatures doivent \u00eatre d\u00e9pos\u00e9es au plus tard le 30 Juin 2021 \u00e0 15h30.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre du lancement de ses activit\u00e9s, EASY FOOD, une startup de restauration mobile recrute des livreurs de nationalit\u00e9 Camerounaise \u00e2g\u00e9s de 18 \u00e0&#8230;<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"closed","template":"","categories":[48],"tags":[],"villes":[136],"contrats":[236,234],"diplomes":[156,158,157,2259],"louma_meta":{"emploi_title":"Livreurs","emplois_employeur":14489,"emplois_date_publication":"2021-05-08","emplois_heure_publication":"","emplois_date_cloture":"2021-06-30","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"A envoyer : \u00e0 la direction g\u00e9n\u00e9rale situ\u00e9 \u00e0 Tsinga ou<br>Sur WhatsApp par ce contact : 655929317"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/14492"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=14492"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/14492\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/14490"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=14492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=14492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=14492"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=14492"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=14492"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=14492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}