{"id":14478,"date":"2021-05-08T13:52:29","date_gmt":"2021-05-08T11:52:29","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=14478"},"modified":"2021-05-08T13:52:33","modified_gmt":"2021-05-08T11:52:33","slug":"expert-e-national-e-en-developpement-des-cooperatives-noa-dc","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/expert-e-national-e-en-developpement-des-cooperatives-noa-dc\/","title":{"rendered":"Expert\/e National\/e en D\u00e9veloppement des Coop\u00e9ratives &#8211; NOA &#8211; DC"},"content":{"rendered":"\n<p>Expert\/e National\/e en D\u00e9veloppement des Coop\u00e9ratives &#8211; NOA &#8211; DC<\/p>\n\n\n\n<p>International Labour Organization (ILO)Bertoua (Cameroon)<\/p>\n\n\n\n<p><strong>Grade:\u00a0<\/strong>NOA, Entry Professional<\/p>\n\n\n\n<p><strong>Occupations:CHardshipLow<\/strong><\/p>\n\n\n\n<p><a rel=\"noreferrer noopener\" href=\"https:\/\/www.unjobnet.org\/jobs\/detail\/apply\/26152266\" target=\"_blank\" class=\"rank-math-link\">Apply Now<\/a><a>\u00a0Save<\/a>Added 3 days agoJOB DESCRIPTION<\/p>\n\n\n\n<p><strong>Grade:<\/strong>&nbsp;NOA<\/p>\n\n\n\n<p><strong>No. du poste:&nbsp;<\/strong>YAOUNDE\/DC\/NO\/2021\/03<br><strong>Date de publication: 04\/05\/2021<br>Date de cl\u00f4ture (minuit, heure de Yaound\u00e9): 20\/05\/2021<\/strong><\/p>\n\n\n\n<p><strong>Job ID:&nbsp;<\/strong>6068<br><strong>D\u00e9partment:<\/strong>&nbsp;BR-Afrique<br><strong>Unit\u00e9:&nbsp;<\/strong>ETD\/BP-Yaound\u00e9<br><strong>Lieu d&rsquo;affectation:&nbsp;<\/strong>Bertoua<br><strong>Type de contrat:<\/strong>Dur\u00e9e d\u00e9termin\u00e9e<\/p>\n\n\n\n<p><strong>Dur\u00e9e du contract:<\/strong>&nbsp;12 mois renouvelables<\/p>\n\n\n\n<p>Selon l\u2019Article 4.2 (e) du Statut du personnel, le pourvoi des postes vacants dans les projets de coop\u00e9ration technique n\u2019est pas r\u00e9gi dans le cadre de l\u2019Annexe I du Statut du personnel et se fait par choix direct du Directeur g\u00e9n\u00e9ral.<\/p>\n\n\n\n<p>Afin de pourvoir \u00e0 ce poste par s\u00e9lection directe le BIT invite les personnes int\u00e9ress\u00e9es \u00e0 soumettre leur candidature en ligne avant la date limite cit\u00e9e ci-dessus.<br><\/p>\n\n\n\n<p>Peuvent soumettre leur candidature:<\/p>\n\n\n\n<ul><li>Les candidats\/tes internes, en accord avec les paragraphes 31 et 32 de l&rsquo;Annexe I du statut du Personnel.<\/li><li>Les candidats\/tes externes*<\/li><\/ul>\n\n\n\n<p>*Le processus de recrutement des fonctionnaires nationaux est soumis aux crit\u00e8res sp\u00e9cifiques de recrutement local et d&rsquo;\u00e9ligibilit\u00e9.<\/p>\n\n\n\n<p>Les nominations avec des contrats de coop\u00e9ration technique ne conf\u00e8rent pas le droit \u00e0 une carri\u00e8re au BIT ni \u00e0 un renouvellement automatique de contrat ou une conversion pour un engagement d\u2019une autre nature au sein de l&rsquo;Organisation.\u00a0Un an de contrat \u00e0 dur\u00e9e d\u00e9termin\u00e9e sera accord\u00e9, cons\u00e9cutive \u00e0 l&rsquo;obtention de la clearance m\u00e9dicale.\u00a0Par ailleurs, les prolongations de contrats de coop\u00e9ration technique sont conditionn\u00e9es notamment aux \u00e9l\u00e9ments suivants: la disponibilit\u00e9 des fonds, la continuit\u00e9 du besoin des fonctions exerc\u00e9es et des services et une conduite satisfaisants.<\/p>\n\n\n\n<p>*Conditions d&#8217;emploi pour les candidats externes: Conform\u00e9ment \u00e0 la pratique en vigueur au BIT, le\/la candidat\/e ext\u00e9rieur\/e sera normalement recrut\u00e9\/e au premier \u00e9chelon de ce grade.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Introduction<\/strong><\/h2>\n\n\n\n<p>Depuis 2004\/2005, le Cameroun conna\u00eet un afflux massif des r\u00e9fugi\u00e9s fuyant la guerre civile et les pers\u00e9cutions en R\u00e9publique centrafricaine (RCA). Ces r\u00e9fugi\u00e9s sont concentr\u00e9s dans les R\u00e9gions de l\u2019Adamaoua, de l\u2019Est et du Nord. Selon un rapport du Haut-Commissariat des Nations-Unies pour les R\u00e9fugi\u00e9s (HCR) , le Cameroun comptait en ao\u00fbt 2020 un total 189 005 ( dont 98 238 femmes ) r\u00e9fugi\u00e9s centrafricains vivant dans la R\u00e9gion de l\u2019Est et pr\u00e8s de 64 636 (dont 33 611 femmes) dans la R\u00e9gion de l\u2019Adamaoua. Une enqu\u00eate effectu\u00e9e par le HCR aupr\u00e8s des r\u00e9fugi\u00e9s centrafricains en 2018 a r\u00e9v\u00e9l\u00e9 que pr\u00e8s de 74% parmi eux ont l\u2019intention de rester au Cameroun jusqu\u2019\u00e0 ce que la situation politique et s\u00e9curitaire dans leur pays se stabilise.<\/p>\n\n\n\n<p>Les femmes dans les communaut\u00e9s de r\u00e9fugi\u00e9s et d&rsquo;accueil de ces deux R\u00e9gions sont confront\u00e9es \u00e0 plusieurs types de discrimination et de violence. Jusqu\u2019\u00e0 ce jour, il existe une cohabitation pacifique entre les r\u00e9fugi\u00e9s et les populations h\u00f4tes. Cependant, il est urgent de promouvoir des voies de d\u00e9veloppement inclusives pour ces r\u00e9fugi\u00e9s et populations h\u00f4tes afin d&rsquo;am\u00e9liorer les moyens de subsistance de tous, r\u00e9duisant ainsi le potentiel de conflits li\u00e9s migrations transfrontali\u00e8res.<\/p>\n\n\n\n<p>En vue de contribuer \u00e0 la revitalisation des \u00e9conomies et \u00e0 la coh\u00e9sion sociale entre les r\u00e9fugi\u00e9s et les communaut\u00e9s d\u2019accueil dans les R\u00e9gions de l\u2019Adamaoua et de l\u2019Est, l\u2019Agence internationale de coop\u00e9ration cor\u00e9enne (KOICA) a d\u00e9cid\u00e9 de financer le projet \u00ab Autonomiser les femmes pour des \u00e9conomies r\u00e9silientes et des communaut\u00e9s pacifiques dans les r\u00e9gions de l&rsquo;Est et de l&rsquo;Adamaoua au Cameroun affect\u00e9es par les r\u00e9fugi\u00e9s\u00bb. En utilisant une approche de d\u00e9veloppement de syst\u00e8mes de march\u00e9, le Projet d\u00e9veloppe l\u2019entrepreneuriat f\u00e9minin et coop\u00e9ratif aupr\u00e8s des b\u00e9n\u00e9ficiaires tout en facilitant leur acc\u00e8s aux programmes de protection sociale susceptibles de pr\u00e9venir la violence sexiste (VBG) et le VIH \/ SIDA et d&rsquo;att\u00e9nuer leurs effets. Le projet a une dur\u00e9e de quatre ans de 2020 \u00e0 2024 qui comprend une phase de d\u00e9marrage au cours de laquelle le mod\u00e8le d&rsquo;intervention sera r\u00e9vis\u00e9 et finalis\u00e9.<\/p>\n\n\n\n<p>Le projet sera mis en \u0153uvre par le Bureau international du Travail (BIT), en partenariat avec diff\u00e9rentes parties prenantes (Agence de Promotion des Petites et Moyennes Entreprises du Cameroun, Collectivit\u00e9s locales, ONG travaillant avec les r\u00e9fugi\u00e9s, Prestataires de services d\u2019appui financiers et non-financiers).<\/p>\n\n\n\n<p>Le BIT cherche \u00e0 recruter un\/e Expert\/e national\/e en d\u00e9veloppement des coop\u00e9ratives pour appuyer le Conseiller technique principal du projet dans la mise en \u0153uvre du projet.<\/p>\n\n\n\n<p>Le poste est bas\u00e9 \u00e0 Bertoua, capitale r\u00e9gionale de l\u2019Est, au Cameroun, sous la supervision de l\u2019Equipe d\u2019appui technique de l\u2019OIT au travail d\u00e9cent et Bureau de pays pour le Cameroun, la Guin\u00e9e Equatoriale, Sao Tom\u00e9-et-Principe (ETD\/BP-Yaound\u00e9).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Fonctions et responsabilit\u00e9s essentielles<\/strong><\/h2>\n\n\n\n<p>Le\/La titulaire du poste travaillera en tant qu\u2019Expert\/e national\/e en d\u00e9veloppement des coop\u00e9ratives du Projet au Cameroun, sous la supervision directe du Conseiller technique principal du projet, bas\u00e9 \u00e0 Bertoua et sous la responsabilit\u00e9 g\u00e9n\u00e9rale du Directeur de l\u2019ETD\/BP-Yaound\u00e9.<\/p>\n\n\n\n<p>Le\/La titulaire b\u00e9n\u00e9ficiera de l\u2019appui technique du Service des Coop\u00e9ratives du D\u00e9partement ENTREPRISES au si\u00e8ge et d\u2019autres expert-e-s techniques de la sous-r\u00e9gion et du si\u00e8ge. Le\/La titulaire du poste sera responsable de la mise en \u0153uvre technique des activit\u00e9s li\u00e9es \u00e0 la composante 2 du Projet qui a pour r\u00e9sultat \u00ab Les femmes r\u00e9fugi\u00e9es et les populations h\u00f4tes ont cr\u00e9\u00e9 des entreprises \u00e9cologiques durables et florissantes et des organisations bas\u00e9es sur des membres telles que les coop\u00e9ratives\u00bb, ainsi que l&rsquo;identification des synergies avec d&rsquo;autres r\u00e9sultats et le soutien des activit\u00e9s connexes. Les activit\u00e9s au titre du r\u00e9sultat 2 comprennent le renforcement des capacit\u00e9s des r\u00e9fugi\u00e9s et des communaut\u00e9s d&rsquo;accueil par le biais des programmes de formation coop\u00e9rative de l&rsquo;OIT et d&rsquo;autres formations techniques, et la facilitation de l&rsquo;acc\u00e8s au financement et aux march\u00e9s, sur la base d\u2019une approche des syst\u00e8mes de march\u00e9 sensibles aux conflits.Advertisement<\/p>\n\n\n\n<p>Il\/Elle fera parfaite \u00e9quipe avec les autres Experts(es) et personnels du Projet, et effectuera son travail conform\u00e9ment aux r\u00e8gles et r\u00e8glements de l&rsquo;OIT, avec pour principales fonctions et responsabilit\u00e9s :<\/p>\n\n\n\n<p>\u2022 Contribuer \u00e0 l\u2019\u00e9laboration du plan de travail d\u00e9taill\u00e9 du Projet et sensible aux conflits et au genre, en pr\u00e9parant le plan de travail d\u00e9taill\u00e9 de la composante 2 du Projet avec des d\u00e9clinaisons mensuelles et trimestrielles sur la base des objectifs et des r\u00e9sultats attendus et suivre l\u2019ex\u00e9cution des activit\u00e9s;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>section facultatif (si besoin)<\/strong><\/h2>\n\n\n\n<p>\u2022 Collecter et analyser les informations n\u00e9cessaires \u00e0 la mise en \u0153uvre des activit\u00e9s de la composante 2; identifier les probl\u00e8mes potentiels et proposer des solutions ;<\/p>\n\n\n\n<p>\u2022 Elaborer et soumettre au gestionnaire du Projet les Termes de r\u00e9f\u00e9rences des activit\u00e9s relevant de la composante 2 du Projet ;<\/p>\n\n\n\n<p>\u2022 Mettre en \u0153uvre et assurer le suivi technique des activit\u00e9s de la composante 2, en \u00e9troite collaboration avec le Gestionnaire du projet, les sp\u00e9cialistes du BIT impliqu\u00e9s (notamment le sp\u00e9cialiste en d\u00e9veloppement des entreprises bas\u00e9 \u00e0 Yaound\u00e9 et le sp\u00e9cialiste en d\u00e9veloppement des coop\u00e9ratives bas\u00e9 \u00e0 Gen\u00e8ve) et les mandants tripartites du BIT dans les deux R\u00e9gions b\u00e9n\u00e9ficiaires, et en recourant en tant de besoin aux collaborateurs ext\u00e9rieurs et partenaires d\u2019ex\u00e9cution ;<\/p>\n\n\n\n<p>\u2022 Assurer l\u2019organisation des sessions de formation des prestataires de services locaux sur l\u2019utilisation des outils de formation en entrepreneuriat coop\u00e9ratif du BIT, y compris leur adaptation si n\u00e9cessaire;<\/p>\n\n\n\n<p>\u2022 Suivre les prestataires de services non-financiers b\u00e9n\u00e9ficiaires du Projet dans l\u2019ex\u00e9cution de leur contrats relatifs aux formations techniques et \u00e0 l\u2019accompagnement des coop\u00e9ratives b\u00e9n\u00e9ficiaires;<\/p>\n\n\n\n<p>\u2022 Faciliter l\u2019acc\u00e8s des r\u00e9fugi\u00e9s et des communaut\u00e9s h\u00f4tes accompagn\u00e9s \u00e0 travers l\u2019approche coop\u00e9rative aux produits et services financiers innovants ainsi qu\u2019aux march\u00e9s nationaux et internationaux ;<\/p>\n\n\n\n<p>\u2022 Contribuer \u00e0 la pr\u00e9paration des sessions du comit\u00e9 de pilotage, des missions d\u2019appui du BIT et des missions d\u2019\u00e9valuation du Projet dans les deux R\u00e9gions b\u00e9n\u00e9ficiaires ;<\/p>\n\n\n\n<p>\u2022 Appuyer l\u2019\u00e9dition et la publication des documents produits par le Projet, en \u00e9troite collaboration avec le Responsable de la communication de l\u2019ETD\/BP-Yaound\u00e9 ;<\/p>\n\n\n\n<p>\u2022 Fournir de fa\u00e7on r\u00e9guli\u00e8re les informations pertinentes relatives aux activit\u00e9s de la composante 2 et produire des notes d\u2019information sur la mise en \u0153uvre de la composante 2, en vue de l\u2019\u00e9laboration des rapports p\u00e9riodiques d\u2019avancement du Projet, en collaboration avec l\u2019assistant\/e en suivi-\u00e9valuation du Projet;<\/p>\n\n\n\n<p>\u2022 Ex\u00e9cuter d\u2019autres t\u00e2ches assign\u00e9es par le gestionnaire du Projet relevant des comp\u00e9tences du titulaire du poste.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Qualifications requises<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Formation<\/strong><\/h2>\n\n\n\n<p>Etre titulaire d\u2019un dipl\u00f4me universitaire de premier grade en sciences \u00e9conomiques, gestion d\u2019entreprise, gestion des coop\u00e9ratives, le genre dans le d\u00e9veloppement, agronome, agro-\u00e9conomiste ou autres domaines \u00e9quivalents.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Exp\u00e9rience<\/strong><\/h2>\n\n\n\n<p>Au moins deux ans d\u2019exp\u00e9rience av\u00e9r\u00e9e dans la promotion des coop\u00e9ratives, la finance rurale, l\u2019agriculture durable, et l\u2019autonomisation des femmes.<\/p>\n\n\n\n<p>La connaissance des produits du BIT en entrepreneuriat coop\u00e9ratif ou l\u2019utilisation d\u2019autres outils ou programmes en entrepreneuriat coop\u00e9ratif serait un atout.<\/p>\n\n\n\n<p>Une exp\u00e9rience professionnelle dans les R\u00e9gions de l\u2019Adamaoua\/de l\u2019Est ou de travail au profit des r\u00e9fugi\u00e9s seront des atouts suppl\u00e9mentaires.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Langues<\/strong><\/h2>\n\n\n\n<p>Parfaite ma\u00eetrise du fran\u00e7ais ou de l\u2019anglais (parl\u00e9 et bonnes capacit\u00e9s r\u00e9dactionnelles) et capacit\u00e9 \u00e0 parler et travailler dans la seconde langue.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Comp\u00e9tences<\/strong><\/h2>\n\n\n\n<p>\uf02d Bonne connaissance de l\u2019environnement juridique et fiscale des coop\u00e9ratives au Cameroun<br>\uf02d Aptitude \u00e0 interpr\u00e9ter les informations relatives au projet ainsi qu\u2019\u00e0 d\u00e9celer et \u00e0 analyser les probl\u00e8mes de mise en \u0153uvre.<br>\uf02d Aptitude \u00e0 collaborer avec les coll\u00e8gues et partenaires pour l\u2019atteinte d\u2019objectifs communs.<br>\uf02d Bonnes aptitudes r\u00e9dactionnelles.<br>\uf02d Aisance dans la communication orale et \u00e9crite.<br>\uf02d Aptitude \u00e0 travailler de fa\u00e7on autonome de m\u00eame qu\u2019au sein d\u2019une \u00e9quipe.<br>\uf02d Excellente aptitude \u00e0 la gestion du temps et tr\u00e8s bon sens de l\u2019organisation.<br>\uf02d Capacit\u00e9 prouv\u00e9e \u00e0 int\u00e9grer l\u2019analyse de genre dans la mise en \u0153uvre du projet.<br>\uf02d Capacit\u00e9 \u00e0 respecter les d\u00e9lais prescrits.<br>\uf02d Bonnes connaissance de logiciels usuels de bureautique (Word, Excel, PowerPoint) et de communications (internet et courrier \u00e9lectronique).<br>\uf02d Aptitude \u00e0 travailler dans un environnement multiculturel et \u00e0 adopter un comportement non discriminatoire et sensible aux consid\u00e9rations de genre.<\/p>\n\n\n\n<p><strong>Processus de recrutement<\/strong><\/p>\n\n\n\n<p>Veuillez noter que tous les candidats doivent remplir un formulaire de demande en ligne. Pour se faire, veuillez vous rendre sur le site&nbsp;<a href=\"https:\/\/performancemanager5.successfactors.eu\/login?company=ILO\" target=\"_blank\" rel=\"noreferrer noopener\">ILO People<\/a>. Le syst\u00e8me fournit les instructions n\u00e9cessaires afin de faciliter la proc\u00e9dure de demande en ligne.<\/p>\n\n\n\n<p><strong>Alerte \u00e0 la fraude<\/strong><\/p>\n\n\n\n<p>Le BIT ne facture aucun frais \u00e0 aucun moment du processus de recrutement, que ce soit au moment de postuler, pour l&rsquo;entretien, la proc\u00e9dure de recrutement proprement dite ou la formation. Les messages \u00e9manant d&rsquo;addresses email diff\u00e9rentes de celles du BIT &#8211; ilo@.org &#8211; ne doivent en aucun cas \u00eatre consid\u00e9r\u00e9es. En outre, le BIT n&rsquo;a pas besoin et ne demande pas de conna\u00eetre les informations relatives au compte bancaire du postulant.<\/p>\n\n\n\n<p><strong><u>NB<\/u><\/strong><strong>&nbsp;: \u00ab Le BIT attache une grande importance aux valeurs \u00e9thiques, \u00e0 la diversit\u00e9 parmi son personnel et vise \u00e0 assurer un \u00e9quilibre entre les sexes en son sein \u00bb.<\/strong><\/p>\n\n\n\n<p><strong>Seuls les candidats pr\u00e9s\u00e9lectionn\u00e9s seront contact\u00e9s pour les tests appropri\u00e9s.<\/strong><\/p>\n\n\n\n<p><strong>Le recrutement du candidat est conditionn\u00e9 par la r\u00e9ception et la disponibilit\u00e9 des fonds.<\/strong><a href=\"https:\/\/www.unjobnet.org\/jobs\/detail\/apply\/26152266\" target=\"_blank\" rel=\"noreferrer noopener\">Apply at ILO&rsquo;s Website<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Expert\/e National\/e en D\u00e9veloppement des Coop\u00e9ratives &#8211; NOA &#8211; DC<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[436],"tags":[2535],"villes":[136],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Expert\/e National\/e en D\u00e9veloppement des Coop\u00e9ratives - NOA - DC","emplois_employeur":6083,"emplois_date_publication":"2021-05-08","emplois_heure_publication":"","emplois_date_cloture":"2021-05-20","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"https:\/\/jobs.ilo.org\/job\/Bertoua-Experte-Nationale-en-D%C3%A9veloppement-des-Coop%C3%A9ratives-NOA-DC\/672314801\/"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/14478"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=14478"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/14478\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/6084"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=14478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=14478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=14478"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=14478"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=14478"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=14478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}