{"id":13553,"date":"2021-04-22T00:26:04","date_gmt":"2021-04-21T22:26:04","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=13553"},"modified":"2021-04-22T11:46:43","modified_gmt":"2021-04-22T09:46:43","slug":"offre-demploi-deux02-regleurs-gc","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/offre-demploi-deux02-regleurs-gc\/","title":{"rendered":"Offre d&#8217;emploi: DEUX(02) REGLEURS GC"},"content":{"rendered":"\n<p>Implant\u00e9 dans les 05 continents le groupe VINCI ENERGIES compte 69 400 collaborateurs repartis dans  53 pays. Dans un monde en \u00e9volution permanente VINCI ENERGIES acc\u00e9l\u00e8re le d\u00e9ploiement des nouvelles technologies pour concr\u00e9tiser. Au Cameroun, VINCI ENERGIES est repr\u00e9sent\u00e9 \u00e0 travers deux marques ACTEMIUM d\u00e9di\u00e9 industrie et OMEXOM sp\u00e9cialiste du Power et Grid. Ces deux marques offrent solutions et services \u00e9nerg\u00e9tiques \u00e0 haute valeur ajout\u00e9e.<\/p>\n\n\n\n<p>Pour int\u00e9grer notre service projet, nous recherchons deux R\u00e9gleurs GC.<\/p>\n\n\n\n<ul><li>MISSION: r\u00e9glage des embases des pyl\u00f4nes<\/li><li>LIAISON FONCTIONNELLE: et HIERARCHIQUE: Chef de projet<\/li><li>ACTIVITE PRINCIPALE: savoir r\u00e9gler les embases des massifs de pyl\u00f4nes 90KV\/225KV par les deux m\u00e9thodes ci-dessous:<ul><li>R\u00e9glage par tendeurs de r\u00e9glage;<\/li><li>R\u00e9glage par gabarits de r\u00e9glage d&rsquo;assainissement.<\/li><\/ul><\/li><\/ul>\n\n\n\n<p>Pr\u00e9requis:<\/p>\n\n\n\n<ul><li>Formation: niveau Bac F4 +2 (G\u00e9nie civil)<\/li><li>Conceptions et dimensionnement des ouvrages GC\/lecture et interpr\u00e9tation des plans GC;<\/li><li>maitrise du DAO et de la CAO (Auto card et autres logiciels de dessin et de conception GC);<\/li><li>connaissance minimum en \u00e9tude g\u00e9otechnique( \u00e9tude des sols);<\/li><li>connaissance basique en topographie( balisage, profil en long, piquetage, implantation et tra\u00e7age des fouilles suivant plan);<\/li><li>savoir \u00e9crire l&rsquo;anglais ou le fran\u00e7ais.<\/li><\/ul>\n\n\n\n<p>Qualit\u00e9s:<\/p>\n\n\n\n<p>rigoureux, respectueux des d\u00e9lais, disponible pour tous, honn\u00eate, flexible, sens des priorit\u00e9s et du devoir.<\/p>\n\n\n\n<p>L&rsquo;\u00e9quipe de RODDY et YOUSSEF sera ravie de vous accueillir dans ce projet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cegelec Cameroun recrute deux(02) R\u00e9gleurs GC pour ses services. Bien vouloir faire parvenir vos CV \u00e0 l&rsquo;adresseCameroun@vinci-energies.com avec en objet\u00a0\u00bb Recrutement R\u00e9gleurs GC.<br \/>\nNB: si vous n&rsquo;\u00eates pas contact\u00e9s apr\u00e8s dix jours, votre candidature n&rsquo;aura pas \u00e9t\u00e9 prise en compte. <\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[976,697],"tags":[10,2412,2413],"villes":[144],"contrats":[151],"diplomes":[162,248],"louma_meta":{"emploi_title":"Offre d'emploi: DEUX(02) REGLEURS GC","emplois_employeur":9315,"emplois_date_publication":"2021-04-21","emplois_heure_publication":"23:24","emplois_date_cloture":"2021-04-28","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"Cameroun@vinci-energies.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/13553"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=13553"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/13553\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/9316"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=13553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=13553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=13553"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=13553"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=13553"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=13553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}