{"id":12807,"date":"2021-04-05T13:34:39","date_gmt":"2021-04-05T11:34:39","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=12807"},"modified":"2021-04-05T13:34:42","modified_gmt":"2021-04-05T11:34:42","slug":"offre-demploi-02-assistantes-de-direction","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/offre-demploi-02-assistantes-de-direction\/","title":{"rendered":"Offre d&#8217;emploi: 02 ASSISTANTES DE DIRECTION"},"content":{"rendered":"\n<p>MC PROD recrute deux(02) Assistantes de Direction pour les besoins de ses services.<\/p>\n\n\n\n<p>Responsabilit\u00e9s:<\/p>\n\n\n\n<ul><li>Gestion du planning;<\/li><li>suivi et traitement du courrier;<\/li><li>organisation des d\u00e9placements;<\/li><li>pr\u00e9paration des r\u00e9unions;<\/li><li>participation \u00e0 la communication interne et externe de l&rsquo;entreprise.<\/li><\/ul>\n\n\n\n<p>Profil:<\/p>\n\n\n\n<ul><li>Etre \u00e2g\u00e9 entre 23 et 35ans;<\/li><li>avoir le sens de l&rsquo;organisation;<\/li><li>avoir l&rsquo;esprit d&rsquo;initiative;<\/li><li>\u00eatre disponible et \u00e0 l&rsquo;\u00e9coute;<\/li><li>bonnes qualit\u00e9s relationnelles;<\/li><li>\u00eatre \u00e0 l&rsquo;aise au t\u00e9l\u00e9phone;<\/li><li>\u00eatre polyvalente et r\u00e9active;<\/li><li>maitrise des outils bureautiques;<\/li><li>avoir une connaissance des r\u00e9seaux sociaux;<\/li><li>\u00eatre capable de g\u00e9rer un budget serait un atout;<\/li><li>avoir une bonne maitrise de la langue fran\u00e7aise ( \u00eatre bilingue serait un atout).<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>MC PROD recrute deux(02) Assistantes de Direction pour les besoins de ses services. CV+lettre de motivation+ photo enti\u00e8re r\u00e9cente \u00e0 faire parvenir \u00e0 l&rsquo;adresse: MCPROD70@GMAIL.COM<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[21,1182],"tags":[2297,4,2295],"villes":[135],"contrats":[234],"diplomes":[248,212],"louma_meta":{"emploi_title":"Offre d'emploi: 02 ASSISTANTES DE DIRECTION","emplois_employeur":6121,"emplois_date_publication":"2021-04-05","emplois_heure_publication":"12:34","emplois_date_cloture":"2021-04-05","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"MCPROD70@GMAIL.COM"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/12807"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=12807"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/12807\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/6122"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=12807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=12807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=12807"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=12807"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=12807"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=12807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}