{"id":12805,"date":"2021-04-05T13:11:10","date_gmt":"2021-04-05T11:11:10","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=12805"},"modified":"2021-04-05T13:11:13","modified_gmt":"2021-04-05T11:11:13","slug":"offre-demploi-administrateur-de-base-de-donnees","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/offre-demploi-administrateur-de-base-de-donnees\/","title":{"rendered":"Offre d&#8217;emploi: ADMINISTRATEUR DE BASE DE DONNEES"},"content":{"rendered":"\n<p>MC PROD recrute pour les besoins de ses services un Administrateur de Base de Donn\u00e9es.<\/p>\n\n\n\n<p>Profil:<\/p>\n\n\n\n<ul><li>Avoir des comp\u00e9tences en gestion des bases de donn\u00e9es;<\/li><li>\u00eatre capable de g\u00e9rer une base de donn\u00e9es, de la param\u00e9trer et de l&rsquo;am\u00e9liorer;<\/li><li>\u00eatre capable d&rsquo;analyser les besoins des utilisateurs;<\/li><li>avoir des bases en MySQL;<\/li><li>\u00eatre capable de r\u00e9diger les proc\u00e9dures, les expliquer et v\u00e9rifier leur application;<\/li><li>avoir des comp\u00e9tences en programmation informatique ( ayant les bases en programmation dans les langages suivants: Javascript, Java, Css3, Html5 et Php);<\/li><li>avoir des bases en algorithme informatique;<\/li><li>pouvoir \u00e9crire et faire ex\u00e9cuter les scripts ou requ\u00eates informatiques;<\/li><li>\u00eatre \u00e2g\u00e9 de 23 ans;<\/li><li>\u00eatre de bonne moralit\u00e9;<\/li><li>\u00eatre autonome et responsable.<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>MC PROD recrute un Administrateur de Base de Donn\u00e9es pour ses services. Les CV, lettre de motivation, photo enti\u00e8re r\u00e9cente \u00e0 faire parvenir \u00e0 l&rsquo;adresse:  MCPROD70@GMAIL.COM avec en objet RECRUTEMENT ADD<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[22],"tags":[2296,4,2295],"villes":[135],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Offre d'emploi: ADMINISTRATEUR DE BASE DE DONNEES","emplois_employeur":6121,"emplois_date_publication":"2021-04-05","emplois_heure_publication":"12:10","emplois_date_cloture":"2021-04-05","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"MCPROD70@GMAIL.COM"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/12805"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=12805"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/12805\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/6122"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=12805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=12805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=12805"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=12805"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=12805"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=12805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}