{"id":12721,"date":"2021-04-02T15:23:25","date_gmt":"2021-04-02T13:23:25","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=12721"},"modified":"2021-04-02T15:23:27","modified_gmt":"2021-04-02T13:23:27","slug":"prestation-de-services","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/prestation-de-services\/","title":{"rendered":"PRESTATION DE SERVICES"},"content":{"rendered":"\n<p>SMART SOLUTIONS ENGINEERING (SSE)<br>YAOUNDE-CAMEROUN<br>Ventes, Services; Conseil et R\u00e9alisation Tel : 674 44 66 51\/ 697467620\/ 667050341 E-mail djiyodenis@rocketmail.com<\/p>\n\n\n\n<p><br>PRESTATION DE SERVICES<\/p>\n\n\n\n<p><br>Vous avez besoin d\u2019un consultant en :<\/p>\n\n\n\n<p><br>\uf076 Etude d\u2019Impact Environnemental et Social (EIES) ;<\/p>\n\n\n\n<p><br>\uf076 Qualit\u00e9, Hygi\u00e8ne, S\u00e9curit\u00e9 et Environnement (QHSE) ; <\/p>\n\n\n\n<p>\uf076 R\u00e9alisation des audits (internes et externes) ;<\/p>\n\n\n\n<p><br>\uf076 \u00e9tudes de Danger,<\/p>\n\n\n\n<p><br>N\u2019h\u00e9sitez pas \u00e0 nous contacter, nous sommes la solution id\u00e9ale pour vous.<\/p>\n\n\n\n<p><br>Vous avez besoin d\u2019un consultant pour :<\/p>\n\n\n\n<p><br>\uf076 Surveillance et contr\u00f4le environnementale des projets ;<\/p>\n\n\n\n<p><br>\uf076 La mise en \u0153uvre et le suivi des mesures de sauvegardes<\/p>\n\n\n\n<p><br>environnementales et sociales ;<\/p>\n\n\n\n<p><br>\uf076 R\u00e9daction des termes de r\u00e9f\u00e9rences (TDR) ;<\/p>\n\n\n\n<p><br>\uf076 Analyse des caract\u00e9ristiques microbiologiques de l\u2019eau et normes de rejets<\/p>\n\n\n\n<p><br>\uf076 Gestion rationnelle de l\u2019exploitation <\/p>\n\n\n\n<p>industrielle des ressources hydriques<\/p>\n\n\n\n<p><br>\uf076 Gestion des d\u00e9chets (d\u00e9ch\u00e8terie) et \u00e9co-toxicologie<\/p>\n\n\n\n<p><br>\uf076 Mise en \u0153uvre et impl\u00e9mentations des clauses environnementales et<br>sociales des projets sous financement du Fonds Europ\u00e9en de<br>d\u00e9veloppement FED<\/p>\n\n\n\n<p><br>\uf076 R\u00e9daction des Plans de Gestion Environnementale et Sociale ;<br>\uf076 R\u00e9daction des Plans Hygi\u00e8ne Sant\u00e9 et S\u00e9curit\u00e9 ;<br>\uf076 R\u00e9daction des Plans de Gestion Plans de Protection de l\u2019environnement ;<br>\uf076 Elaboration des Plans de Signalisation ;<br>\uf076 R\u00e9alisation des diff\u00e9rentes inspections environnementales.<br>\uf076 R\u00e9dactions des plans d\u2019assurance qualit\u00e9 ;<br>\uf076Impl\u00e9mentation des Mesures de Sauvegardes environnementales et<br>Sociales<\/p>\n\n\n\n<p><br>\uf076 R\u00e9daction des m\u00e9thodologies d\u2019Avant Projets Sommaires dans le domaine<br>des \u00e9tudes d\u2019impact environnemental et social.<br>Appelez juste nos contacts (674446651\/ 697467620\/ 667050341)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SMART SOLUTIONS ENGINEERING (SSE)YAOUNDE-CAMEROUNVentes, Services; Conseil et R\u00e9alisation Tel : 674 44 66 51\/ 697467620\/ 667050341 E-mail djiyodenis@rocketmail.com PRESTATION DE SERVICES Vous avez besoin d\u2019un&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[1182],"tags":[],"villes":[136],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"PRESTATION DE SERVICES","emplois_employeur":12568,"emplois_date_publication":"2021-04-02","emplois_heure_publication":"","emplois_date_cloture":"2021-04-30","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"1","emploi_email":"djiyodenis@rocketmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/12721"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=12721"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/12721\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/12575"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=12721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=12721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=12721"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=12721"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=12721"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=12721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}