{"id":12172,"date":"2021-03-16T17:21:29","date_gmt":"2021-03-16T16:21:29","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=12172"},"modified":"2021-03-16T17:21:32","modified_gmt":"2021-03-16T16:21:32","slug":"chef-des-ventes-la-pasta-sa","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/chef-des-ventes-la-pasta-sa\/","title":{"rendered":"Chef des ventes LA PASTA SA"},"content":{"rendered":"\n<p>Le Groupe CADYST Consumer S.A. est une holding dont la mission est d\u2019apporter aux populations africaines des<br>produits de qualit\u00e9, respectant les standards internationaux, fabriqu\u00e9s localement et accessible \u00e0 tous.<br>Le Groupe CADYST Consumer S.A. est constitu\u00e9 de 3 soci\u00e9t\u00e9s : LA PASTA S.A, PANZANI Cameroun et SAE.<br>Pour les besoins de ses services \u00e0 Douala, la Direction Commerciale et Marketing de LA PASTA SA recherche des<br>candidat(es) au poste de :<br>Chef des ventes (01)<\/p>\n\n\n\n<p>Raison d\u2019\u00eatre du poste :<\/p>\n\n\n\n<p>Coordonner les op\u00e9rations de ventes sur l\u2019ensemble du territoire<br><\/p>\n\n\n\n<p>Missions principales :<\/p>\n\n\n\n<p>\u2022 Participer \u00e0 l\u2019\u00e9laboration de la strat\u00e9gie commerciale<br>\u2022 Elaborer et cascader les pr\u00e9visions de vente<br>\u2022 Mettre en \u0153uvre les plans d\u2019actions d\u00e9finis<br>\u2022 Prospecter et g\u00e9rer certains comptes clients<br>\u2022 R\u00e9aliser des objectifs quantitatifs et qualitatifs pour les diff\u00e9rentes unit\u00e9s<br>\u2022 S\u2019assurer de la couverture effective des zones dans lesquelles l\u2019entreprise est implant\u00e9e<br>\u2022 Contr\u00f4ler, animer et former l\u2019\u00e9quipe de vente<br>\u2022 Analyser les r\u00e9sultats et prendre les mesures correctives n\u00e9cessaires<br>\u2022 Effectuer la veille concurrentielle<br>\u2022 Faire un reporting r\u00e9gulier de l\u2019activit\u00e9<br><\/p>\n\n\n\n<p>Profil \/ Comp\u00e9tences cl\u00e9s :<\/p>\n\n\n\n<p>\u2022 Minimum dipl\u00f4me de Ma\u00eetrise en Commerce \/ Marketing \/ Vente ou \u00e9quivalent<br>\u2022 Exp\u00e9rience minimale de 07 ans dans la vente et\/ou le marketing dont 04 dans le management des \u00e9quipes<br>\u2022 Ma\u00eetrise parfaite du march\u00e9 FMCG<br>\u2022 Le bilinguisme Fran\u00e7ais \/Anglais est un atout<br>\u2022 Ma\u00eetrise de Microsoft Office<br><\/p>\n\n\n\n<p>Il \/elle doit avoir\/\u00eatre :<\/p>\n\n\n\n<p>\u2022 Avoir une forte capacit\u00e9 de n\u00e9gociation et de persuasion<br>\u2022 Le sens de l\u2019organisation<br>\u2022 Ouvert d\u2019esprit et dynamique<br>\u2022 Bon relationnel et p\u00e9dagogue<br>\u2022 Tenace<br>\u2022 La r\u00e9sistance au stress<br><\/p>\n\n\n\n<p>Partager les valeurs suivantes : Leadership \u2013 Professionnalisme \u2013 Responsabilit\u00e9 &#8211; Esprit d\u2019Equipe<br>Souhaitez-vous faire partie de cette aventure palpitante ? Souhaitez-vous rejoindre une \u00e9quipe jeune et dynamique,<br>dans un environnement en permanente mutation? Souhaitez-vous faire carri\u00e8re au sein d\u2019un Groupe \u00e0 fort potentiel<br>de croissance tant sur le plan national qu\u2019international, o\u00f9 votre potentiel, votre enthousiasme et votre<br>performance seront appr\u00e9ci\u00e9s \u00e0 leur juste valeur ?<br>Pour postuler rendez-vous sur notre site www.lapastacameroun.com \u00e0 l\u2019onglet \u00ab carri\u00e8re \u00bb menu \u00aboffre<br>d\u2019emploi \u00bb<br>D\u00e9lai de recevabilit\u00e9 des dossiers de candidature : 19\/03\/2021<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Groupe CADYST Consumer S.A. est une holding dont la mission est d\u2019apporter aux populations africaines desproduits de qualit\u00e9, respectant les standards internationaux, fabriqu\u00e9s localement&#8230;<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"closed","template":"","categories":[251,1273],"tags":[],"villes":[135],"contrats":[234,148],"diplomes":[163,159],"louma_meta":{"emploi_title":"Chef des ventes","emplois_employeur":5525,"emplois_date_publication":"2021-03-16","emplois_heure_publication":"","emplois_date_cloture":"2021-03-19","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":" www.lapastacameroun.com  \u00e0 l\u2019onglet \u00ab carri\u00e8re \u00bb menu \u00aboffre d\u2019emploi \u00bb"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/12172"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=12172"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/12172\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/5526"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=12172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=12172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=12172"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=12172"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=12172"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=12172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}