{"id":11981,"date":"2021-03-12T10:01:41","date_gmt":"2021-03-12T09:01:41","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=11981"},"modified":"2021-03-12T10:01:43","modified_gmt":"2021-03-12T09:01:43","slug":"un-chef-cuisinier","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/un-chef-cuisinier\/","title":{"rendered":"Un Chef Cuisinier"},"content":{"rendered":"\n<p><strong>REFERENCE ANNONCE :&nbsp;<\/strong>EMP\/NID1\/03\/2021\/3<\/p>\n\n\n\n<p><strong>Date d&rsquo;\u00e9ch\u00e9ance : 20 mars 2021<\/strong><\/p>\n\n\n\n<p><strong>Lieu de travail :&nbsp;&nbsp;<\/strong>LOGPOM (\u00e0 100 M\u00e8tres du Carrefour ANDEM)<\/p>\n\n\n\n<p>Plac\u00e9 sous l&rsquo;autorit\u00e9 fonctionnelle de la gestionnaire, l&rsquo;agent technique sp\u00e9cialis\u00e9 en restauration assure le bon fonctionnement du service de restauration de l&rsquo;\u00e9tablissement. Il coordonne l&rsquo;activit\u00e9 des autres agents participant \u00e0 la restauration et g\u00e8re le processus de production des repas&nbsp;<\/p>\n\n\n\n<p><strong>ACTIVITES PRINCIPALES&nbsp;<\/strong><\/p>\n\n\n\n<p>Les activit\u00e9s principales sont fix\u00e9es par les responsables de l&rsquo;\u00e9tablissement compte tenu du mode d&rsquo;organisation adopt\u00e9 :&nbsp;<\/p>\n\n\n\n<ul><li>propose, \u00e9labore et r\u00e9alise les menus en liaison avec le service de coordination&nbsp;<\/li><li>assure la confection et le suivi des repasdepuis la commandedes marchandises jusqu&rsquo;\u00e0leur distribution&nbsp;<\/li><li>contr\u00f4le l&rsquo;approvisionnement et la gestion des stocks des produits alimentaires&nbsp;<\/li><li>r\u00e9ceptionne les livraisons de produits alimentaires et contr\u00f4le leur conformit\u00e9&nbsp;<\/li><li>conseille sur les produits et mat\u00e9riels \u00e0 acqu\u00e9rir et pr\u00e9pare les commandes&nbsp;<\/li><li>\u00e9value les prix de revient dans le cadre qui lui estimparti&nbsp;<\/li><li>veille \u00e0 la di\u00e9t\u00e9tique et \u00e0 l&rsquo;hygi\u00e8ne alimentaire&nbsp;<\/li><li>encadre, organise et coordonne le travail des agents au sein du service de restauration&nbsp;<\/li><li>fait appliquer les r\u00e8gles de fabrication culinaire&nbsp;<\/li><li>surveille et contr\u00f4le la pr\u00e9paration des repas et la maintenance des mat\u00e9riels&nbsp;<\/li><li>veille \u00e0 l&rsquo;hygi\u00e8ne et \u00e0 la propret\u00e9 des locaux de cuisine&nbsp;<\/li><\/ul>\n\n\n\n<p>Service de restauration&nbsp;<\/p>\n\n\n\n<ul><li>participe au service de distribution des repas<\/li><li>participe au lavage des mat\u00e9riels, des mobiliers et des locaux de cuisine et de restauration.<\/li><\/ul>\n\n\n\n<p><strong>COMPETENCES NECESSAIRES A LA TENUE DU POSTE&nbsp;<\/strong><\/p>\n\n\n\n<p><em>Savoirs :&nbsp;<\/em><\/p>\n\n\n\n<ul><li>Titulaire au moins d&rsquo;un BTS en restauration\/ DQP en Cuisine\/ CAP en Cuisine&nbsp;<\/li><li>ma\u00eetrise des propri\u00e9t\u00e9s physiques, nutritionnelles&nbsp;<\/li><li>conna\u00eetre les r\u00e8gles pratiques d&rsquo;hygi\u00e8ne et de s\u00e9curit\u00e9 dans la restauration&nbsp;<\/li><li>animer et diriger une \u00e9quipe&nbsp;<\/li><li>conna\u00eetre les textes de base de la restauration&nbsp;<\/li><li>savoir g\u00e9rer les stocks&nbsp;<\/li><li>ma\u00eetrise de l&rsquo;art culinaire en restauration collective et les proportionn\u00e9ment&nbsp;<\/li><\/ul>\n\n\n\n<p><em>Savoir- faire :&nbsp;<\/em><\/p>\n\n\n\n<ul><li>organiser son travail en fonction de consignes orales ou \u00e9crites&nbsp;<\/li><li>respecter les normes d&rsquo;utilisation et de s\u00e9curit\u00e9 dans la r\u00e9alisation des travaux&nbsp;<\/li><\/ul>\n\n\n\n<p><em>Savoir-\u00eatre :&nbsp;<\/em><\/p>\n\n\n\n<ul><li>hygi\u00e8ne irr\u00e9prochable&nbsp;<\/li><li>organis\u00e9 et m\u00e9thodique&nbsp;<\/li><li>rigueur&nbsp;<\/li><li>discr\u00e9tion&nbsp;<\/li><li>esprit d&rsquo;\u00e9quipe&nbsp;<\/li><li>Leader&nbsp;<\/li><\/ul>\n\n\n\n<p>**********************************************************<\/p>\n\n\n\n<p><em>Pour postuler \u00e0 cette annonce, veuillez nous adresser votre candidature comprenant :<\/em><\/p>\n\n\n\n<ul><li><em>Une lettre de motivation adress\u00e9e<\/em><\/li><li><em>Un curriculum vitae<\/em><\/li><\/ul>\n\n\n\n<p><strong><em>IMPORTANT!<\/em><em>&nbsp;Toute candidature sans r\u00e9f\u00e9rence d&rsquo;annonce sera pur caduque<\/em><\/strong><\/p>\n\n\n\n<p><em>\u00e0 l&rsquo;adresse\u00a0<\/em><a rel=\"noreferrer noopener\" class=\"rank-math-link\" href=\"mailto:cv.campusjeunes@gmail.com\" target=\"_blank\"><em>cv.campusjeunes@gmail.com<\/em>\u00a0<\/a><strong><em>en indiquant dans l&rsquo;objet du mail la r\u00e9f\u00e9rence de l&rsquo;annonce \u00a0\u00bb EMP\/NID1\/03\/2021\/3 \u00ab\u00a0<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>REFERENCE ANNONCE :&nbsp;EMP\/NID1\/03\/2021\/3 Date d&rsquo;\u00e9ch\u00e9ance : 20 mars 2021 Lieu de travail :&nbsp;&nbsp;LOGPOM (\u00e0 100 M\u00e8tres du Carrefour ANDEM) Plac\u00e9 sous l&rsquo;autorit\u00e9 fonctionnelle de la&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[569],"tags":[],"villes":[136],"contrats":[236,234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Chef Cuisinier ","emplois_employeur":3046,"emplois_date_publication":"2021-03-12","emplois_heure_publication":"","emplois_date_cloture":"2021-03-20","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"3","emploi_email":"cv.campusjeunes@gmail.com "},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/11981"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=11981"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/11981\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/9483"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=11981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=11981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=11981"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=11981"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=11981"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=11981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}