{"id":11766,"date":"2021-03-08T09:37:00","date_gmt":"2021-03-08T08:37:00","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=11766"},"modified":"2021-03-09T12:38:46","modified_gmt":"2021-03-09T11:38:46","slug":"comptable-senior","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/comptable-senior\/","title":{"rendered":"COMPTABLE SENIOR"},"content":{"rendered":"\n<p>COMPTABLE SENIOR<\/p>\n\n\n\n<p>Partager18<br>Cible RH (DOUALA)<br>Publi\u00e9e : 2 mars, 2021<br>Domaine de l&rsquo;offre : COMPTABILITE et FINANCE Lieu : DOUALA<br>Type de l&rsquo;offre : Full Time<br>R\u00e9f\u00e9rence : CS-RH-07-03-20 _ Type de contrat : CDD _ CDI M\u00e9tier\/Sp\u00e9cialit\u00e9 : Comptabilit\u00e9 et finance : Douala, Littoral, CM ; Publication : 02-03-20<\/p>\n\n\n\n<p>NOTRE CLIENT<\/p>\n\n\n\n<p>Entreprise Camerounaise sp\u00e9cialis\u00e9e dans le b\u00e9ton, \u00e9tanch\u00e9it\u00e9, toiture, rev\u00eatement de sol, jointement et collage<\/p>\n\n\n\n<p>ACTIVITE(S) DU POSTE :<\/p>\n\n\n\n<p>Strat\u00e9gie<\/p>\n\n\n\n<p>Veiller au respect et \u00e0 l\u2019application des directives de la direction g\u00e9n\u00e9rale<\/p>\n\n\n\n<p>Mise en place du contr\u00f4le Interne et veiller \u00e0 la correcte application<\/p>\n\n\n\n<p>Contr\u00f4le<\/p>\n\n\n\n<p>Valider l\u2019exhaustivit\u00e9 du chiffre d\u2019affaires<\/p>\n\n\n\n<p>Coordonner le recouvrement client avec l\u2019assistance de l\u2019administration des ventes afin de diminuer l\u2019encours client<\/p>\n\n\n\n<p>Veiller \u00e0 la correcte application des proc\u00e9dures internes. (Effectuer des contr\u00f4les de mani\u00e8re r\u00e9currentes selon les directives de la DF) ;<\/p>\n\n\n\n<p>Participer au contr\u00f4le interne.<\/p>\n\n\n\n<p>Finance \/comptabilit\u00e9 :<\/p>\n\n\n\n<p>Contr\u00f4le des Saisies, pointage et lettrage des \u00e9critures comptables d\u2019achats et de ventes<\/p>\n\n\n\n<p>Gestion des charges constat\u00e9es d\u2019avances et proposition des \u00e9critures mensuelles<\/p>\n\n\n\n<p>Gestion des factures non parvenue et proposition des \u00e9critures mensuelles<\/p>\n\n\n\n<p>Gestion des investissements et comptabilisation<\/p>\n\n\n\n<p>Analyse des \u00e9critures de stock et en cours de route<\/p>\n\n\n\n<p>Contr\u00f4le et saisie des \u00e9critures de d\u00e9clarations mensuelles<\/p>\n\n\n\n<p>Contr\u00f4le et saisie des op\u00e9rations de cl\u00f4tures mensuelles et annuelles<\/p>\n\n\n\n<p>Participer \u00e0 l&rsquo;\u00e9laboration du bilan et du compte de r\u00e9sultat<\/p>\n\n\n\n<p>Participation au reporting<\/p>\n\n\n\n<p>Principale interlocuteur avec le CAC<\/p>\n\n\n\n<p>Envoi des lettres de circularisation<\/p>\n\n\n\n<p>Pr\u00e9paration rapport CAC<\/p>\n\n\n\n<p>Diverses t\u00e2ches du d\u00e9partement financier<\/p>\n\n\n\n<p>Participer \u00e0 l\u2019\u00e9laboration de la liasse fiscale<\/p>\n\n\n\n<p>Tr\u00e9sorerie :<\/p>\n\n\n\n<p>Rapprochement bancaire<\/p>\n\n\n\n<p>Suivi et saisie des op\u00e9rations de tr\u00e9sorerie<\/p>\n\n\n\n<p>Suivi des ch\u00e8ques arriv\u00e9s et d\u00e9part pour la banque<\/p>\n\n\n\n<p>Suivi de la tr\u00e9sorerie<\/p>\n\n\n\n<p>Pr\u00e9paration paiement<\/p>\n\n\n\n<p>Suivi caisse, contr\u00f4le inopin\u00e9 et inventaire mensuelle<\/p>\n\n\n\n<p>Communication, relation de travail et formation :<\/p>\n\n\n\n<p>Maintenir un climat de travail agr\u00e9able<\/p>\n\n\n\n<p>Participer au travail en \u00e9quipe et coacher les collaborateurs sous sa responsabilit\u00e9<\/p>\n\n\n\n<p>Participer aux r\u00e9unions propos\u00e9es par la direction g\u00e9n\u00e9rale et les autres structures si n\u00e9cessaire.<\/p>\n\n\n\n<p>Suivre les formations propos\u00e9es par les RH suivant planning de formation.<\/p>\n\n\n\n<p>PROFIL DU POSTE :<\/p>\n\n\n\n<p>Avoir minimum un Bac+4 en Comptabilit\u00e9 et finance<\/p>\n\n\n\n<p>Avoir au minimum 5 ann\u00e9es d\u2019exp\u00e9rience professionnelle dans une fonction similaire ;<\/p>\n\n\n\n<p>Exp\u00e9rience en cabinet d\u2019expertise comptable est un atout<\/p>\n\n\n\n<p>Parfaite Connaissance des proc\u00e9dures comptables et financi\u00e8re<\/p>\n\n\n\n<p>Maitrise des progiciels en comptabilit\u00e9<\/p>\n\n\n\n<p>Maitrise de l\u2019outil informatique et du pack office<\/p>\n\n\n\n<p>Maitrise des langues : fran\u00e7ais et anglais<\/p>\n\n\n\n<p>Savoir \u00eatre : Capacit\u00e9 d\u2019analyse et de synth\u00e8se, Sens de l&rsquo;organisation &amp; des priorit\u00e9s, Aisance relationnelle et sens de la confidentialit\u00e9, Proactivit\u00e9 et diplomatie, Polyvalence<\/p>\n\n\n\n<p>Bien vouloir envoyer votre curriculum vitae (CV) d\u00e9taill\u00e9 via le lien suivant :  HYPERLINK \u00ab\u00a0http:\/\/www.emplois.groupe-cible.com\u00a0\u00bb<\/p>\n\n\n\n<p>DATE LIMITE : 10 Mars 2021 \u00e0 12H00<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COMPTABLE SENIOR<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[282],"tags":[2197],"villes":[135],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"COMPTABLE SENIOR","emplois_employeur":2630,"emplois_date_publication":"2021-03-08","emplois_heure_publication":"","emplois_date_cloture":"2021-03-31","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"http:\/\/emplois.groupe-cible.com\/job\/comptable-senior-1#.YEXfnGhKhdg"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/11766"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=11766"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/11766\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/2631"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=11766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=11766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=11766"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=11766"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=11766"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=11766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}