{"id":11692,"date":"2021-03-05T06:41:06","date_gmt":"2021-03-05T05:41:06","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=11692"},"modified":"2021-03-05T06:41:09","modified_gmt":"2021-03-05T05:41:09","slug":"responsable-commercial-h-f","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/responsable-commercial-h-f\/","title":{"rendered":"Responsable Commercial H\/F"},"content":{"rendered":"\n<p>Responsable Commercial H\/F<\/p>\n\n\n\n<p>Lieu<\/p>\n\n\n\n<p>Kribi,&nbsp;SouthPubli\u00e9<\/p>\n\n\n\n<p>2 joursCat\u00e9gorie du poste<\/p>\n\n\n\n<p>Commerce, Business DevelopmentType de poste<\/p>\n\n\n\n<p>CDI &#8211; temps pleinExp\u00e9rience<\/p>\n\n\n\n<p>Non pr\u00e9cis\u00e9<a href=\"https:\/\/application.careerbuilder1.eu\/apave\/apply\/cb1\/J3T3867192085L7XWC3?IPath=TNJob&amp;Job_DID=J3T3867192085L7XWC3&amp;SiteID=cbnsv&amp;VID=VXA3ECDF3094B611EA90B001D84278736F2330FZ&amp;sc_cmp1=JS_JobDetails_ApplyNow&amp;TN_DID=TNKD38560K16M285NSH4&amp;language=fr\">Postuler<\/a><\/p>\n\n\n\n<p id=\"shareThisJDP\">Partager cette offre avec<a href=\"https:\/\/www.jobs.net\/jobs\/apave\/fr\/job\/Cameroon\/Responsable-Commercial-H-F\/J3T3867192085L7XWC3\/#\"><\/a><a href=\"https:\/\/www.jobs.net\/jobs\/apave\/fr\/job\/Cameroon\/Responsable-Commercial-H-F\/J3T3867192085L7XWC3\/#\"><\/a><a target=\"_blank\" href=\"https:\/\/www.jobs.net\/jobs\/apave\/fr\/job\/Cameroon\/Responsable-Commercial-H-F\/J3T3867192085L7XWC3\/#\" rel=\"noreferrer noopener\"><\/a><a target=\"_blank\" href=\"https:\/\/www.jobs.net\/jobs\/apave\/fr\/job\/Cameroon\/Responsable-Commercial-H-F\/J3T3867192085L7XWC3\/#\" rel=\"noreferrer noopener\"><\/a><a target=\"_blank\" href=\"https:\/\/www.jobs.net\/jobs\/apave\/fr\/job\/Cameroon\/Responsable-Commercial-H-F\/J3T3867192085L7XWC3\/#\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<p>Description du posteR\u00e9f\u00e9rence :CAD\/0321\/002536<\/p>\n\n\n\n<p>Type de contrat :&nbsp;CDI<\/p>\n\n\n\n<p>M\u00e9tier\/Sp\u00e9cialit\u00e9 :&nbsp;Transport \/ Logistique<\/p>\n\n\n\n<p>Localisation g\u00e9ographique :<br>Pays : Cameroun<br>Ville : Kribi, R\u00e9gion du Sud, CM<\/p>\n\n\n\n<p><strong>Notre soci\u00e9t\u00e9 :&nbsp;<\/strong><\/p>\n\n\n\n<p>Leader en recrutement sur le continent africain, Apave International vous propose chaque semaine de nombreuses opportunit\u00e9s de carri\u00e8re au sein d&rsquo;entreprises priv\u00e9es ou publiques et d&rsquo;Institutions Internationales.<\/p>\n\n\n\n<p><strong>Mission :&nbsp;<\/strong><\/p>\n\n\n\n<ul><li>Prospecter et analyser les besoins des clients, y apporter des r\u00e9ponses et n\u00e9gocier les propositions ;<\/li><li>Encadrer, animer et piloter l\u2019\u00e9quipe commerciale et marketing tant sur le d\u00e9veloppement commercial (avant-vente, prospection, montage des offres) que sur la r\u00e9alisation (mise en \u0153uvre, gestion des projets, allocation des ressources internes et externes) ;<\/li><li>Contribuer \u00e0 la rentabilit\u00e9 des nouveaux projets\/march\u00e9s apport\u00e9s et \u00e0 la profitabilit\u00e9 des activit\u00e9s y aff\u00e9rentes, dans le respect de la politique globale de l\u2019entreprise et des investisseurs ;<\/li><li>\u00c9tablir une collaboration efficace avec les autres services de la soci\u00e9t\u00e9 et notamment les fonctions supports, mettre en \u0153uvre la politique qualit\u00e9 et veiller au bon emploi des syst\u00e8mes d\u2019information par ses collaborateurs ;<\/li><li>Entretenir une veille sur les nouveaux mod\u00e8les\/march\u00e9s \u00e0 explorer pour enrichir le portefeuille du Terminal \u00e0 conteneurs, tout en respectant la plate-forme des partenaires et les attentes des clients ;<\/li><li>Participer \u00e0 la construction des business plans avec l&rsquo;aide de la direction financi\u00e8re ;<\/li><li>Identifiez les opportunit\u00e9s d\u2019affaires li\u00e9es \u00e0 l\u2019activit\u00e9 ou tout autre type de d\u00e9veloppement (nouveaux mod\u00e8les ou march\u00e9s) ;<\/li><li>Mettre en place une veille concurrentielle et de benchmarks r\u00e9guliers, afin d&rsquo;anticiper les \u00e9volutions du march\u00e9 et proposer les points d&rsquo;am\u00e9lioration ;<\/li><li>D\u00e9finir et les objectifs et contr\u00f4ler l&rsquo;activit\u00e9 des attach\u00e9s commerciaux;<\/li><li>Assurer les Reportings r\u00e9guliers de l&rsquo;activit\u00e9 commerciale de l&rsquo;entreprise.<\/li><\/ul>\n\n\n\n<p><strong>Profil :&nbsp;<\/strong><\/p>\n\n\n\n<ul><li>Formation initiale et dipl\u00f4mes : BAC + 5 en commerce international, action commerciale ou tout autre dipl\u00f4me \u00e9quivalent<\/li><li>Exp\u00e9rience professionnelle : Exp\u00e9rience cumul\u00e9e de 10 ans dont 7 ans un poste similaire et dans le secteur du transport maritime \/logistique impliquant la gestion commerciale, marketing, financi\u00e8re et budg\u00e9taire<\/li><li>Bonnes connaissances de l\u2019environnement portuaire et des m\u00e9tiers portuaires<\/li><li>Tr\u00e8s bonne maitrise des op\u00e9rations des terminaux portuaires<\/li><li>Solides connaissances du transport maritime<\/li><li>Connaissance de la l\u00e9gislation camerounaise en mati\u00e8re de transport, acconage et manutention portuaire<\/li><li>Bonnes connaissances de la finance pour non financiers et des aspects de rentabilit\u00e9<\/li><li>Maitrise des techniques de gestion et de management<\/li><\/ul>\n\n\n\n<p>Niveau d&rsquo;\u00e9tudes : MASTER 2 \/ BAC+5<\/p>\n\n\n\n<p>Sp\u00e9cialisation :&nbsp;Transport<\/p>\n\n\n\n<p>Niveau d&rsquo;exp\u00e9rience :&nbsp;Exp\u00e9riment\u00e9 (de 10 \u00e0 20 ans)<\/p>\n\n\n\n<p>Langues :&nbsp;<br>Anglais&nbsp;:&nbsp;Ma\u00eetrise courante<br>Fran\u00e7ais&nbsp;:&nbsp;Ma\u00eetrise courante<\/p>\n\n\n\n<p>Crit\u00e8res du poste<\/p>\n\n\n\n<ul><li>Formation initiale et dipl\u00f4mes : BAC + 5 en commerce international, action commerciale ou tout autre dipl\u00f4me \u00e9quivalent<\/li><li>Exp\u00e9rience professionnelle : Exp\u00e9rience cumul\u00e9e de 10 ans dont 7 ans un poste similaire et dans le secteur du transport maritime \/logistique impliquant la gestion commerciale, marketing, financi\u00e8re et budg\u00e9taire<\/li><li>Bonnes connaissances de l\u2019environnement portuaire et des m\u00e9tiers portuaires<\/li><li>Tr\u00e8s bonne maitrise des op\u00e9rations des terminaux portuaires<\/li><li>Solides connaissances du transport maritime<\/li><li>Connaissance de la l\u00e9gislation camerounaise en mati\u00e8re de transport, acconage et manutention portuaire<\/li><li>Bonnes connaissances de la finance pour non financiers et des aspects de rentabilit\u00e9<\/li><li>Maitrise des techniques de gestion et de management<\/li><\/ul>\n\n\n\n<p><a href=\"https:\/\/application.careerbuilder1.eu\/apave\/apply\/cb1\/J3T3867192085L7XWC3?IPath=TNJob&amp;Job_DID=J3T3867192085L7XWC3&amp;SiteID=cbnsv&amp;VID=VXA3ECDF3094B611EA90B001D84278736F2330FZ&amp;sc_cmp1=JS_JobDetails_ApplyNow&amp;TN_DID=TNKD38560K16M285NSH4&amp;language=fr\" class=\"rank-math-link\">Postuler<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Responsable Commercial H\/F<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[251],"tags":[],"villes":[145],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Responsable Commercial H\/F","emplois_employeur":2981,"emplois_date_publication":"2021-03-05","emplois_heure_publication":"","emplois_date_cloture":"2021-03-31","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"https:\/\/application.careerbuilder1.eu\/apave\/apply\/cb1\/J3T3867192085L7XWC3?IPath=TNJob&Job_DID=J3T3867192085L7XWC3&SiteID=cbnsv&VID=VXA3ECDF3094B611EA90B001D84278736F2330FZ&sc_cmp1=JS_JobDetails_ApplyNow&TN_DID=TNKD38560K16M285NSH4&language=fr"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/11692"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=11692"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/11692\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/2982"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=11692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=11692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=11692"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=11692"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=11692"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=11692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}