{"id":11371,"date":"2021-02-25T04:00:53","date_gmt":"2021-02-25T03:00:53","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=11371"},"modified":"2021-02-25T04:00:57","modified_gmt":"2021-02-25T03:00:57","slug":"appui-a-la-gestion-de-projet-analyste","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/appui-a-la-gestion-de-projet-analyste\/","title":{"rendered":"Appui \u00e0 la Gestion de Projet &#8211; Analyste"},"content":{"rendered":"\n<h1 class=\"wp-block-heading\">Appui \u00e0 la Gestion de Projet &#8211; Analyste<\/h1>\n\n\n\n<h2 class=\"wp-block-heading\">&nbsp;YAOUND\u00c9 (CAMEROON)<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.impactpool.org\/organizations\/unops-united-nations-office-for-project-services\"><img decoding=\"async\" src=\"https:\/\/d15l9woddkztht.cloudfront.net\/logos\/unops---united-nations-office-for-project-services-bf38db01-8412-4b04-a657-cb0b0cc2be16.svg\" alt=\"Unops   united nations office for project services bf38db01 8412 4b04 a657 cb0b0cc2be16\" \/><\/a><\/figure>\n\n\n\n<ul><li><strong>Organization:<\/strong>&nbsp;UNOPS &#8211; United Nations Office for Project Services<\/li><li><strong>Location:<\/strong>&nbsp;Yaound\u00e9 (Cameroon)<\/li><li><strong>Grade:<\/strong>&nbsp;LICA-8, Local Individual Contractors Agreement &#8211; Junior level<\/li><li><strong>Occupational Groups:<\/strong><ul><li>Project and Programme Management<\/li><li>Operations and Administrations<\/li><li>Legal &#8211; Broad<\/li><li>Legal &#8211; International Law<\/li><\/ul><\/li><li><strong>Closing Date:<\/strong>&nbsp;2021-03-03<\/li><\/ul>\n\n\n\n<p>SAVE JOB<a href=\"https:\/\/www.impactpool.org\/jobs\/676587#\"><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">BACKGROUND INFORMATION &#8211; JOB-SPECIFIC<\/h2>\n\n\n\n<p>Le bureau de l\u2019UNOPS au Cameroun a ouvert en D\u00e9cembre 2019, et compte plusieurs projets \u00e0 son actif, dont la nature varie de la construction, aux \u00e9tudes techniques dans diff\u00e9rents secteurs, aux activit\u00e9s WASH, \u00e0 la gestion de ressources humaines pour d\u2019autres entit\u00e9s, aux achats y compris dans le domaine m\u00e9dical (COVID-19).<\/p>\n\n\n\n<p>Le bureau travaille constamment \u00e0 \u00e9tendre ses activit\u00e9s afin d\u2019appuyer ses partenaires dans la mise en \u0153uvre de leurs programmes et projets de d\u00e9veloppement.&nbsp;<\/p>\n\n\n\n<p>Le bureau du Cameroun est li\u00e9 au bureau CDOH bas\u00e9 en RDC. Depuis 1999, le bureau a diversifi\u00e9 et renforc\u00e9 ses domaines d\u2019expertise, contribuant ainsi activement aux efforts de d\u00e9veloppement durable men\u00e9s sur le terrain. Il poss\u00e8de une vaste expertise qui couvre la r\u00e9habilitation et la construction d\u2019infrastructures de base (services sociaux et administratifs), de routes et de ponts, ainsi que l\u2019achat de biens et de services, en plus de proposer des services de gestion et de soutien aux projets.Le.la charg\u00e9.e d\u2019appui au projet rend compte au chef de projet, qui le.la supervise et lui fournit des directives. Le.la charg\u00e9.e d\u2019appui au projet soutient le chef de projet dans les activit\u00e9s quotidiennes, la coordination et la mise en \u0153uvre de la mission. Cette personne surveille \u00e9troitement les op\u00e9rations et la performance financi\u00e8re, d\u00e9tecte les probl\u00e8mes potentiels, soutient l\u2019analyse des probl\u00e8mes et l\u2019\u00e9laboration de solutions, coordonne la r\u00e9solution des probl\u00e8mes selon les mesures adopt\u00e9es, r\u00e9dige les correspondances aux parties prenantes concern\u00e9es et pr\u00e9pare les rapports de mission. Le.la charg\u00e9.e d\u2019appui au projet peut souvent devoir travailler dans des environnements complexes et difficiles avec des ressources limit\u00e9es.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">LA R\u00c9PUBLIQUE D\u00c9MOCRATIQUE DU CONGO<\/h2>\n\n\n\n<p>L\u2019UNOPS CDOH, le Centre Op\u00e9rationnel pour l\u2019Afrique Central &nbsp;en R\u00e9publique d\u00e9mocratique du Congo (RDC) fournit des services depuis son bureau principal bas\u00e9 \u00e0 Kinshasa RDC. Le bureau de CDOH couvre 11 pays en Afrique Centrale et Australe tels que la RDC, la R\u00e9publique du Congo, la R\u00e9publique Centrafricaine, le Cameroun, le Burundi, le Rwanda, le Gabon, la Guin\u00e9e Equatoriale, Madagascar, Angola et Comores.<\/p>\n\n\n\n<p>&nbsp;L\u2019organisation r\u00e9pond aux besoins du gouvernement de la RDC gr\u00e2ce au financement des donateurs bilat\u00e9raux, de la Banque Mondiale, d\u2019institutions financi\u00e8res internationales et d\u2019agences des Nations Unies. L\u2019UNOPS en RDC fournit un large \u00e9ventail de services de gestion de projets et d\u2019autres services connexes, y compris en mati\u00e8re d\u2019achats, de gestion de contrats, de logistique, de ressources humaines et de gestion financi\u00e8re.<\/p>\n\n\n\n<p>L\u2019UNOPS aide ses partenaires \u00e0 atteindre les objectifs de leurs projets, notamment dans les domaines des infrastructures physiques et sociales, des \u00e9lections et de la protection de l\u2019environnement.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">FUNCTIONAL COMPETENCIES<\/h2>\n\n\n\n<p>1. La mise en \u0153uvre du projet<\/p>\n\n\n\n<ul><li>Pr\u00e9parer et maintenir les dossiers du projet, notamment les rapports de projet internes et externes.<\/li><li>G\u00e9rer le flux d\u2019information, le contr\u00f4le de changements, le registre des risques et la r\u00e9solution des probl\u00e8mes en \u00e9tablissant des proc\u00e9dures de contr\u00f4le des documents.<\/li><li>Assurer l\u2019avanc\u00e9e des activit\u00e9s et la livraison des lots de travaux.<\/li><li>Assurer la coordination avec le chef de projet et lui communiquer l\u2019avanc\u00e9e des travaux.<\/li><li>Informer et conseiller le chef de projet \u00e0 l\u2019\u00e9gard de tout \u00e9cart par rapport au plan et effectuer les mises \u00e0 jour n\u00e9cessaires.<\/li><li>Relever et g\u00e9rer les risques en collaboration avec le chef de projet.<\/li><\/ul>\n\n\n\n<p>2. La gestion des finances et des achats<\/p>\n\n\n\n<ul><li>Tenir \u00e0 jour et classer tous les documents financiers du projet \u00e0 des fins de v\u00e9rification et d\u2019examen.<\/li><li>Assurer la saisie exacte des donn\u00e9es dans le progiciel de gestion int\u00e9gr\u00e9 de l\u2019UNOPS.<\/li><li>Assurer le suivi des d\u00e9penses et du budget du projet ainsi que de l\u2019ensemble des proc\u00e9dures administratives conform\u00e9ment au plan de travail.<\/li><li>Traiter les paiements directs et les demandes de paiement anticip\u00e9, et pr\u00e9parer les r\u00e9visions budg\u00e9taires du projet.&nbsp;<\/li><li>\u00c9laborer les rapports financiers en adoptant des contr\u00f4les financiers et des mod\u00e8les de rapport conformes aux exigences de l\u2019UNOPS.<\/li><li>Soutenir le chef de projet en assurant le suivi des budgets et de la tr\u00e9sorerie, et rendre compte des obligations relatives aux d\u00e9penses afin d\u2019assurer le respect du calendrier.<\/li><li>Avertir le chef de projet de tout d\u00e9ficit financier ou de d\u00e9penses excessives.<\/li><li>Proposer des r\u00e9visions budg\u00e9taires et prendre les mesures correctives n\u00e9cessaires.<\/li><li>Coordonner les rencontres, les communications et les rapports n\u00e9cessaires avec les fournisseurs.<\/li><\/ul>\n\n\n\n<p>3. Le suivi et l\u2019\u00e9laboration de rapports&nbsp;<\/p>\n\n\n\n<ul><li>Participer activement \u00e0 la pr\u00e9paration de rapports et de documents de projet en assistant le chef de projet.<\/li><li>Tenir \u00e0 jour et classer les documents du projet et les autres documents de soutien.<\/li><li>G\u00e9rer les dossiers suivants&nbsp;: registre d\u2019assurance de la qualit\u00e9, registres de configuration et tous les autres registres et dossiers indiqu\u00e9s par le chef de projet.<\/li><li>Soutenir le chef de projet en assurant la gestion des \u00e9l\u00e9ments suivants&nbsp;:&nbsp;i. Dossier \u00e9lectronique;&nbsp;ii. Documents se rapportant aux achats, aux ressources humaines et aux finances, conform\u00e9ment aux exigences de la&nbsp;directive organisationnelle no&nbsp;12.<\/li><li>G\u00e9rer la compilation, la consolidation et l\u2019analyse des donn\u00e9es utiles \u00e0 la mission.<\/li><li>Assister le chef de projet dans la pr\u00e9paration des rapports d\u2019ach\u00e8vement du projet et assurer le respect des obligations contractuelles.<\/li><\/ul>\n\n\n\n<p>4. La coordination et la gestion des parties prenantes et des communications<\/p>\n\n\n\n<ul><li>Soutenir la coordination et la gestion des communications.<\/li><li>Communiquer et b\u00e2tir des relations solides avec d\u2019autres agences des Nations Unies et des organisations non gouvernementales (ONG) internationales afin de faciliter la mise en \u0153uvre des activit\u00e9s et d\u2019am\u00e9liorer la qualit\u00e9 et la pertinence des donn\u00e9es et analyses.<\/li><li>Selon les besoins, participer \u00e0 des rencontres avec des agences des Nations Unies, des ONG et d\u2019autres parties prenantes.<\/li><\/ul>\n\n\n\n<p>5. La gestion des connaissances et l\u2019innovation&nbsp;<\/p>\n\n\n\n<ul><li>Soutenir la gestion des le\u00e7ons apprises conform\u00e9ment au syst\u00e8me de rapport choisi.<\/li><li>Assurer le renforcement des capacit\u00e9s locales \u00e0 tous les niveaux et favoriser les occasions de soutien au projet.<\/li><li>Contribuer \u00e0 la diffusion et au partage des bonnes pratiques et le\u00e7ons apprises en mati\u00e8re de planification et de renforcement des connaissances.<\/li><li>Apporter son expertise dans l\u2019utilisation d\u2019outils et de techniques.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">EDUCATION<\/h2>\n\n\n\n<p>Le\/la candidat.e doit \u00eatre titulaire d\u2019un dipl\u00f4me de Licence en administration des affaires, logistique, gestion de crise, comptabilit\u00e9, relations internationales ou toute autre discipline pertinente. Un dipl\u00f4me universitaire de premier cycle combin\u00e9 \u00e0 deux (2) ann\u00e9es d\u2019exp\u00e9rience professionnelle suppl\u00e9mentaire peut \u00eatre accept\u00e9 au lieu de l\u2019exigence mentionn\u00e9e ci-dessus.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">EXPERIENCE<\/h2>\n\n\n\n<ul><li>Le\/la candidat.e doit poss\u00e9der au moins deux (2) ann\u00e9es d\u2019exp\u00e9rience pertinente avec prise de responsabilit\u00e9s progressive, principalement ax\u00e9es sur la supervision, la production de rapports, le d\u00e9veloppement et la coordination, dans le domaine de la gestion de projets et d\u2019activit\u00e9s.<\/li><li>Le\/la candidat.e doit avoir au moins une ann\u00e9e d\u2019exp\u00e9rience dans le domaine de la comptabilit\u00e9 et de gestion financi\u00e8re.<\/li><li>Une exp\u00e9rience de travail dans des contextes d\u2019aide humanitaire d\u2019urgence ainsi qu\u2019une bonne connaissance des m\u00e9canismes de coordination humanitaire, des donateurs, des mesures de s\u00e9curit\u00e9 et des activit\u00e9s dans ce domaine est souhaitable.<\/li><li>Une connaissance av\u00e9r\u00e9e des r\u00e8gles et proc\u00e9dures des Nations Unies dans les domaines des achats, des finances, des ressources humaines ainsi que la connaissance des r\u00e8gles et r\u00e8glements administratifs des Nations Unies sont un atout.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">LANGUAGES<\/h2>\n\n\n\n<p>Une excellente connaissance du fran\u00e7ais et de l\u2019Anglais est essentielle.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">CERTIFICATIONS<\/h2>\n\n\n\n<p>Les cours de base ou de praticien&nbsp;PRINCE2\u00ae sont un atout.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">COMPETENCIES FR<\/h2>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><\/td><td><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><\/td><td>D\u00e9montre une compr\u00e9hension des effets de son r\u00f4le sur tous les partenaires et accorde la priorit\u00e9 aux b\u00e9n\u00e9ficiaires. Forge et entretient des relations externes fortes et constitue un partenaire comp\u00e9tent pour les autres (si cela s\u2019applique \u00e0 son r\u00f4le).<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><\/td><td>\u00c9value les donn\u00e9es et les processus afin de prendre des d\u00e9cisions logiques et pragmatiques. Adopte une approche neutre et rationnelle en calculant les risques. Applique l\u2019innovation et la cr\u00e9ativit\u00e9 \u00e0 une d\u00e9marche de r\u00e9solution des probl\u00e8mes.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><\/td><td>\u00c9tablit efficacement une s\u00e9rie de mesures pour soi- m\u00eame et pour les autres pour atteindre un objectif. Les actions pos\u00e9es m\u00e8nent \u00e0 l\u2019accomplissement total de la t\u00e2che en respectant les exigences de qualit\u00e9 dans tous les domaines. Rep\u00e8re les possibilit\u00e9s et prend des initiatives pour les saisir. Comprend qu\u2019un usage responsable des ressources optimise l\u2019effet de nos activit\u00e9s aupr\u00e8s des b\u00e9n\u00e9ficiaires.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><\/td><td>Traite tous les individus avec respect ; accorde de la consid\u00e9ration aux diff\u00e9rences et encourage les autres \u00e0 faire de m\u00eame. Incarne les normes \u00e9thiques et organisationnelles. R\u00e9pond \u00e0 de hautes exigences en mati\u00e8re d\u2019honn\u00eatet\u00e9. Est un mod\u00e8le pour les questions de diversit\u00e9 et d\u2019inclusion.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><\/td><td>Ouvert au changement et flexible dans un environnement tr\u00e8s dynamique. Adapte efficacement son approche pour suivre l\u2019\u00e9volution des circonstances ou des besoins. Apprend de son exp\u00e9rience et modifie son comportement. Ses r\u00e9sultats sont coh\u00e9rents, m\u00eame sous pression. Cherche continuellement l\u2019am\u00e9lioration.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><\/td><td>Exprime des id\u00e9es ou faits de mani\u00e8re claire, concise et ouverte. La communication indique une consid\u00e9ration pour les sentiments et les besoins des autres. \u00c9coute activement et partage ses connaissances spontan\u00e9ment. G\u00e8re les conflits efficacement en respectant les diff\u00e9rences et en trouvant un terrain d\u2019entente.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><\/td><td>Agit comme exemple positif contribuant \u00e0 l\u2019esprit d\u2019\u00e9quipe. Collabore et soutient le perfectionnement des autres. Pour les responsables seulement : agit en tant qu\u2019exemple positif de leadership, motive, dirige et inspire les autres \u00e0 r\u00e9ussir, utilise des styles de leadership appropri\u00e9s.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">CONTRACT TYPE, LEVEL AND DURATION<\/h2>\n\n\n\n<p>Contract type: Local Individual Contractor Agreements (LICA)<br>Contract level: LICA 8<br>Contract duration: Ongoing ICA &#8211; Open ended, subject to organizational requirements, availability of funds and satisfactory performance.<\/p>\n\n\n\n<p>For more&nbsp;details about the ICA contractual modality, please follow this link:<br><a href=\"https:\/\/www.unops.org\/english\/Opportunities\/job-opportunities\/what-we-offer\/Pages\/Individual-Contractor-Agreements.aspx\">https:\/\/www.unops.org\/english\/Opportunities\/job-opportunities\/what-we-offer\/Pages\/Individual-Contractor-Agreements.aspx<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">CONSID\u00c9RATIONS SUPPL\u00c9MENTAIRES<\/h2>\n\n\n\n<ul><li>Veuillez noter que l\u2019offre d\u2019emploi prend fin \u00e0 la date de cl\u00f4ture, \u00e0 minuit, heure de Copenhague (heure d\u2019Europe centrale).<\/li><li>Les candidatures re\u00e7ues apr\u00e8s la date de cl\u00f4ture ne seront pas examin\u00e9es.<\/li><li>Seuls les candidats pr\u00e9s\u00e9lectionn\u00e9s pour l\u2019entretien seront contact\u00e9s.<\/li><li><strong>Nous encourageons vivement les femmes qualifi\u00e9es \u00e0 postuler.<\/strong><\/li><li>Pour les postes de fonctionnaires, l\u2019UNOPS se r\u00e9serve le droit d\u2019affecter un candidat \u00e0 un poste de niveau moins \u00e9lev\u00e9 que celui publi\u00e9 dans cette annonce.<\/li><li>Le candidat s\u00e9lectionn\u00e9 est tenu de respecter les politiques de s\u00e9curit\u00e9, les instructions administratives, les plans et les proc\u00e9dures de l\u2019UNOPS et du Syst\u00e8me de gestion de la s\u00e9curit\u00e9 de l\u2019ONU.<\/li><\/ul>\n\n\n\n<p><em>La politique de l\u2019UNOPS exige de proc\u00e9der \u00e0 la v\u00e9rification des r\u00e9f\u00e9rences de tous les candidats potentiels \u00e0 un poste ou un stage. Ces v\u00e9rifications sont d\u00e9terminantes pour l\u2019embauche.<br><br><strong>\u00c9quilibre entre le travail et la vie personnelle:&nbsp;&nbsp;<\/strong>L&rsquo;UNOPS accorde de la valeur \u00e0 son personnel et reconna\u00eet l&rsquo;importance de maintenir un \u00e9quilibre entre les responsabilit\u00e9s professionnelles et personnelles. Nous avons une politique progressiste en la mati\u00e8re et offrons plusieurs possibilit\u00e9s d&rsquo;horaires flexibles. Cette politique s&rsquo;applique au personnel de l&rsquo;UNOPS et pour tout type de contrats.&nbsp;<br><br>L&rsquo;UNOPS cherche \u00e0 accommoder raisonnablement les candidats ayant des besoins particuliers, sur demande.&nbsp;<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">INFORMATIONS G\u00c9N\u00c9RALES SUR L\u2019UNOPS<\/h2>\n\n\n\n<p>La mission de l\u2019UNOPS consiste \u00e0 aider les personnes d\u00e9munies en renfor\u00e7ant la capacit\u00e9 des Nations Unies, des gouvernements et de ses autres partenaires \u00e0 mener leurs activit\u00e9s en mati\u00e8re d\u2019infrastructures, d\u2019achats et de gestion de projets de mani\u00e8re durable et efficace.<\/p>\n\n\n\n<p>Au sein de ces trois principaux domaines d\u2019expertise, l\u2019organisation fournit \u00e0 ses partenaires des services transactionnels, de conseils et de mise en \u0153uvre, pour des projets allant de la construction d\u2019\u00e9coles et d\u2019h\u00f4pitaux \u00e0 l\u2019achat de biens et de services, en passant par la formation de travailleurs locaux. L\u2019UNOPS travaille en \u00e9troite collaboration avec des gouvernements et des communaut\u00e9s afin d\u2019assurer la durabilit\u00e9 \u00e9conomique, sociale et environnementale des projets que l\u2019organisation soutient, avec un int\u00e9r\u00eat particulier pour le renforcement des capacit\u00e9s nationales.<\/p>\n\n\n\n<p>L\u2019UNOPS intervient dans des contextes parmi les plus difficiles au monde et sa vision consiste \u00e0 am\u00e9liorer les pratiques de mise en \u0153uvre durables dans les domaines du d\u00e9veloppement, de l\u2019aide humanitaire et de la consolidation de la paix, tout en satisfaisant ou d\u00e9passant syst\u00e9matiquement les attentes de ses partenaires.<\/p>\n\n\n\n<p>Comptant plus de 7000 membres du personnel dans plus de 80 pays, l&rsquo;UNOPS apporte \u00e0 ses partenaires les connaissances logistiques, techniques et de gestion dont ils ont besoin, peu importe l&rsquo;endroit o\u00f9 ils en ont besoin. Sa structure flexible et sa port\u00e9e internationale permettent \u00e0 l&rsquo;organisation de r\u00e9pondre rapidement aux besoins de ses partenaires tout en g\u00e9n\u00e9rant des \u00e9conomies d&rsquo;\u00e9chelle.\u00a0<em>We do our best to provide you the most accurate info, but closing dates may be wrong on our site. Please check on the recruiting organization&rsquo;s page for the exact info. Candidates are responsible for complying with deadlines and are encouraged to submit applications well ahead.<\/em>Before applying, please make sure that you have read the requirements for the position and that you qualify.<br><strong>Applications from non-qualifying applicants will most likely be discarded by the recruiting manager.<\/strong><a rel=\"noreferrer noopener\" class=\"rank-math-link\" target=\"_blank\" href=\"https:\/\/jobs.unops.org\/Pages\/ViewVacancy\/VADetails.aspx?id=21196\">APPLY<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Appui \u00e0 la Gestion de Projet &#8211; Analyste<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[1139,436],"tags":[2121],"villes":[136],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Appui \u00e0 la Gestion de Projet - Analyste","emplois_employeur":9492,"emplois_date_publication":"2021-02-25","emplois_heure_publication":"","emplois_date_cloture":"2021-03-25","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"https:\/\/jobs.unops.org\/Pages\/ViewVacancy\/VADetails.aspx?id=21196"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/11371"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=11371"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/11371\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/9493"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=11371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=11371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=11371"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=11371"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=11371"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=11371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}