{"id":11330,"date":"2021-02-25T02:38:20","date_gmt":"2021-02-25T01:38:20","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=11330"},"modified":"2021-02-25T02:38:22","modified_gmt":"2021-02-25T01:38:22","slug":"commerciaux-h-f-douala","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/commerciaux-h-f-douala\/","title":{"rendered":"COMMERCIAUX (H\/F) \u2013 Douala"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">COMMERCIAUX (H\/F) \u2013 Douala<\/h2>\n\n\n\n<h4 class=\"wp-block-heading\"><a href=\"https:\/\/web.doopinet.com\/doojobs\">Un Employeur<\/a><\/h4>\n\n\n\n<p>&nbsp;Douala, Littoral, Cameroon&nbsp;\u00b7&nbsp;<\/p>\n\n\n\n<p>&nbsp;09 Mar. 2021&nbsp;\u00b7&nbsp;<\/p>\n\n\n\n<p>&nbsp;Permanent \/ CDI&nbsp;\u00b7&nbsp;<\/p>\n\n\n\n<p>&nbsp;Commerce &#8211; Vente &#8211; Distribution&nbsp;\u00b7&nbsp;<\/p>\n\n\n\n<p>\u00a0Commercial<\/p>\n\n\n\n<p><strong>Description<\/strong>Recrutement des Commerciaux<br>Une soci\u00e9t\u00e9 de la place, soci\u00e9t\u00e9 de vente et de distribution du mat\u00e9riel m\u00e9dical recherche pour les besoins de ses services,des Commerciauxdans les villes de Douala, Yaound\u00e9 et Bafoussam.<br><strong>Poste bas\u00e9 \u00e0<\/strong>: Douala, Yaound\u00e9 et Bafoussam<br><strong>Prise de poste<\/strong>: D\u00e8s que possible<br><strong>Salaire<\/strong>: A n\u00e9gocier\u00a0<\/p>\n\n\n\n<p><strong>Missions \/ Responsabilit\u00e9s \/ Activit\u00e9s<\/strong><\/p>\n\n\n\n<ul><li>Prospection commerciale dans les diff\u00e9rentes zones d\u00e9finies par le responsable commerciale<\/li><li>Cr\u00e9er, suivre et d\u00e9velopper le portefeuille client<\/li><li>N\u00e9gocier et conclure les ventes<\/li><li>Enregistrer les commandes et assurer les livraisons<\/li><li>Assurer le service apr\u00e8s-vente<\/li><li>Promouvoir l&rsquo;image et la notori\u00e9t\u00e9 de l&rsquo;entreprise<\/li><li>Etre attentif aux \u00e9volutions du march\u00e9, aux offres du march\u00e9 et aux offres de la concurrence afin d&rsquo;adapter en permanence les offres de l&rsquo;entreprise<\/li><li>N\u00e9gocier les partenariats commerciaux<\/li><li>Mettre en place des m\u00e9thodes et des actions commerciales<\/li><li>Analyser les r\u00e9sultats g\u00e9n\u00e9raux des ventes, proposer des actions de d\u00e9veloppement et d&rsquo;ajustement des offres de l&rsquo;entreprise<\/li><li>Parfaite ma\u00eetrise du marketing et des techniques de vente<\/li><li>Fid\u00e9liser la client\u00e8le<\/li><\/ul>\n\n\n\n<p><strong>Comp\u00e9tences \/ Exigences \/ Qualit\u00e9s<\/strong><strong>Profil recherch\u00e9 :<\/strong><\/p>\n\n\n\n<ul><li>Bac+2 en action commercial \/ Marketing \/ Commerce \/ Vente<\/li><li>02 ans d&rsquo;exp\u00e9rience professionnelle en tant que commercial<\/li><li>Ma\u00eetrise de l&rsquo;outil informatique<\/li><li>Sens relationnel pouss\u00e9<\/li><li>Ma\u00eetrise de Microsoft office.<\/li><li>Connaissance d&rsquo;un ERP<\/li><\/ul>\n\n\n\n<p><strong>Qualit\u00e9s attendues :<\/strong><\/p>\n\n\n\n<ul><li>Dynamisme, rigueur, Initiative, pers\u00e9v\u00e9rance, esprit de synth\u00e8se ;<\/li><li>Forte capacit\u00e9 d&rsquo;autonomie et d&rsquo;adaptation ;<\/li><li>Capacit\u00e9 de travailler dans un environnement multiculturel ;<\/li><li>Capacit\u00e9s d&rsquo;analyse, d&rsquo;organisation, d&rsquo;adaptation et de pr\u00e9sentation ;<\/li><li>Capacit\u00e9 \u00e0 remettre en cause mais aussi \u00e0 proposer d&rsquo;autres axes de mani\u00e8re constructive ;<\/li><li>Travail sous pression ;<\/li><li>Discr\u00e9tion et sens de la confidentialit\u00e9 ;<\/li><li>Travail en \u00e9quipe ;<\/li><li>Respect des d\u00e9lais.<\/li><\/ul>\n\n\n\n<p><strong>Profil du candidat<\/strong>\u00bb Niveau d&rsquo;exp\u00e9rience: Exp\u00e9riment\u00e9<br>\u00bb Ann\u00e9es d&rsquo;exp\u00e9rience: Entre 1 an et 3 ans<br>\u00bb Niveau Acad\u00e9mique Minimum: Bac+2 (BTS \/ HND,&#8230;)<br><strong>Documents de candidature<\/strong>\u00bb Curriculum Vitae<br>\u00bb Lettre de Motivation<br><strong>Instructions de candidature<\/strong><\/p>\n\n\n\n<p>Pour postuler, envoyez votre candidature \u00e0\u00a0<a rel=\"noreferrer noopener\" class=\"rank-math-link\" href=\"mailto:recrutement.intermed@yahoo.com\" target=\"_blank\">recrutement.intermed@yahoo.com<\/a>\u00a0au plus tard le 9\u00a0Mars 2021.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COMMERCIAUX (H\/F) \u2013 Douala<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[251],"tags":[2112],"villes":[135],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"COMMERCIAUX (H\/F) \u2013 Douala","emplois_employeur":3046,"emplois_date_publication":"2021-02-25","emplois_heure_publication":"","emplois_date_cloture":"2021-03-25","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"recrutement.intermed@yahoo.com "},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/11330"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=11330"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/11330\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/9483"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=11330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=11330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=11330"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=11330"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=11330"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=11330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}