{"id":11041,"date":"2021-02-19T07:11:49","date_gmt":"2021-02-19T06:11:49","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=11041"},"modified":"2021-02-19T07:53:38","modified_gmt":"2021-02-19T06:53:38","slug":"une-01-responsable-mission-pour-le-suivi-evaluation-redevabilite-apprentissage","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/une-01-responsable-mission-pour-le-suivi-evaluation-redevabilite-apprentissage\/","title":{"rendered":"UN(E) (01) RESPONSABLE MISSION POUR LE SUIVI EVALUATION REDEVABILITE APPRENTISSAGE"},"content":{"rendered":"\n<p><strong>PREMIERE URGENCE&nbsp; INTERNATIONALE RECHERCHE UN(E) (01) RESPONSABLE MISSION POUR LE SUIVI EVALUATION REDEVABILITE APPRENTISSAGE<\/strong><\/p>\n\n\n\n<p><strong><u>Contexte<\/u><\/strong><\/p>\n\n\n\n<p>Premi\u00e8re Urgence Internationale (PUI) est une Organisation Non Gouvernementale de solidarit\u00e9 internationale, \u00e0 but non lucratif, apolitique et la\u00efque. Elle a pour objectif de r\u00e9pondre \u00e0 l\u2019ensemble des besoins fondamentaux des victimes civiles mises en p\u00e9ril, marginalis\u00e9es ou exclues par les effets de catastrophes naturelles, de guerres et de situations d\u2019effondrement \u00e9conomique. PUI est pr\u00e9sente dans 19 pays, en Afrique, en Asie, au Moyen-Orient, dans le Caucase et les Cara\u00efbes, et intervient dans les domaines de la s\u00e9curit\u00e9 alimentaire, la sant\u00e9, la nutrition, la r\u00e9habilitation d\u2019infrastructures, l\u2019eau et l\u2019assainissement et la relance \u00e9conomique.<\/p>\n\n\n\n<p>PUI est pr\u00e9sente au Cameroun depuis 2008 et vient en aide aux r\u00e9fugi\u00e9s centrafricains, nig\u00e9rians et aux populations vuln\u00e9rables camerounaises, par le biais de projets dans les secteurs de l\u2019acc\u00e8s \u00e0 l\u2019eau, \u00e0 l\u2019hygi\u00e8ne et l\u2019assainissement, la s\u00e9curit\u00e9 alimentaire, la construction de logements, la gestion de site de r\u00e9fugi\u00e9s, dans les R\u00e9gions de l\u2019Est, de l\u2019Adamaoua, du Nord et de L\u2019Extr\u00eame Nord. Enfin depuis 2017, PUI est en charge de d\u00e9velopper le m\u00e9canisme de r\u00e9ponse rapide aux mouvements de population dans la r\u00e9gion de l\u2019Extr\u00eame nord.<\/p>\n\n\n\n<p><strong><u>Objectif global&nbsp;:<\/u><\/strong><\/p>\n\n\n\n<p><strong><\/strong>Sous la responsabilit\u00e9 directe du\/de la CDM Adjoint(e) aux programmes, le\/la responsable de Suivi Evaluation Redevabilit\u00e9 Apprentissage (SERA) est en charge de la mise en place d\u2019une strat\u00e9gie SERA sur l\u2019ensemble de la mission, en lien fonctionnel avec les Charg\u00e9s SERA bas\u00e9s sur chacune des zones d\u2019intervention de PUI. Ses missions principales sont les suivantes&nbsp;:<\/p>\n\n\n\n<ul><li>Contribuer \u00e0 l\u2019\u00e9laboration de la strat\u00e9gie SERA et protection transversale \/ genre et veiller \u00e0 son impl\u00e9mentation au sein de tous les projets mis en place au Cameroun<\/li><li>Renforcer en continu les capacit\u00e9s des \u00e9quipes SERA et op\u00e9rationnelles dans la gestion des enqu\u00eates<\/li><li>Veiller \u00e0 l\u2019harmonisation des processus d\u2019archivage des Sources de v\u00e9rification programme sur les bases et en coordination<\/li><li>Appuyer la r\u00e9daction des rapports bailleurs dans ses domaines de comp\u00e9tences<\/li><li>Coordonner la r\u00e9alisation d\u2019enqu\u00eates sur toutes les bases ne disposant pas de Ressources humaines SERA.<\/li><\/ul>\n\n\n\n<p><strong><u>Responsabilit\u00e9s et champs d\u2019actions:<\/u><\/strong><\/p>\n\n\n\n<ol><li><strong>DEVELOPPEMENT ET MISE EN OEUVRE DE LA STRATEGIE SERA DE LA MISSION<\/strong><\/li><li><strong>RENFORCEMENT DE CAPACITES DES EQUIPES SERA<\/strong><\/li><li><strong>GESTION DES SOURCES DE VERIFICATION &amp; ARCHIVAGE<\/strong><\/li><li><strong>CAPITALISATION &amp; APPUI AU REPORTING \/ DEVELOPPEMENT DE PROJETS<\/strong><\/li><li><strong>APPUI&nbsp; ET SUPERVISION DES ENQUETES \/VEILLE<\/strong><\/li><\/ol>\n\n\n\n<p><strong><u>Objectifs sp\u00e9cifiques et activit\u00e9s associ\u00e9es<\/u><\/strong><\/p>\n\n\n\n<p><strong>1. DEVELOPPEMENT ET MISE EN OEUVRE DE LA STRATEGIE SERA DE LA MISSION<\/strong><\/p>\n\n\n\n<ul><li>Travailler, en collaboration avec les \u00e9quipes programme, sur la conception et l\u2019am\u00e9lioration des m\u00e9canismes de suivi et \u00e9valuation participatifs.<\/li><li>S\u2019assurer de la mise en place du plan de redevabilit\u00e9 et plus particuli\u00e8rement de gestion des plaintes, y compris dans les propositions de projets<\/li><li>S\u2019assurer que la planification du projet mis en \u0153uvre par PUI int\u00e8gre des activit\u00e9s de monitoring, des r\u00e9unions de lancement&nbsp; de pilotage de projet, de redevabilit\u00e9 et de capitalisation.<\/li><li>Bas\u00e9 sur le plan de monitoring, \u00e9laborer des outils de suivi et mod\u00e8les des sources de v\u00e9rification pour chaque projet<\/li><li>Elaborer et mettre \u00e0 jour en lien avec les charg\u00e9s SERA ou les RP un calendrier des activit\u00e9s SERA et les \u00e9ch\u00e9ances de remont\u00e9e de sources de v\u00e9rification et la planification des enqu\u00eates pour chacun des projets.<\/li><li>Sensibiliser les \u00e9quipes programme et support \u00e0 l\u2019importance du SERA et ses enjeux pour faciliter la collaboration et le respect des \u00e9ch\u00e9ances<\/li><li>Mettre en place un syst\u00e8me d\u2019alerte pour l\u2019\u00e9quipe programme au travers la diffusion d\u2019\u00e9tats des lieux r\u00e9guliers SERA par projet pour r\u00e9orienter\/r\u00e9ajuster le projet pour en am\u00e9liorer la qualit\u00e9 (Conformit\u00e9 des donn\u00e9es collect\u00e9es avec les indicateurs contractuels)<\/li><li>Veiller \u00e0 l\u2019int\u00e9gration et au respect du genre et des principes de protection et DoNoHarm dans tous les projets<\/li><li>S\u2019assurer de la mise en place au sein de tous les projets de PUI d\u2019un cadre clair de redevabilit\u00e9 et de remont\u00e9e des plaintes et retours des communaut\u00e9s<\/li><li>Elaborer en lien avec les agents et charg\u00e9s SERA&nbsp; ou en leur absence les responsables de projet, un plan de monitoring pour chacun des projets permettant d\u2019identifier les donn\u00e9es \u00e0 collecter et les m\u00e9canismes de collecte selon les indicateurs fix\u00e9s dans les documents projets contractuels<\/li><li>Effectuer des visites de contr\u00f4le (y compris inopin\u00e9s) sur les bases et sous bases pour v\u00e9rifier la mise en place de la strat\u00e9gie de SERA<\/li><li>Fournir \u00e0 chaque membre de l\u2019\u00e9quipe programme arrivant sur la mission l\u2019ensemble des outils et des le\u00e7ons apprises disponibles sur son volet d\u2019intervention.<\/li><\/ul>\n\n\n\n<p><strong>2. RENFORCEMENT DE CAPACITES DES EQUIPES SERA<\/strong><\/p>\n\n\n\n<ul><li>Assurer la supervision technique de tous les agents et charg\u00e9s SERA de la mission<\/li><li>Assurer un suivi rapproch\u00e9 de leur travail conform\u00e9ment au plan de monitoring \u00e9labor\u00e9 en d\u00e9but de projet<\/li><li>Former les \u00e9quipes SERA et les \u00e9quipes projets \u00e0 la mise en \u0153uvre de la strat\u00e9gie SERA<\/li><li>Participer au renforcement des \u00e9quipes op\u00e9rationnelles sur les th\u00e9matiques transversales (genre&nbsp;; protection&nbsp;; protection des donn\u00e9es&nbsp;; redevabilit\u00e9) et la gestion d\u2019enqu\u00eate (m\u00e9thodologie d\u2019\u00e9chantillonnage&nbsp;; traitement et analyse des donn\u00e9es).<\/li><li>Participer \u00e0 la formation des \u00e9quipes terrain sur le suivi des activit\u00e9s ainsi que la collecte des donn\u00e9es. Assurer un suivi technique de toutes les \u00e9quipes SERA et programme dans son domaine de comp\u00e9tences&nbsp;<\/li><li>Veiller \u00e0 la qualit\u00e9 des donn\u00e9es rapport\u00e9es par le terrain<\/li><li>Renforcer les capacit\u00e9s des \u00e9quipes en charge de la gestion des plaintes sur les bases<\/li><\/ul>\n\n\n\n<p><strong>3. GESTION DES SOURCES DE VERIFICATION &amp; ARCHIVAGE<\/strong><\/p>\n\n\n\n<ul><li>Renforcer les capacit\u00e9s des \u00e9quipes programme et SERA sur la proc\u00e9dure d\u2019archivage et veiller \u00e0 sa mise en application sur chaque projet<\/li><li>Assurer l\u2019archivage des documents contractuels des projets aussi bien num\u00e9rique et physique en coordination<\/li><li>Assurer la diffusion des rapports d\u2019activit\u00e9 et des outils de suivi pour faciliter la mise en \u0153uvre des activit\u00e9s et l\u2019\u00e9change d\u2019exp\u00e9rience entre les bases via la dropbox.<\/li><li>Appuyer et former les Charg\u00e9s SERA \/ RP dans la conception des outils de suivi des Sources de v\u00e9rification<\/li><li>S\u2019assurer que les mod\u00e8les de sources de v\u00e9rification sont disponibles et diffus\u00e9s<\/li><li>V\u00e9rifier la conformit\u00e9 et la coh\u00e9rence des donn\u00e9es collect\u00e9es au travers des sources de v\u00e9rification avec les objectifs contractuellement fix\u00e9s.&nbsp;<\/li><li>V\u00e9rifier que les sources de v\u00e9rification et leurs outils de suivi sont d\u00fbment compl\u00e9t\u00e9es et envoy\u00e9es par les Charg\u00e9s SERA selon les \u00e9ch\u00e9ances fix\u00e9es<\/li><li>Tenir \u00e0 jour les outils de suivi des sources de v\u00e9rification au niveau de la coordination et v\u00e9rifier ceux remplis au niveau de chaque base.<\/li><\/ul>\n\n\n\n<p><strong>4. CAPITALISATION &amp; APPUI AU REPORTING \/ DEVELOPPEMENT DE PROJETS<\/strong><\/p>\n\n\n\n<ul><li>Veiller \u00e0 l\u2019harmonisation des pratiques entre les bases en produisant ou mettant \u00e0 jour les outils en place&nbsp;<\/li><li>Veiller \u00e0 la capitalisation des activit\u00e9s SERA (planification&nbsp;; mise en \u0153uvre&nbsp;; r\u00e9sultats obtenus) afin d\u2019accro\u00eetre le savoir-faire de la mission.<\/li><li>Promouvoir les exercices de capitalisation des le\u00e7ons apprises et meilleures pratiques au niveau de la mission et veiller \u00e0 la diss\u00e9mination aupr\u00e8s des \u00e9quipes<\/li><li>Accompagner les \u00e9quipes (SERA \/ RP) techniquement et valider l\u2019outil de suivi mensuel des projets avant partage \u00e0 la Cheffe de mission Adjointe programmes<\/li><li>Contribuer au reporting bailleurs pour les parties concern\u00e9es<\/li><li>Assurer, dans le cadre de d\u00e9veloppement de propositions de projets, le partage d\u2019informations capitalis\u00e9es existantes sur les zones et th\u00e9matiques cibl\u00e9es ;<\/li><\/ul>\n\n\n\n<p><strong>5.&nbsp;APPUI \/ SUPERVISION DES ENQUETES&nbsp;\/ VEILLE<\/strong><\/p>\n\n\n\n<ul><li>Appuyer les agents et charg\u00e9s SERA\/ RP dans l\u2019\u00e9laboration et la r\u00e9alisation des enqu\u00eates<\/li><li>Valider les m\u00e9thodologies et outils d\u2019enqu\u00eate pour s\u2019assurer de l\u2019adaptation de ceux-ci avec les indicateurs fix\u00e9s<\/li><li>Mettre \u00e0 disposition des \u00e9quipes les outils m\u00e9thodologiques d\u2019enqu\u00eate pour faciliter le travail des \u00e9quipes op\u00e9rationnelles<\/li><li>Elaboration de modules de formation pour les \u00e9quipes programme sur les m\u00e9thodologies d\u2019enqu\u00eate&nbsp;<\/li><li>Elaboration de modules de formation pour les enqu\u00eateurs<\/li><li>Mise \u00e0 disposition de rapports d\u2019enqu\u00eate type<\/li><li>Assurer une veille de la situation humanitaire sur les zones d\u2019intervention&nbsp;: collecte et diffusion des rapports d\u2019autres acteurs et d\u2019informations contextuelles.<\/li><\/ul>\n\n\n\n<p><strong><u>Profil recherch\u00e9:<\/u><\/strong><\/p>\n\n\n\n<ul><li><strong>Etre titulaire au minimum d\u2019un dipl\u00f4me de niveau Bacc+3 en gestion des projets&nbsp;; suivi \u00e9valuation des projets et \/ ou forte exp\u00e9rience. Bac +5 appr\u00e9ci\u00e9.<\/strong><\/li><\/ul>\n\n\n\n<p><strong>Exp\u00e9rience Professionnelle&nbsp;<\/strong><\/p>\n\n\n\n<p>Justifier d\u2019une&nbsp;<strong>exp\u00e9rience d\u2019au moins deux (02) ans&nbsp;<\/strong>\u00e0 un poste similaire dans une ONG ou institution internationale.<\/p>\n\n\n\n<p><strong>Connaissances&nbsp;et comp\u00e9tences requises<\/strong><\/p>\n\n\n\n<ul><li>Outils et m\u00e9thodologies d\u2018\u00e9valuations<\/li><li>Excellente maitrise des bases de donn\u00e9es<\/li><li>Excel, ACCESS, Epi Info, SPSS ou similaire dans l&rsquo;analyse des donn\u00e9es<\/li><li>Gestion de projets<\/li><li>Bonnes capacit\u00e9 r\u00e9dactionnelle<\/li><li>Genre et protection transversale.<\/li><li>R\u00e9daction des rapports<\/li><\/ul>\n\n\n\n<p><strong>Connaissances&nbsp;et comp\u00e9tences appr\u00e9ci\u00e9es<\/strong><\/p>\n\n\n\n<ul><li>Anglais&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li><li>Bonne connaissance de la zone d\u2019intervention<\/li><\/ul>\n\n\n\n<p><strong>Caract\u00e9ristiques personnelles requises&nbsp;:<\/strong><\/p>\n\n\n\n<ul><li>Honn\u00eatet\u00e9, transparence, impartialit\u00e9 et int\u00e9grit\u00e9<\/li><li>Sens des responsabilit\u00e9s<\/li><li>Sens de la diplomatie<\/li><li>Capacit\u00e9 d\u2019analyse et de synth\u00e8se<\/li><li>Capacit\u00e9 d\u2019\u00e9coute<\/li><li>Capacit\u00e9 de communication orale et \u00e9crite<\/li><li>Disponibilit\u00e9<\/li><li>Ponctualit\u00e9<\/li><li>Organis\u00e9<\/li><li>Rigueur et pr\u00e9cision<\/li><li>Discr\u00e9tion<\/li><li>Fermet\u00e9<\/li><li>Force de propositions<\/li><li>Autonomie<\/li><\/ul>\n\n\n\n<p><strong><u>Conditions<\/u><\/strong><\/p>\n\n\n\n<ul><li>Poste bas\u00e9 \u00e0 Yaound\u00e9 (R\u00e9gion du centre) avec d\u00e9placement sur les zones d\u2019intervention<\/li><li>Contrat \u00e0 Dur\u00e9e D\u00e9termin\u00e9e&nbsp;;<\/li><li>Salaire d\u00e9fini selon la grille salariale PUI&nbsp;;<\/li><li><strong>Entr\u00e9e en poste \u00e0 partir du 15 MARS 2021.<\/strong><\/li><\/ul>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>LE (LA) CANDIDAT(E) DOIT ENVOYER SON DOSSIER (UNIQUEMENT LETTRE MOTIVATION ET CV), A L\u2019ADRESSE MAIL&nbsp;<\/strong><strong><a href=\"mailto:recrutement@premiere-urgence.cm\">recrutement@premiere-urgence.cm<\/a><\/strong><strong>&nbsp;&nbsp;EN MENTIONNANT UNIQUEMENT \u00ab&nbsp;PUI SERA NAT&nbsp;\u00bb&nbsp;EN OBJET.<\/strong><strong>LES DOSSIERS FOURNIS NE SERONT PAS RESTITU\u00c9S AUX CANDIDATS.<\/strong><strong>DATE LIMITE DE D\u00c9POT DES DOSSIERS&nbsp;:&nbsp;<u>LE DIMANCHE, 28 FEVRIER 202<\/u><\/strong><strong><u>1<\/u><\/strong><strong>SEULS LES CANDIDATS PRESELECTIONNES SERONT CONTACTES PERSONNELLEMENT.<\/strong><strong>LES ORIGINAUX DES DIPLOMES, CERTIFICAT DE TRAVAIL, RECOMMANDATIONS DEVRONT ETRE APPORTES PAR LES CANDIDATS CONVOQUES POUR LES TESTS ET ENTRETIENS.<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>UN(E) (01) RESPONSABLE MISSION POUR LE SUIVI EVALUATION REDEVABILITE APPRENTISSAGE<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[436],"tags":[2051],"villes":[136],"contrats":[234],"diplomes":[159],"louma_meta":{"emploi_title":"UN(E) (01) RESPONSABLE MISSION POUR LE SUIVI EVALUATION REDEVABILITE APPRENTISSAGE","emplois_employeur":3532,"emplois_date_publication":"2021-02-19","emplois_heure_publication":"","emplois_date_cloture":"2021-02-19","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":" recrutement@premiere-urgence.cm"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/11041"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=11041"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/11041\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/3534"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=11041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=11041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=11041"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=11041"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=11041"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=11041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}