{"id":10763,"date":"2021-02-15T15:23:37","date_gmt":"2021-02-15T14:23:37","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=10763"},"modified":"2021-02-15T15:23:41","modified_gmt":"2021-02-15T14:23:41","slug":"caristes","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/caristes\/","title":{"rendered":"Caristes"},"content":{"rendered":"\n<p>BAO Cash &amp; Carry OFFRE D&rsquo;EMPLOI Dans le cadre de l&rsquo;ouverture de ses prochains magasins sur Douala , BAO Cash &amp; Carry lance un recrutement pour le poste suivant :<br>Caristes<\/p>\n\n\n\n<p>Le d\u00e9p\u00f4t des candidatures se fait uniquementen ligne \u00e0 l&rsquo;adresse suivante : recrutement@bao-cc.com<\/p>\n\n\n\n<p>Bien vouloir pr\u00e9ciseren objetle poste pour lequel vous postulez .<\/p>\n\n\n\n<p>Date limite de soumission des candidatures : 15 F\u00e9vrier 2021<\/p>\n\n\n\n<p>Seuls les candidats retenus seront contact\u00e9s<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Caristes<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[251],"tags":[1960],"villes":[135],"contrats":[234],"diplomes":[162],"louma_meta":{"emploi_title":"Caristes","emplois_employeur":10712,"emplois_date_publication":"2021-02-15","emplois_heure_publication":"","emplois_date_cloture":"2021-02-15","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":""},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/10763"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=10763"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/10763\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/10713"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=10763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=10763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=10763"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=10763"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=10763"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=10763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}