{"id":10565,"date":"2021-02-10T17:26:54","date_gmt":"2021-02-10T16:26:54","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=10565"},"modified":"2021-02-10T17:26:59","modified_gmt":"2021-02-10T16:26:59","slug":"offre-demploi-responsable-comptable","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/offre-demploi-responsable-comptable\/","title":{"rendered":"Offre d\u2019emploi : Responsable Comptable"},"content":{"rendered":"\n<ol><li>CONTEXTE<br>OFFRE D\u2019EMPLOI (H\/F)<\/li><li><\/li><li><br>Une soci\u00e9t\u00e9 de la place, op\u00e9rant dans le secteur agro-alimentaire (import-distribution en gros), recherche pour les besoins de ses activit\u00e9s, un Responsable Comptable. La soci\u00e9t\u00e9 est bas\u00e9e \u00e0 Douala et poss\u00e8de une Agence \u00e0 Yaound\u00e9.<\/li><li>PROFIL DU POSTE (CDI)<br>Rattach\u00e9 au Responsable Administratif et Financier, il collabore \u00e9troitement avec lui pour envisager la r\u00e9organisation du service comptabilit\u00e9 de l\u2019entreprise. Sa mission consiste en effet \u00e0 tenir la comptabilit\u00e9 de l\u2019entreprise en temps r\u00e9el, et de pouvoir fournir \u00e0 la direction la position des comptes, notamment les clients, fournisseurs, stocks, etc.<br>Activit\u00e9s principales :<\/li><\/ol>\n\n\n\n<ul><li>Superviser la tenue de la Comptabilit\u00e9 financi\u00e8re de l\u2019entreprise : imputation et saisie des pi\u00e8ces comptables de base (achats, ventes, tr\u00e9sorerie et op\u00e9rations diverses, etc.) ;<\/li><li>Effectuer le suivi de la facturation ;<\/li><li>G\u00e9rer les \u00e9ch\u00e9anciers (Clients\/Fournisseurs) : suivre les encaissements clients et paiements<br>fournisseurs ;<\/li><li>Effectuer les d\u00e9clarations fiscale et sociale mensuelles ainsi que les paiements y aff\u00e9rents ;<\/li><li>Rapprocher les soldes des comptes bancaires de l\u2019entreprise ;<\/li><li>Etablir et v\u00e9rifier les \u00e9tats de gestion (jour\/semaine\u2026) : stocks, tr\u00e9sorerie, clients et fournisseurs ;<\/li><li>Organiser et superviser le transfert de stocks entre la direction et l\u2019agence de Yaound\u00e9 ;<\/li><li>Organiser les inventaires p\u00e9riodiques des stocks de marchandises (p\u00e9riode \u00e0 d\u00e9finir par la<br>direction) ;<\/li><li>Concevoir et actualiser des outils d\u2019analyse et de suivi ;<\/li><li>Pr\u00e9parer et pr\u00e9senter les \u00e9tats comptables ;<\/li><li>Contr\u00f4ler la r\u00e9gularit\u00e9 et la sinc\u00e9rit\u00e9 des documents comptables ;<\/li><li>Organiser, planifier et coordonner la production comptable et financi\u00e8re annuelle en<br>respectant les d\u00e9lais et la r\u00e8glementation fiscale ;<\/li><li>D\u00e9finir et faire appliquer les proc\u00e9dures comptables et financi\u00e8res.<br>1<\/li><\/ul>\n\n\n\n<p>3- PROFIL DU CANDIDAT<br>Ag\u00e9 de 30 ans minimum et parfaitement bilingue (Fran\u00e7ais\/Anglais), le candidat doit r\u00e9pondre<br>aux exigences suivantes :<br>3-1. Connaissances et qualit\u00e9s recherch\u00e9es :<\/p>\n\n\n\n<ul><li>Une bonne connaissance du secteur de l\u2019agro-alimentaire (principalement la distribution<br>des boissons import\u00e9es) serait un atout<\/li><li>Capacit\u00e9 \u00e0 encadrer une \u00e9quipe pluridisciplinaire<\/li><li>Facilit\u00e9 d\u2019adaptation<\/li><li>Capacit\u00e9 \u00e0 travailler sous pression et \u00e0 respecter les d\u00e9lais<\/li><li>Rigoureux et anim\u00e9 par la recherche de la performance.<br>3-2. Formation requise (ou dipl\u00f4me) :<br>BAC G2 + 3 minimum en Finance\/comptabilit\u00e9 (ou tout autre dipl\u00f4me \u00e9quivalent).<br>3-3. Exp\u00e9rience souhait\u00e9e\/exig\u00e9e :<br>Trois (03) ans, minimum \u00e0 un poste similaire, de pr\u00e9f\u00e9rence dans une entreprise du secteur de l\u2019agro-alimentaire. Poste ouvert aux int\u00e9ress\u00e9s exer\u00e7ant en Cabinet d\u2019expertise comptable et ayant tenu le dossier d\u2019un client du secteur de l\u2019agro-alimentaire.<br>4- CONTACT<br>\uf028 668-95-08-92 (WhatsApp)<br>@ info@dk-tconsulting.com<br>Date limite de d\u00e9p\u00f4t des candidatures : 20 F\u00e9vrier 2021 R\u00e9f. NEG 02\/21<br>2<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>CONTEXTEOFFRE D\u2019EMPLOI (H\/F) Une soci\u00e9t\u00e9 de la place, op\u00e9rant dans le secteur agro-alimentaire (import-distribution en gros), recherche pour les besoins de ses activit\u00e9s, un Responsable&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[],"tags":[1909,1641,1910],"villes":[136],"contrats":[234],"diplomes":[212],"louma_meta":{"emploi_title":"Offre d\u2019emploi : Responsable Comptable","emplois_employeur":3046,"emplois_date_publication":"2021-02-10","emplois_heure_publication":"","emplois_date_cloture":"2021-02-20","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"info@dk-tconsulting.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/10565"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=10565"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/10565\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/9483"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=10565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=10565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=10565"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=10565"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=10565"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=10565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}