{"id":10563,"date":"2021-02-10T17:18:07","date_gmt":"2021-02-10T16:18:07","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=10563"},"modified":"2021-02-10T17:19:33","modified_gmt":"2021-02-10T16:19:33","slug":"responsable-technique-de-production","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/responsable-technique-de-production\/","title":{"rendered":"RESPONSABLE TECHNIQUE DE PRODUCTION"},"content":{"rendered":"\n<p>RESPONSABLE TECHNIQUE DE PRODUCTION<br>LECKPA GROUP (Yaound\u00e9, Cameroun)<br>Publi\u00e9e : 10 F\u00e9vrier 2021<br>Domaine de l&rsquo;offre : responsable technique de production Lieu : Yaound\u00e9, Cameroun Type de l&rsquo;offre : PRE-EMPLOI (06 mois) Temps Plein<br>NB : Tout candidats doit non seulement avoir une formation en \u00e9levage mais il doit aussi avoir<br>d\u00e9j\u00e0 pratiqu\u00e9 l\u2019activit\u00e9 de production des poussins sur une certaine p\u00e9riode.<br>LECKPA GROUP SARL recherche actuellement \u00e0 Yaound\u00e9 dans le domaine de l\u2019agronomie, un Technicien exp\u00e9riment\u00e9 dans l\u2019activit\u00e9 de production des poussins de poulets d\u2019un jour.<br>MISSIONS<br>Rattach\u00e9 au Manageur des op\u00e9rations, le technicien aura pour principales missions de :<\/p>\n\n\n\n<ul><li>La responsabilit\u00e9 technique de toutes les taches lier \u00e0 la production ;<\/li><li>Propos\u00e9 des solutions fiables et des proc\u00e9d\u00e9s v\u00e9rifi\u00e9s pour la r\u00e9solution des probl\u00e8mes li\u00e9s \u00e0 la production ;<\/li><li>Constituer une \u00e9quipe de travail qualifi\u00e9 en Participant au recrutement des autres techniciens auxiliaires comp\u00e9tents ;<\/li><li>Travailler en \u00e9troite collaboration avec le directeur commercial ;<\/li><li>Etablir un calendrier d\u2019activit\u00e9 allant du jour 1 \u00e0 la livraison de la totalit\u00e9 des poussins ;<\/li><li>S\u2019assurer du respect absolu du calendrier d\u2019activit\u00e9 ;<\/li><li>S\u2019assurer de la bonne qualit\u00e9 des poussins produits et proposer des am\u00e9liorations comp\u00e9titives etc\u2026<br>QUALITES<\/li><li>Etre capable de manipuler ais\u00e9ment les couveuses ou incubateurs<br>Page 1 sur 2<\/li><li>Avoir un sens pouss\u00e9 de l\u2019organisation et l\u2019anticipation ;<\/li><li>Etre un bon chef d\u2019\u00e9quipe et rigoureux ;<\/li><li>Etre dot\u00e9 d\u2019un bon relationnel et d\u2019une grande capacit\u00e9 d\u2019adaptation ;<\/li><li>Avoir une grande autonomie dans le travail ;<\/li><li>Avoir l\u2019esprit d\u2019\u00e9quipe ;<\/li><li>Pouvoir travailler sous pression<\/li><li>Etre capable de bien utiliser les logiciels Word, Excel, PowerPoint ;<br>PROFIL<br>&#8211;<\/li><li>&#8211;<br>Avoir une formation pratique en \u00e9levage en g\u00e9n\u00e9rale et en avicultures en particulier. Avoir l\u2019exp\u00e9rience dans l\u2019activit\u00e9 de production des poussins de poulets d\u2019un jour ;<br>Etre en mesure de faire toutes les manipulations courantes sur les couveuses ; Etre capable de d\u00e9fendre la qualit\u00e9 des poussins qu\u2019il produit etc\u2026<\/li><li>Avoir une bonne sant\u00e9 physique ;<\/li><li>Avoir une bonne capacit\u00e9 d\u2019improvisation ;<br>N.B : Avoir son ordinateur portable personnel (si possible mais pas obligatoire) et son t\u00e9l\u00e9phone Android(obligatoire)<br>Deadline : Dimanche le 28 F\u00e9vrier 2021<br>Envoyez votre dossier de candidature CV et Lettre de Motivation \u00e0:<br>jobs@leckpagroup.com<br>Page 2 sur 2<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>RESPONSABLE TECHNIQUE DE PRODUCTION<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[21],"tags":[128,242],"villes":[136],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"RESPONSABLE TECHNIQUE DE PRODUCTION","emplois_employeur":8367,"emplois_date_publication":"2021-02-10","emplois_heure_publication":"","emplois_date_cloture":"2021-02-28","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"3","emploi_email":"jobs@leckpagroup.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/10563"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=10563"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/10563\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/8368"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=10563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=10563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=10563"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=10563"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=10563"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=10563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}