{"id":10211,"date":"2021-02-02T12:09:34","date_gmt":"2021-02-02T11:09:34","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=10211"},"modified":"2021-02-02T12:09:39","modified_gmt":"2021-02-02T11:09:39","slug":"offre-demploi-charges-de-clientele","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/offre-demploi-charges-de-clientele\/","title":{"rendered":"Offre d\u2019emploi : Charg\u00e9s de Client\u00e8le"},"content":{"rendered":"\n<p>Smobilpay\/TCK<\/p>\n\n\n\n<p>Douala Cameroun<br>20 candidats<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>   *I-Descrition du poste*\n\n Nous recherchons les charg\u00e9es client\u00e8les qualifi\u00e9es pour rejoindre notre \u00e9quipe.\nNos candidats id\u00e9ales poss\u00e8dent des comp\u00e9tences exceptionnelles en communication orale et \u00e9crite et sont capables de d\u00e9velopper un contenu engageant.vous devez \u00eatre des personnes humaines, sociables avec des grandes aptitudes en service \u00e0 la client\u00e8le et la capacit\u00e9 de converser et de convaincre instantan\u00e9ment avec notre communaut\u00e9.<\/code><\/pre>\n\n\n\n<p>En fin de compte , vous devriez \u00eatre en mesure d&rsquo;agir comme le visage et la voix d&rsquo;une marque sp\u00e9cifique et de g\u00e9rer toutes les communications communautaires.<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>  II- PROFIL DU POSTE<\/code><\/pre>\n\n\n\n<p>** \u00catre \u00e2g\u00e9e entre 18-28<br>** Avoir au moins un BEPC ou CAP et plus<br>** \u00catre disponible, discret, serviable, ponctuelle, courtois et une bonne pr\u00e9sentation.<\/p>\n\n\n\n<pre class=\"wp-block-code\"><code>   III- DOSSIER DE CANDIDATURE<\/code><\/pre>\n\n\n\n<ul><li>CV<br>*Photocopie de la carte<\/li><li>Plan de localisation<\/li><li>Lettre de motivation manuscrite<\/li><\/ul>\n\n\n\n<p>Les personnes int\u00e9ress\u00e9es sont pri\u00e9es de bien vouloir nous transmettre leurs dossiers de candidature au plus tard le vendredi 05\/02\/2021 \u00e0 15hr. Nous sommes situ\u00e9s \u00e0 bali face hotel Serena.<br>Pour plus d&rsquo;informations veuillez contacter 677552209 via WhatsApp<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Offre d\u2019emploi : Charg\u00e9s de Client\u00e8le <\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[251],"tags":[1843],"villes":[136],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Offre d\u2019emploi : Charg\u00e9s de Client\u00e8le ","emplois_employeur":3046,"emplois_date_publication":"2021-02-02","emplois_heure_publication":"","emplois_date_cloture":"2021-03-09","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"3","emploi_email":"Pour plus d'informations veuillez contacter 677552209 via WhatsApp"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/10211"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=10211"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/10211\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/9483"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=10211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=10211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=10211"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=10211"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=10211"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=10211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}